{"id":90147,"date":"2023-05-01T14:03:45","date_gmt":"2023-05-01T18:03:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=90147"},"modified":"2023-05-01T14:03:47","modified_gmt":"2023-05-01T18:03:47","slug":"gripe-unida-a-neumonia-bacteriana-incrementa-3-veces-riesgo-de-muerte","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gripe-unida-a-neumonia-bacteriana-incrementa-3-veces-riesgo-de-muerte\/","title":{"rendered":"Gripe unida a neumon\u00eda bacteriana incrementa 3 veces riesgo de muerte"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/gripe.png\" alt=\"\" class=\"wp-image-90148\" width=\"192\" height=\"127\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/gripe.png 692w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/gripe-300x199.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/gripe-600x399.png 600w\" sizes=\"auto, (max-width: 192px) 100vw, 192px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">MADRID. (Europapress).- La gripe, junto con una neumon\u00eda bacteriana, podr\u00eda incrementar m\u00e1s de tres veces el riesgo de muerte, por lo que prevenir neumon\u00edas bacterianas es especialmente importante cuando surge una infecci\u00f3n por el virus de la gripe, seg\u00fan un estudio realizado por investigadores del Instituto de Salud Carlos III (ISCIII).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n, publicada en la revista \u2018International Journal of Infectious Diseases\u2019, ha sido coordinada por el Grupo de Investigaci\u00f3n de Virolog\u00eda e Inmunidad Innata de la Universidad CEU San Pablo (USPCEU), que dirige el doctor Estanislao Nistal Vill\u00e1n, en colaboraci\u00f3n con la Unidad de Inmunolog\u00eda y Trasplantes del Centro Nacional de Microbiolog\u00eda del ISCIII, liderada por el doctor Jordi Ochando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los investigadores han analizado datos de m\u00e1s de 48.000 pacientes publicados entre 2010 y 2020, provenientes de 135 estudios desarrollados en 28 pa\u00edses, en busca de las principales causas que incrementan la gravedad en caso de gripe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados, adem\u00e1s, han sido validados de forma independiente mediante la plataforma \u2018TrinetX\u2019 con datos de casi cuatro millones de pacientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados apuntan hacia las infecciones pulmonares bacterianas como uno de los factores de riesgo m\u00e1s relevantes en infecciones por virus de la gripe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAlgunas de las bacterias que causan estas neumon\u00edas secundarias pueden vivir en nuestro cuerpo y colonizar nuestro aparato respiratorio superior o infectarnos desde el exterior. Las m\u00e1s habituales, como \u2018Streptococcus pneumoniae\u2019 y \u2018Staphylococcus aureus\u2019, son responsables de m\u00e1s del 60 por ciento de las neumon\u00edas bacterianas asociadas a la gripe\u00bb, detallan Javier Arranz-Herrero y Jes\u00fas Presa, primeros autores del estudio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LA PREVENCI\u00d3N DE NEUMON\u00cdAS BACTERIANAS, UNA DE LAS CLAVES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio tambi\u00e9n arroja la posibilidad de que se est\u00e9n infradiagnosticando las complicaciones bacterianas en casos de gripe, y pone de manifiesto la necesidad de afrontar estrategias de prevenci\u00f3n, diagn\u00f3stico y tratamiento antibi\u00f3tico en casos donde exista un riesgo alto de complicaciones asociadas a las infecciones gripales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gripe es una enfermedad causada por distintos virus Influenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abExisten distintas condiciones f\u00edsicas, de edad, o enfermedades que hacen que los pacientes que desarrollen gripe tengan un riesgo alto de sufrir complicaciones y de morir\u00bb, a\u00f1ade Nistal Vill\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID. (Europapress).- La gripe, junto con una neumon\u00eda bacteriana, podr\u00eda incrementar m\u00e1s de tres veces el riesgo de muerte, por lo que prevenir neumon\u00edas bacterianas es especialmente importante cuando surge una infecci\u00f3n por el virus de la gripe, seg\u00fan un estudio realizado por investigadores del Instituto de Salud Carlos III (ISCIII). La investigaci\u00f3n, publicada en la revista \u2018International Journal of Infectious Diseases\u2019, ha sido coordinada por el Grupo de Investigaci\u00f3n de Virolog\u00eda e Inmunidad Innata de la Universidad CEU San Pablo (USPCEU), que dirige el doctor Estanislao Nistal Vill\u00e1n, en colaboraci\u00f3n con la Unidad de Inmunolog\u00eda y Trasplantes del Centro Nacional de Microbiolog\u00eda del ISCIII, liderada por el doctor Jordi Ochando. Los investigadores han analizado datos de m\u00e1s de 48.000 pacientes publicados entre 2010 y 2020, provenientes de 135 estudios desarrollados en 28 pa\u00edses, en busca de las principales causas que incrementan la gravedad en caso de gripe. Los resultados, adem\u00e1s, han sido validados de forma independiente mediante la plataforma \u2018TrinetX\u2019 con datos de casi cuatro millones de pacientes. Los resultados apuntan hacia las infecciones pulmonares bacterianas como uno de los factores de riesgo m\u00e1s relevantes en infecciones por virus de la gripe. \u00abAlgunas de las bacterias que causan estas neumon\u00edas secundarias pueden vivir en nuestro cuerpo y colonizar nuestro aparato respiratorio superior o infectarnos desde el exterior. Las m\u00e1s habituales, como \u2018Streptococcus pneumoniae\u2019 y \u2018Staphylococcus aureus\u2019, son responsables de m\u00e1s del 60 por ciento de las neumon\u00edas bacterianas asociadas a la gripe\u00bb, detallan Javier Arranz-Herrero y Jes\u00fas Presa, primeros autores del estudio. LA PREVENCI\u00d3N DE NEUMON\u00cdAS BACTERIANAS, UNA DE LAS CLAVES El estudio tambi\u00e9n arroja la posibilidad de que se est\u00e9n infradiagnosticando las complicaciones bacterianas en casos de gripe, y pone de manifiesto la necesidad de afrontar estrategias de prevenci\u00f3n, diagn\u00f3stico y tratamiento antibi\u00f3tico en casos donde exista un riesgo alto de complicaciones asociadas a las infecciones gripales. La gripe es una enfermedad causada por distintos virus Influenza. \u00abExisten distintas condiciones f\u00edsicas, de edad, o enfermedades que hacen que los pacientes que desarrollen gripe tengan un riesgo alto de sufrir complicaciones y de morir\u00bb, a\u00f1ade Nistal Vill\u00e1n.<\/p>\n","protected":false},"author":9,"featured_media":90148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-90147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=90147"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90147\/revisions"}],"predecessor-version":[{"id":90149,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90147\/revisions\/90149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/90148"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=90147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=90147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=90147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}