{"id":90337,"date":"2023-05-11T09:39:28","date_gmt":"2023-05-11T13:39:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=90337"},"modified":"2023-05-11T09:39:31","modified_gmt":"2023-05-11T13:39:31","slug":"estados-unidos-advierte-deportara-dominicanos-que-busquen-la-vuelta-por-mexico","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/estados-unidos-advierte-deportara-dominicanos-que-busquen-la-vuelta-por-mexico\/","title":{"rendered":"Estados Unidos advierte deportar\u00e1 dominicanos que busquen \u00abla vuelta por M\u00e9xico\u00bb"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/imagen-ap23129855086657-2-9a511372-focus-0-0-895-573.jpg\" alt=\"\" class=\"wp-image-90338\" width=\"237\" height=\"152\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/imagen-ap23129855086657-2-9a511372-focus-0-0-895-573.jpg 895w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/imagen-ap23129855086657-2-9a511372-focus-0-0-895-573-300x192.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/imagen-ap23129855086657-2-9a511372-focus-0-0-895-573-768x492.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/imagen-ap23129855086657-2-9a511372-focus-0-0-895-573-600x384.jpg 600w\" sizes=\"auto, (max-width: 237px) 100vw, 237px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>T\u00edtulo 42<\/strong>&nbsp;llega a su fin hoy jueves y con \u00e9l comienzan las advertencias de deportaciones para todos aquellos migrantes que no forman parte del programa de permisos temporales que Estados Unidos otorgar\u00e1 a ciudadanos de cuatros pa\u00edses para ingresar por la frontera suroeste al territorio estadounidense.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo ha dejado claro el agregado de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP por sus siglas en ingl\u00e9s) en la Rep\u00fablica Dominicana, Jonathan Mardo, quien record\u00f3 que los dominicanos no est\u00e1n incluidos en las 30 mil visas humanitarias que ser\u00e1n entregadas este a\u00f1o por el Gobierno americano.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Con el cierre del\u00a0<strong>T\u00edtulo 42<\/strong>, que no es m\u00e1s que la restricci\u00f3n de solicitud de asilo interpuesta por la administraci\u00f3n de Donald Trump, que permit\u00eda deportar indistintamente a los inmigrantes bajo el alegato de la crisis sanitaria provocada por la pandemia del COVID-19, la frontera sur de Estados Unidos ha comenzado a abarrotarse de inmigrantes de distintos pa\u00edses que buscan ser admitidos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los permisos que entregar\u00e1 Estados Unidos est\u00e1n destinados para ciudadanos provenientes de Hait\u00ed, Venezuela, Cuba y Nicaragua.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mardo asegur\u00f3 que todo aquel que no tenga una base legal para permanecer en EE.UU. no ser\u00e1n elegible para legalizar su estatus y estar\u00e1 sujeto a la deportaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que su pa\u00eds est\u00e1 comprometido con la&nbsp;<strong>migraci\u00f3n<\/strong>&nbsp;legal, ordenada y humana, indicando que no es seguro entrar por canales irregulares.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLos riesgos e inconvenientes de viajar a los Estados Unidos en yola a trav\u00e9s del Canal de la Mona o caminando por los desiertos de M\u00e9xico superan los beneficios percibidos de migrar a los Estados Unidos\u00bb, dijo Mardo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCruzar ilegalmente la frontera entre los Estados Unidos y M\u00e9xico es extremadamente peligroso. Cientos de personas mueren cada a\u00f1o intentando cruzar la frontera suroeste de los Estados Unidos. Los inmigrantes no solo se enfrentan a las inclemencias del medio ambiente, sino que caminan durante d\u00edas por el desierto sin agua\u00bb, continu\u00f3 el funcionario estadounidense.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A inicios de este a\u00f1o, Blas N\u00fa\u00f1ez-Neto, subsecretario Interino de Pol\u00edtica Fronteriza e Inmigraci\u00f3n en el Departamento de Seguridad Nacional, dijo a Diario Libre, que aquellos dominicanos varados en la frontera mexicana y que tienen una cualidad voluble para evitar ser deportados bajo el&nbsp;<strong>T\u00edtulo 42<\/strong>, que a\u00fan se encontraba vigente, pod\u00edan presentar su aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el cierre de este, las oportunidades de los dominicanos que deseen entrar a EE.UU. se vuelven nulas o escasas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 est\u00e1 pasando?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que se anunci\u00f3 el fin del&nbsp;<strong>T\u00edtulo 42<\/strong>&nbsp;en Estados Unidos, la frontera sur entre M\u00e9xico y Estados Unidos se ha vuelto a abarrotar de migrantes. Las im\u00e1genes dantescas de personas durmiendo en las calles y de la Guardia Nacional de Texas dej\u00e1ndolos varados mientras intentan entrar irregularmente, le dieron la vuelta al mundo este mi\u00e9rcoles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras, Estados Unidos se prepara para arrestar y deportar \u00abgrandes cifras\u00bb de inmigrantes a partir de hoy jueves. Con la intenci\u00f3n de prevenir el peor de los escenarios, el presidente estadounidense Joe Biden despleg\u00f3 unos 24 mil agentes en la frontera que atender\u00e1n a los migrantes que \u00ablegalmente\u00bb puedan ser admitidos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSer\u00e1 ca\u00f3tico por un tiempo\u00bb, fueron las palabras de Biden en una rueda de prensa el martes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de ma\u00f1ana viernes, los migrantes que soliciten asilo, van a ser entrevistados por los agentes migratorios posados en la frontera. La admisi\u00f3n al territorio norteamericano estar\u00e1 sujeta a que estos puedan demostrar que son perseguidos o que corren peligro en sus pa\u00edses de origen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;T\u00edtulo 42&nbsp;llega a su fin hoy jueves y con \u00e9l comienzan las advertencias de deportaciones para todos aquellos migrantes que no forman parte del programa de permisos temporales que Estados Unidos otorgar\u00e1 a ciudadanos de cuatros pa\u00edses para ingresar por la frontera suroeste al territorio estadounidense.&nbsp; As\u00ed lo ha dejado claro el agregado de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP por sus siglas en ingl\u00e9s) en la Rep\u00fablica Dominicana, Jonathan Mardo, quien record\u00f3 que los dominicanos no est\u00e1n incluidos en las 30 mil visas humanitarias que ser\u00e1n entregadas este a\u00f1o por el Gobierno americano.\u00a0 Con el cierre del\u00a0T\u00edtulo 42, que no es m\u00e1s que la restricci\u00f3n de solicitud de asilo interpuesta por la administraci\u00f3n de Donald Trump, que permit\u00eda deportar indistintamente a los inmigrantes bajo el alegato de la crisis sanitaria provocada por la pandemia del COVID-19, la frontera sur de Estados Unidos ha comenzado a abarrotarse de inmigrantes de distintos pa\u00edses que buscan ser admitidos. Los permisos que entregar\u00e1 Estados Unidos est\u00e1n destinados para ciudadanos provenientes de Hait\u00ed, Venezuela, Cuba y Nicaragua.&nbsp; Mardo asegur\u00f3 que todo aquel que no tenga una base legal para permanecer en EE.UU. no ser\u00e1n elegible para legalizar su estatus y estar\u00e1 sujeto a la deportaci\u00f3n.&nbsp; Dijo que su pa\u00eds est\u00e1 comprometido con la&nbsp;migraci\u00f3n&nbsp;legal, ordenada y humana, indicando que no es seguro entrar por canales irregulares.&nbsp; \u00abLos riesgos e inconvenientes de viajar a los Estados Unidos en yola a trav\u00e9s del Canal de la Mona o caminando por los desiertos de M\u00e9xico superan los beneficios percibidos de migrar a los Estados Unidos\u00bb, dijo Mardo. \u00abCruzar ilegalmente la frontera entre los Estados Unidos y M\u00e9xico es extremadamente peligroso. Cientos de personas mueren cada a\u00f1o intentando cruzar la frontera suroeste de los Estados Unidos. Los inmigrantes no solo se enfrentan a las inclemencias del medio ambiente, sino que caminan durante d\u00edas por el desierto sin agua\u00bb, continu\u00f3 el funcionario estadounidense.\u00a0 A inicios de este a\u00f1o, Blas N\u00fa\u00f1ez-Neto, subsecretario Interino de Pol\u00edtica Fronteriza e Inmigraci\u00f3n en el Departamento de Seguridad Nacional, dijo a Diario Libre, que aquellos dominicanos varados en la frontera mexicana y que tienen una cualidad voluble para evitar ser deportados bajo el&nbsp;T\u00edtulo 42, que a\u00fan se encontraba vigente, pod\u00edan presentar su aplicaci\u00f3n. Con el cierre de este, las oportunidades de los dominicanos que deseen entrar a EE.UU. se vuelven nulas o escasas.&nbsp; \u00bfQu\u00e9 est\u00e1 pasando? Desde que se anunci\u00f3 el fin del&nbsp;T\u00edtulo 42&nbsp;en Estados Unidos, la frontera sur entre M\u00e9xico y Estados Unidos se ha vuelto a abarrotar de migrantes. Las im\u00e1genes dantescas de personas durmiendo en las calles y de la Guardia Nacional de Texas dej\u00e1ndolos varados mientras intentan entrar irregularmente, le dieron la vuelta al mundo este mi\u00e9rcoles.&nbsp; Mientras, Estados Unidos se prepara para arrestar y deportar \u00abgrandes cifras\u00bb de inmigrantes a partir de hoy jueves. Con la intenci\u00f3n de prevenir el peor de los escenarios, el presidente estadounidense Joe Biden despleg\u00f3 unos 24 mil agentes en la frontera que atender\u00e1n a los migrantes que \u00ablegalmente\u00bb puedan ser admitidos.&nbsp; \u00abSer\u00e1 ca\u00f3tico por un tiempo\u00bb, fueron las palabras de Biden en una rueda de prensa el martes.&nbsp; A partir de ma\u00f1ana viernes, los migrantes que soliciten asilo, van a ser entrevistados por los agentes migratorios posados en la frontera. La admisi\u00f3n al territorio norteamericano estar\u00e1 sujeta a que estos puedan demostrar que son perseguidos o que corren peligro en sus pa\u00edses de origen.<\/p>\n","protected":false},"author":9,"featured_media":90338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-90337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=90337"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90337\/revisions"}],"predecessor-version":[{"id":90339,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90337\/revisions\/90339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/90338"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=90337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=90337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=90337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}