{"id":9050,"date":"2014-10-05T03:34:55","date_gmt":"2014-10-05T07:34:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9050"},"modified":"2014-10-05T03:34:55","modified_gmt":"2014-10-05T07:34:55","slug":"sigue-en-estado-critico-paciente-ebola-en-eu","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sigue-en-estado-critico-paciente-ebola-en-eu\/","title":{"rendered":"Sigue en estado cr\u00edtico paciente \u00e9bola en EU"},"content":{"rendered":"<div id=\"attachment_9051\" style=\"width: 613px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Paciente-de-ebola-en-USA.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9051\" class=\"wp-image-9051 size-full\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Paciente-de-ebola-en-USA.jpg\" alt=\"Paciente de ebola en USA\" width=\"603\" height=\"336\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Paciente-de-ebola-en-USA.jpg 603w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Paciente-de-ebola-en-USA-300x167.jpg 300w\" sizes=\"auto, (max-width: 603px) 100vw, 603px\" \/><\/a><p id=\"caption-attachment-9051\" class=\"wp-caption-text\">Limpiadores de materiales t\u00f3xicos colocan una cubierta de pl\u00e1stico en las afueras de un apartamento en Dallas, donde estuvo hospedado Eric Duncan, infectado de \u00e9bola en EU.<\/p><\/div>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Paciente-de-ebola-en-USA.jpg\"><br \/>\n<\/a>DALLAS. AP. El \u00fanico paciente enfermo de \u00e9bola en Estados Unidos se encuentra en estado de salud cr\u00edtico, report\u00f3 ayer el hospital de Dallas que lo trata.<!--more--><\/p>\n<p>Candace White, una portavoz de Texas Health Resources, que opera el Hospital Presbiteriano en Texas en Dallas donde Thomas Duncan est\u00e1 siendo atendido, emiti\u00f3 una nota de prensa de seis palabras en la que se limit\u00f3 a decir que el \u201cse\u00f1or Duncan est\u00e1 en condici\u00f3n cr\u00edtica\u201d.<\/p>\n<p>La vocera no dio m\u00e1s detalles sobre su condici\u00f3n y no dio respuesta a los mensajes por correo electr\u00f3nico ni a las llamadas telef\u00f3nicas. El hospital previamente hab\u00eda dicho que Duncan estaba en aislamiento y su estado de salud era serio, pero estable.<\/p>\n<p>Duncan viaj\u00f3 de Liberia, azotada por un brote de \u00e9bola, a Dallas el mes pasado antes de mostrar s\u00edntomas de la enfermedad. Fue tratado y dado de alta del hospital antes de regresar dos d\u00edas m\u00e1s tarde en una ambulancia y ser ingresado al ser diagnosticado con \u00e9bola.<\/p>\n<p>Funcionarios de salud dijeron el s\u00e1bado que est\u00e1n monitoreando a unas 50 personas que pudieran haber tenido contacto con Duncan, en busca de indicios de infecci\u00f3n, incluyendo nueve que se piensa est\u00e1n en alto riesgo.<\/p>\n<p>Entre los monitoreados est\u00e1n personas que viajaron en la ambulancia con Duncan antes de su diagn\u00f3stico, dijo el m\u00e9dico Tom Frieden, director de los Centros de Control y Prevenci\u00f3n de Enfermedades.<\/p>\n<p>El viernes, un equipo de limpiadores de materiales peligrosos descontamin\u00f3 el apartamento en Dallas donde Duncan se estaba quedando. La familia que vive all\u00ed fue trasladada a una vivienda privada en barrio cerrado, donde est\u00e1n siendo monitoreados cuidadosamente.<\/p>\n<p>La ciudad ha tenido problemas para encontrar un lugar que aceptase a Louise Troh, oriunda de Liberia, su hijo de 13 a\u00f1os y dos sobrinos. \u201cNadie quiere a esa familia\u201d, dijo Sana Syed, portavoz de la municipalidad.<\/p>\n<p>El equipo de descontaminaci\u00f3n se llev\u00f3 s\u00e1banas, toallas y un colch\u00f3n usado por Duncan, adem\u00e1s de una maleta y otros objetos usados por el paciente, dijeron funcionarios.<\/p>\n<p>Los materiales fueron sellados en barriles industriales que iban a ser colocados en camiones hasta poder ser llevados a su destrucci\u00f3n.<\/p>\n<p>El primer diagn\u00f3stico de \u00e9bola en Estados Unidos ha creado preocupaciones sobre si la enfermedad que ha matado a 3.400 personas en \u00c1frica occidental se pudiera diseminar en territorio estadounidense.<\/p>\n<p>Funcionarios federales de salud dicen que est\u00e1n confiados de que pueden mantenerla controlada.<\/p>\n<p>El virus de \u00e9bola no se disemina por el aire y solamente puede ser transmitido por contacto directo con fluidos corporales sangre, sudor, v\u00f3mito, heces, orina, saliva o semen de una persona infectada que muestra s\u00edntomas.<\/p>\n<p>Alto riesgo<\/p>\n<p>Atlanta EU EFE. Las autoridades sanitarias de Estados Unidos precisaron ayer que nueve personas que tuvieron contacto con el primer paciente de \u00e9bola diagnosticado en este pa\u00eds tienen \u201calto riesgo\u201d de desarrollar la enfermedad.<\/p>\n<p>\u201cEn este momento hemos identificado, en conjunto con nuestros compa\u00f1eros en Texas, nueve individuos que estuvieron definitivamente en contacto con el paciente y eso incluye a miembros de la familia y personal m\u00e9dico\u201d.<\/p>\n<p><strong>UN APUNTE<\/strong><\/p>\n<p><strong>A\u00edslan pasajeros<\/strong><\/p>\n<p>Nueva York. EFE. Los pasajeros de un vuelo procedente de Bruselas fueron aislados ayer temporalmente en el aeropuerto de Newark (Nueva Jersey, EE.UU.) hasta que los equipos m\u00e9dicos descartaron que un hombre que viajaba a bordo con s\u00edntomas parecidos a los del \u00e9bola sufriera la enfermedad. \u00a0 La falsa alarma se dispar\u00f3 por los v\u00f3mitos sufridos durante el viaje por el enfermo, que fue trasladado al Hospital Universitario de Newark .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DALLAS. AP. El \u00fanico paciente enfermo de \u00e9bola en Estados Unidos se encuentra en estado de salud cr\u00edtico, report\u00f3 ayer el hospital de Dallas que lo trata.<\/p>\n","protected":false},"author":3,"featured_media":9051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-9050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9050"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9050\/revisions"}],"predecessor-version":[{"id":9052,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9050\/revisions\/9052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9051"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}