{"id":90619,"date":"2023-05-24T08:41:20","date_gmt":"2023-05-24T12:41:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=90619"},"modified":"2023-05-24T08:41:39","modified_gmt":"2023-05-24T12:41:39","slug":"celtics-vencen-al-heat-116-99-y-siguen-con-vida-en-la-final-de-la-conferencia-este","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/celtics-vencen-al-heat-116-99-y-siguen-con-vida-en-la-final-de-la-conferencia-este\/","title":{"rendered":"Celtics vencen al Heat 116-99 y siguen con vida en la final de la Conferencia Este"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/646d8328642c7.jpeg\" alt=\"\" class=\"wp-image-90620\" width=\"240\" height=\"160\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/646d8328642c7.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/646d8328642c7-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/646d8328642c7-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/05\/646d8328642c7-600x400.jpeg 600w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El excelente juego de 34 puntos de Jayson Tatum llev\u00f3 este martes a Boston Celtics a una victoria de 116-99 sobre Miami Heat, logr\u00e1ndose mantener con vida en la Final de la Conferencia Este de la NBA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Kaseya Center de Miami, los Celtics consiguieron su primera victoria en esta serie al mejor de siete encuentros, aunque todav\u00eda los Heat dominan el pleito por 3-1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Heat busca conseguir el boleto para su segunda aparici\u00f3n en las Finales de la NBA en cuatro temporadas, pero tendr\u00e1n que esperar al jueves para finiquitar la serie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una aplastante victoria 128-102 en el partido anterior le dio a Miami una ventaja dominante de 3-0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los c\u00edrculos de la NBA, ning\u00fan equipo en la historia de la Liga ha superado un d\u00e9ficit de 3-0, por ahora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Heat pueden convertirse el jueves en el segundo equipo en la historia que alcanza las Finales siendo el octavo sembrado de su conferencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00fanica franquicia que clasific\u00f3 hasta ahora a las Finales como octavo sembrado fue los NY Knicks en 1999, cuando cayeron por 4-1 ante los San Antonio Spurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, todav\u00eda el quinteto de Miami se encuentran a solo un triunfo de pelear por el cuarto anillo de su historia, tras los de 2006, 2012 y 2013, en unas s\u00e9ptimas Finales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima de esas Finales se sald\u00f3 con una derrota ante Los Angeles Lakers en los playoffs de 2020, que se jugaron a puerta cerrada en Disney World (Florida) por la pandemia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El excelente juego de 34 puntos de Jayson Tatum llev\u00f3 este martes a Boston Celtics a una victoria de 116-99 sobre Miami Heat, logr\u00e1ndose mantener con vida en la Final de la Conferencia Este de la NBA. En el Kaseya Center de Miami, los Celtics consiguieron su primera victoria en esta serie al mejor de siete encuentros, aunque todav\u00eda los Heat dominan el pleito por 3-1. El Heat busca conseguir el boleto para su segunda aparici\u00f3n en las Finales de la NBA en cuatro temporadas, pero tendr\u00e1n que esperar al jueves para finiquitar la serie. Una aplastante victoria 128-102 en el partido anterior le dio a Miami una ventaja dominante de 3-0. En los c\u00edrculos de la NBA, ning\u00fan equipo en la historia de la Liga ha superado un d\u00e9ficit de 3-0, por ahora. Los Heat pueden convertirse el jueves en el segundo equipo en la historia que alcanza las Finales siendo el octavo sembrado de su conferencia. La \u00fanica franquicia que clasific\u00f3 hasta ahora a las Finales como octavo sembrado fue los NY Knicks en 1999, cuando cayeron por 4-1 ante los San Antonio Spurs. No obstante, todav\u00eda el quinteto de Miami se encuentran a solo un triunfo de pelear por el cuarto anillo de su historia, tras los de 2006, 2012 y 2013, en unas s\u00e9ptimas Finales. La \u00faltima de esas Finales se sald\u00f3 con una derrota ante Los Angeles Lakers en los playoffs de 2020, que se jugaron a puerta cerrada en Disney World (Florida) por la pandemia.<\/p>\n","protected":false},"author":9,"featured_media":90620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-90619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=90619"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90619\/revisions"}],"predecessor-version":[{"id":90621,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90619\/revisions\/90621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/90620"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=90619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=90619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=90619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}