{"id":90813,"date":"2023-06-07T07:55:54","date_gmt":"2023-06-07T11:55:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=90813"},"modified":"2023-06-07T07:56:04","modified_gmt":"2023-06-07T11:56:04","slug":"milly-quezada-45-anos-de-una-vida-musical-que-inicio-con-latas-de-pintura-y-dos-palitos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/milly-quezada-45-anos-de-una-vida-musical-que-inicio-con-latas-de-pintura-y-dos-palitos\/","title":{"rendered":"Milly Quezada: 45 a\u00f1os de una vida musical que inici\u00f3 con latas de pintura y dos palitos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"236\" height=\"164\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/mili.jpg\" alt=\"\" class=\"wp-image-90814\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/mili.jpg 236w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/mili-75x52.jpg 75w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Detr\u00e1s de ese recorrido de 45 a\u00f1os en el merengue que registra Milly Quezada, est\u00e1 la historia de una familia dominicana que se radic\u00f3 en los Estados Unidos y ante las adversidades de chocar con un medioambiente diferente, cuatro hermanos se refugiaron en la m\u00fasica y con latas de pintura y dos palitos dieron inicio a lo que hoy es un referente de identidad musical del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Risue\u00f1a y cargada de energ\u00eda, Milly convers\u00f3 con periodistas de List\u00edn Diario, donde narr\u00f3 el g\u00e9nesis de su carrera musical, hasta convertirse en \u201cla reina\u201d del merengue de los \u00faltimos 45 a\u00f1os, motivo por el que presentar\u00e1 \u201cViva la Reina Tour\u201d, el s\u00e1bado 17 de junio en el Teatro Nacional Eduardo Brito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milagros Quezada Borb\u00f3n,&nbsp;<\/strong>nombre de pila de la artista, relat\u00f3 que en los a\u00f1os 70 viv\u00eda en la ciudad de Nueva York, espec\u00edficamente en Washington Heights, donde para esa \u00e9poca la comunidad criolla no era predominante en el lugar. Sin embargo, a pesar de estar envuelta en otra cultura, su patria a\u00f1orada estaba presente en su diario vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn casa se com\u00eda arroz, habichuela y pollo; en casa se escuchaban los merenguitos y se ve\u00eda mucha programaci\u00f3n del canal 47 Telemundo, aunque en la escuela y otros \u00e1mbitos \u00e9ramos influenciados por el sistema anglosaj\u00f3n\u201d, cont\u00f3 la merenguera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La m\u00fasica estuvo presente en su hogar desde muy peque\u00f1a. Seg\u00fan narr\u00f3, tanto ella como sus hermanos tomaban las latas de pintura y con dos palitos empezaban la creaci\u00f3n casera de ritmos sonoros tropicales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO tend\u00edamos una s\u00e1bana en un cordel y hac\u00edamos una velada, yo le dec\u00eda a Rafaelito: &#8211; t\u00fa me presentas: \u201cY ahora se\u00f1oras y se\u00f1ores\u2026\u201d. Cuquita y Fosforito eran sus sobrenombres en la ni\u00f1ez, por la chispa que reflejaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco a poco el grupo de hermanos se fue cohesionando y surgiendo lo que en principio se denomin\u00f3 Milly Quezada y los Vecinos y que posteriormente pas\u00f3 a llamarse Milly, Jocelyn y los Vecinos, convirti\u00e9ndose en las primeras dominicanas en conformar una orquesta de merengue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al grabar su primer disco, el fenecido esposo de Quezada, Rafael V\u00e1zquez, es quien trae la m\u00fasica de la banda al pa\u00eds, lo que abri\u00f3 las puertas a que el publico escuchara por primera vez a una mujer dominicana a ritmo del g\u00e9nero musical aut\u00f3ctono. En ese momento, Milly desconoc\u00eda que estaba adentr\u00e1ndose a un territorio inh\u00f3spito por la mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cJohnny Ventura hace las an\u00e9cdotas de la impresi\u00f3n, y Wilfrido Vargas. Incluso, se sintieron como invadidos; esa es la expresi\u00f3n que me contaba Johnny, (quien se preguntaba): &#8211; \u00bfy qu\u00e9 hace esta mujer o c\u00f3mo se atreve esta mujer a pretender entrar en terreno masculino?-, una expresi\u00f3n como machista, jeejeej\u201d, relat\u00f3 la interprete de \u201cSolo contigo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esto, manifest\u00f3 que los primeros a\u00f1os fueron muy informales y org\u00e1nicos, debido a que tanto ella como sus hermanos ve\u00edan la m\u00fasica como \u201dun desahogo existencial\u201d, al estar en un barrio nuevo, en un pa\u00eds e idioma diferentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La popularidad de Milly iba creciendo como espuma y en la ausencia de otras figuras en el g\u00e9nero. Su \u00fanico desaf\u00edo era entrar a la radio, lo cual logr\u00f3 por primera vez en el pa\u00eds con el tema musical \u201cT\u00fa sabes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reina del merengue indic\u00f3 que el reconocido merenguero Johnny Ventura, al escuchar la canci\u00f3n despert\u00f3 una chispa en \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl ser mujer, ese gritico (estallido que hace en sus canciones), abri\u00f3 el camino; coincidir con la liberaci\u00f3n femenina tambi\u00e9n\u2026\u201d, apunt\u00f3 Quezada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro tema que se populariz\u00f3 fue uno de los m\u00e1s emblem\u00e1ticos del pa\u00eds por su permanencia a trav\u00e9s de los a\u00f1os en el p\u00fablico dominicano: \u201cVamo\u00b4a hablar ingl\u00e9s\u201d, el cual fue escrito por Ramoncito Diaz e interpretado por primera vez en merengue por Milly, Jocelyn y los Vecinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el tema suele ser recordado por la versi\u00f3n en merengue t\u00edpico que grab\u00f3 Manuela Josefa Cabrera Taveras, alias Fefita La Grande, quien lo adopt\u00f3 y lo convirti\u00f3 en un merengue t\u00edpico que nunca ha pasado de moda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La popularidad de canciones como la anterior mencionada, \u201cQui\u00e9reme as\u00ed\u201d y \u201cAngelito negro\u201d motivaron a la grabaci\u00f3n de un disco que inmediatamente se coloc\u00f3 en el gusto popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Darse a conocer en su pa\u00eds era un sue\u00f1o logrado, pero el publico quisqueyano residente en Estados Unidos no se hab\u00eda enterado muy a fondo lo que estaba pasando con la agrupaci\u00f3n. Ese anonimato no tard\u00f3 mucho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La merenguera relat\u00f3 que el lazo entre la di\u00e1spora dominicana y su m\u00fasica lo consigue en las fechas navide\u00f1as de esa \u00e9poca el siglo XX, cuando los dominicanos que resid\u00edan en el extranjero regresaban a pasar la Navidad con su familia y se encuentra con la m\u00fasica de la orquesta posicionada en el gusto popular en Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando los dominicanos ven\u00edan y regresaban a Nueva York se llevaban la bolsita de menta, la botella de ron y el disco que estuviera pegado del momento y por eso mi esposo procuraba que tuvi\u00e9ramos un disco sonando, de ah\u00ed viene la tradici\u00f3n\u201d, declar\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso permiti\u00f3 que los dominicanos que resid\u00edan en suelo norteamericano le conocieran y la hicieran sonar hasta llegar a la radio internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEra un disco por a\u00f1o para la \u00e9poca de diciembre, por eso es que pasamos a constituirnos como la agrupaci\u00f3n de la Navidad. Hubo un disco por a\u00f1o, una gira por a\u00f1o en diciembre\u201d, record\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese transcurso entra los temas \u201cVolvi\u00f3 Juanita\u201d y \u201cLa guacherna\u201d, que se difundi\u00f3 en otros mercados: \u201cNos pegamos en Puerto Rico y ah\u00ed comienza esa tradici\u00f3n navide\u00f1a\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De \u201cVolvi\u00f3 Juanita\u201d refiere que es curioso porque en sus letras no menciona la palabra Navidad: \u201cLa referencia que hace el tema son saquen el lech\u00f3n, saquen los pasteles, la botella de ron, saca el aguardiente vamos a amanecer porque lleg\u00f3 Juanita\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esto, declar\u00f3 que a pesar de que sus merengues no tienen que ver con la Navidad, el dominicano los ha adoptado para esa \u00e9poca festiva del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo eso fue solo el inicio a una larga carrera de \u00e9xitos que le han acompa\u00f1ado durante toda su vida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LA FAMILIA, UN TESORO PRECIADO<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En toda carrera exitosa, se debe pagar el precio de algo y a pesar de que la merenguera dominicana ha dado todo su amor a familia, pas\u00f3 por grandes penas y dif\u00edciles momentos, los cuales tuvo que superar para seguir adelante con su m\u00e1s preciado tesoro, su familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Intentando contener las l\u00e1grimas, record\u00f3 los sacrificios que tuvieron sus hijos durante su ni\u00f1ez al tener una madre que siempre estaba ocupada, resaltando a su hijo menor, quien ten\u00eda solo seis a\u00f1os cuando muri\u00f3 su padre, en 1996.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl pag\u00f3 un precio muy feo en el trayecto de mi carrera, no tenernos en el momento de gran popularidad, no tener un hogar tradicional. Ellos pagaron una cuota muy fuerte\u201d, relat\u00f3 al momento que no pudo frenar sus l\u00e1grimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mostrando su lado vulnerable, narr\u00f3 que sus hijos Miguel y Anthony V\u00e1zquez, quienes le han seguido los pasos en la m\u00fasica, lograron adaptarse a su estilo de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEllos quieren hacer con sus hijos lo que yo no hice con ellos y me lo dicen, y me gusta, pero me duele porque fueron cosas que a ellos les faltaron porque yo tenia que irme a trabajar\u201d, asever\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los procesos m\u00e1s arduos para Milly fue despedir del plano terrenal a su esposo Rafael V\u00e1zquez, con quien cultiv\u00f3 un amor que ha trascendido m\u00e1s all\u00e1 de la muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEse momento fue trascendental en mi vida, cuando muere Rafael yo siempre dec\u00eda: -Rafael era intenso, era 24\/7, los Vecinos, los Vecinos-. Todo lo que a m\u00ed me ha pasado \u00e9l lo so\u00f1\u00f3. \u00c9l dec\u00eda_ -eso viene, eso viene y \u00e9l nunca vio nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c9l se muere en el 1996 y mi mundo se derrumba\u201d, fueron las palabras que enunci\u00f3 al recordar a su fenecido esposo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La perdida de su c\u00f3nyugue le caus\u00f3 depresi\u00f3n, aunque en ese lapso de tiempo tambi\u00e9n comprendi\u00f3 el sentido de la vida, lo que hasta el d\u00eda de hoy hace que no se sienta atra\u00edda por lujos materiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando yo empiezo a salir de cosas y botar cosas, a darlas porque ya Rafael no estaba, ah\u00ed es que t\u00fa te das cuenta del valor de la vida. El valor de la vida est\u00e1 en las cosas que llenan tu alma y tu coraz\u00f3n, todo lo dem\u00e1s es basura\u201d, manifest\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, a finales de 2019, le toc\u00f3 despedir a su hermano Rafael Quezada, quien fue un eslab\u00f3n del merengue junto a la agrupaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este fue un duro golpe para la artista, que confes\u00f3 que \u201cal momento de la perdida de Rafael fue mi perdida m\u00e1s significativa, no solo porque \u00e9l era el menor de cuatro hermanos, sino porque \u00e9l era el gestor de todo esto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo le dec\u00eda a Rafael, relajando: -el d\u00eda que t\u00fa te mueras yo te voy a enterrar a ti con todos esos discos, v\u00e1monos de vacaciones, vamos para Disney con los muchachos. En el entierro yo me acord\u00e9 de esa frase y a m\u00ed me sacaron del cementerio mala\u201d, enunci\u00f3 la int\u00e9rprete de \u201cResistir\u00e1\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A estas alturas, el dinero no es imprescindible para Milly. Otro motor la mueve Ha encontrado la pasi\u00f3n en su rol de abuela, ya que al hablar de sus nietos, en especial de su nieta m\u00e1s peque\u00f1a, pon\u00eda sus emociones a flor de piel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cantante se ve reflejada en su nieta de seis a\u00f1os, con quien ha desarrollado una chispa especial y aunque el idioma natal de la ni\u00f1a es el ingl\u00e9s su abuela busca inculcarle la cultura dominicana y el idioma espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Revel\u00f3 lo alegre que se siente, que su nieta la ver\u00e1 por primera vez sobre un escenario el pr\u00f3ximo 17 de junio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">AMANTE DE LA PLAYA<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quezada se declar\u00f3 una amante de las playas, al momento que mostr\u00f3 su preocupaci\u00f3n por el sargazo que afecta las playas dominicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe provoca preocupaci\u00f3n, hay una degradaci\u00f3n del sistema ambiental y la gente no tiene conciencia de cuidar lo que tenemos\u201d, asever\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como toda apasionada por el mar, dijo que \u201cme encantar\u00eda tener una casita en una playa o en una monta\u00f1a que yo pueda ver el mar de lejitos\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">PUERTAS ABIERTAS AL AMOR<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Milly est\u00e1 abierta a darle una nueva oportunidad al amor, y no pierde las esperanzas de encontrar alguien que conquiste su coraz\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las cosas que le han faltado por hacer, asegura que est\u00e1 volverse a enamorar de la manera que lo hizo de su difunto esposo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVolverme a enamorar y hacer pareja, yo soy de las que le tiene mucho miedo a esa extrema soledad, no a estar sola, pero hay una soledad que entristece. Me encantar\u00eda poder conectar con otra persona\u201d, revel\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que le gustar\u00eda encontrar alguien con experiencias vividas, con una vida hecha que tambi\u00e9n quiera al atardecer tomarse una copa de vino \u201cy re\u00edrnos de nuestros propios defectos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el tema puntualiz\u00f3. \u201cEso ser\u00eda chulo, si viene que venga de Dios si no viene, yo le digo a Dios: &#8211; s\u00edgueme dando cosas que me apasionen\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SU VIDA EN EL CINE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con entusiasmo, la reina dio detalles sobre la pel\u00edcula \u201cMilly, la vida es una\u201d, cinta que retratar\u00e1 los primeros 10 a\u00f1os de su vida musical, as\u00ed como los dif\u00edciles momentos que vivi\u00f3 tras la p\u00e9rdida de su esposo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quezada manifest\u00f3 que la idea nace de la directora Leticia Tonos, quien le propone al artista hacer su autobiograf\u00eda en el cine, pero la primea respuesta fue un rotundo no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo no soy artista que busca notoriedad, ni que me est\u00e9n sacando los trapitos al sol y le dije: ay, no\u201d, expres\u00f3 al referirse las razones de su negaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n asegur\u00f3 hab\u00eda momentos de su vida que no quer\u00eda recordar, como escarbar la muerte de su hermano y su esposo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, termin\u00f3 convenci\u00e9ndose y dio inicio a la cinta, la cual recoger\u00e1 momentos importantes de la vida de Milly, contados por ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas cosas que se van a decir son, obviamente con un colorido para entretener, porque es un musical, pero con un grado de verdad viniendo desde mi persona\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de ser un musical, la merenguera promete ser\u00e1 divertida, inspiracional y con una peque\u00f1a dosis de drama.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRecordar es vivir y duele. Yo se que la gente se va a quedar con un buen sabor de una historia bien contada, entretenida e inspiradora\u201d, afirm\u00f3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ARREPENTIMIENTOS Y ADMIRACIONES<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La vida no es perfecta y mucha gente adulta siente que falt\u00f3 algo por hacer aun estando en la c\u00faspide. A Milagros le habr\u00eda gustado haber hecho una gesti\u00f3n m\u00e1s efectiva de hacer una transici\u00f3n (un crossover) como hizo Gloria Estefan y Mariano Estefan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl esposo de Gloria Estefan tuvo la visi\u00f3n de irse a Europa y pegarse desde de all\u00e1 y regresar pegada que tuvieron en el mercado norteamericano. Nosotros nos quedamos con la m\u00fasica latina y el merengue, viene este arrastre musical junto con el crecimiento de la di\u00e1spora y nos quedamos con eso\u201d, manifest\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 le habr\u00eda gustado lograr lo que ha hecho Romeo Santos, pero con el merengue, que artistas internacionales de habla inglesa canten en espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuiz\u00e1s eso me hubiese gustado, una mejor gesti\u00f3n para hacer el gran crossover\u201d, especific\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto a sus m\u00e9ritos, piensa que \u00a8todo eso han sido bendiciones a\u00f1adidas a lo que es mi pasi\u00f3n por cantar, todo eso yo no lo planifiqu\u00e9, yo no me considero una super cantante, yo me considero bendecida en el sentido de que yo conecto con la gente y eso es sobrenatural\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detr\u00e1s de ese recorrido de 45 a\u00f1os en el merengue que registra Milly Quezada, est\u00e1 la historia de una familia dominicana que se radic\u00f3 en los Estados Unidos y ante las adversidades de chocar con un medioambiente diferente, cuatro hermanos se refugiaron en la m\u00fasica y con latas de pintura y dos palitos dieron inicio a lo que hoy es un referente de identidad musical del pa\u00eds. Risue\u00f1a y cargada de energ\u00eda, Milly convers\u00f3 con periodistas de List\u00edn Diario, donde narr\u00f3 el g\u00e9nesis de su carrera musical, hasta convertirse en \u201cla reina\u201d del merengue de los \u00faltimos 45 a\u00f1os, motivo por el que presentar\u00e1 \u201cViva la Reina Tour\u201d, el s\u00e1bado 17 de junio en el Teatro Nacional Eduardo Brito. Milagros Quezada Borb\u00f3n,&nbsp;nombre de pila de la artista, relat\u00f3 que en los a\u00f1os 70 viv\u00eda en la ciudad de Nueva York, espec\u00edficamente en Washington Heights, donde para esa \u00e9poca la comunidad criolla no era predominante en el lugar. Sin embargo, a pesar de estar envuelta en otra cultura, su patria a\u00f1orada estaba presente en su diario vivir. \u201cEn casa se com\u00eda arroz, habichuela y pollo; en casa se escuchaban los merenguitos y se ve\u00eda mucha programaci\u00f3n del canal 47 Telemundo, aunque en la escuela y otros \u00e1mbitos \u00e9ramos influenciados por el sistema anglosaj\u00f3n\u201d, cont\u00f3 la merenguera. La m\u00fasica estuvo presente en su hogar desde muy peque\u00f1a. Seg\u00fan narr\u00f3, tanto ella como sus hermanos tomaban las latas de pintura y con dos palitos empezaban la creaci\u00f3n casera de ritmos sonoros tropicales. \u201cO tend\u00edamos una s\u00e1bana en un cordel y hac\u00edamos una velada, yo le dec\u00eda a Rafaelito: &#8211; t\u00fa me presentas: \u201cY ahora se\u00f1oras y se\u00f1ores\u2026\u201d. Cuquita y Fosforito eran sus sobrenombres en la ni\u00f1ez, por la chispa que reflejaba. Poco a poco el grupo de hermanos se fue cohesionando y surgiendo lo que en principio se denomin\u00f3 Milly Quezada y los Vecinos y que posteriormente pas\u00f3 a llamarse Milly, Jocelyn y los Vecinos, convirti\u00e9ndose en las primeras dominicanas en conformar una orquesta de merengue. Al grabar su primer disco, el fenecido esposo de Quezada, Rafael V\u00e1zquez, es quien trae la m\u00fasica de la banda al pa\u00eds, lo que abri\u00f3 las puertas a que el publico escuchara por primera vez a una mujer dominicana a ritmo del g\u00e9nero musical aut\u00f3ctono. En ese momento, Milly desconoc\u00eda que estaba adentr\u00e1ndose a un territorio inh\u00f3spito por la mujer. \u201cJohnny Ventura hace las an\u00e9cdotas de la impresi\u00f3n, y Wilfrido Vargas. Incluso, se sintieron como invadidos; esa es la expresi\u00f3n que me contaba Johnny, (quien se preguntaba): &#8211; \u00bfy qu\u00e9 hace esta mujer o c\u00f3mo se atreve esta mujer a pretender entrar en terreno masculino?-, una expresi\u00f3n como machista, jeejeej\u201d, relat\u00f3 la interprete de \u201cSolo contigo\u201d. Ante esto, manifest\u00f3 que los primeros a\u00f1os fueron muy informales y org\u00e1nicos, debido a que tanto ella como sus hermanos ve\u00edan la m\u00fasica como \u201dun desahogo existencial\u201d, al estar en un barrio nuevo, en un pa\u00eds e idioma diferentes. La popularidad de Milly iba creciendo como espuma y en la ausencia de otras figuras en el g\u00e9nero. Su \u00fanico desaf\u00edo era entrar a la radio, lo cual logr\u00f3 por primera vez en el pa\u00eds con el tema musical \u201cT\u00fa sabes\u201d. La reina del merengue indic\u00f3 que el reconocido merenguero Johnny Ventura, al escuchar la canci\u00f3n despert\u00f3 una chispa en \u00e9l. \u201cEl ser mujer, ese gritico (estallido que hace en sus canciones), abri\u00f3 el camino; coincidir con la liberaci\u00f3n femenina tambi\u00e9n\u2026\u201d, apunt\u00f3 Quezada. Otro tema que se populariz\u00f3 fue uno de los m\u00e1s emblem\u00e1ticos del pa\u00eds por su permanencia a trav\u00e9s de los a\u00f1os en el p\u00fablico dominicano: \u201cVamo\u00b4a hablar ingl\u00e9s\u201d, el cual fue escrito por Ramoncito Diaz e interpretado por primera vez en merengue por Milly, Jocelyn y los Vecinos. Sin embargo, el tema suele ser recordado por la versi\u00f3n en merengue t\u00edpico que grab\u00f3 Manuela Josefa Cabrera Taveras, alias Fefita La Grande, quien lo adopt\u00f3 y lo convirti\u00f3 en un merengue t\u00edpico que nunca ha pasado de moda. La popularidad de canciones como la anterior mencionada, \u201cQui\u00e9reme as\u00ed\u201d y \u201cAngelito negro\u201d motivaron a la grabaci\u00f3n de un disco que inmediatamente se coloc\u00f3 en el gusto popular. Darse a conocer en su pa\u00eds era un sue\u00f1o logrado, pero el publico quisqueyano residente en Estados Unidos no se hab\u00eda enterado muy a fondo lo que estaba pasando con la agrupaci\u00f3n. Ese anonimato no tard\u00f3 mucho. La merenguera relat\u00f3 que el lazo entre la di\u00e1spora dominicana y su m\u00fasica lo consigue en las fechas navide\u00f1as de esa \u00e9poca el siglo XX, cuando los dominicanos que resid\u00edan en el extranjero regresaban a pasar la Navidad con su familia y se encuentra con la m\u00fasica de la orquesta posicionada en el gusto popular en Rep\u00fablica Dominicana. \u201cCuando los dominicanos ven\u00edan y regresaban a Nueva York se llevaban la bolsita de menta, la botella de ron y el disco que estuviera pegado del momento y por eso mi esposo procuraba que tuvi\u00e9ramos un disco sonando, de ah\u00ed viene la tradici\u00f3n\u201d, declar\u00f3. Eso permiti\u00f3 que los dominicanos que resid\u00edan en suelo norteamericano le conocieran y la hicieran sonar hasta llegar a la radio internacional. \u201cEra un disco por a\u00f1o para la \u00e9poca de diciembre, por eso es que pasamos a constituirnos como la agrupaci\u00f3n de la Navidad. Hubo un disco por a\u00f1o, una gira por a\u00f1o en diciembre\u201d, record\u00f3. En ese transcurso entra los temas \u201cVolvi\u00f3 Juanita\u201d y \u201cLa guacherna\u201d, que se difundi\u00f3 en otros mercados: \u201cNos pegamos en Puerto Rico y ah\u00ed comienza esa tradici\u00f3n navide\u00f1a\u201d. De \u201cVolvi\u00f3 Juanita\u201d refiere que es curioso porque en sus letras no menciona la palabra Navidad: \u201cLa referencia que hace el tema son saquen el lech\u00f3n, saquen los pasteles, la botella de ron, saca el aguardiente vamos a amanecer porque lleg\u00f3 Juanita\u201d. Ante esto, declar\u00f3 que a pesar de que sus merengues no tienen que ver con la Navidad, el dominicano los ha adoptado para esa \u00e9poca festiva del a\u00f1o. Todo eso fue solo el inicio a una larga carrera de \u00e9xitos que le han acompa\u00f1ado durante toda su vida. [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":90814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-90813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=90813"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90813\/revisions"}],"predecessor-version":[{"id":90815,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90813\/revisions\/90815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/90814"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=90813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=90813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=90813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}