{"id":90918,"date":"2023-06-16T07:08:32","date_gmt":"2023-06-16T11:08:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=90918"},"modified":"2023-06-16T07:08:34","modified_gmt":"2023-06-16T11:08:34","slug":"joselu-y-rodri-guian-a-espana-a-la-final-de-la-liga-de-naciones-al-vencer-a-italia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/joselu-y-rodri-guian-a-espana-a-la-final-de-la-liga-de-naciones-al-vencer-a-italia\/","title":{"rendered":"Joselu y Rodri gu\u00edan a Espa\u00f1a a la final de la Liga de Naciones al vencer a Italia"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/648bc62a4c027.jpeg\" alt=\"\" class=\"wp-image-90919\" width=\"248\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/648bc62a4c027.jpeg 950w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/648bc62a4c027-768x376.jpeg 768w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">riel Jr. de 4-0. El venezolano Gabriel Moreno de 4-2 con una anotada y una empujada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro fin de semana, otra final europea para Rodri. El mediocampista, cuyo gol en Estambul asegur\u00f3 el s\u00e1bado que el Manchester City consiguiera su primer t\u00edtulo de la Liga de Campeones en Estambul, volvi\u00f3 a desempe\u00f1ar un papel protag\u00f3nico, esta vez con la selecci\u00f3n de Espa\u00f1a, que super\u00f3 el jueves 2-1 a Italia para avanzar a la final de la Liga de Naciones, que disputar\u00e1 el domingo ante la Croacia de Luka Modric.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstoy emocionado con mi a\u00f1o&#8230; Me quiero emerger como una figura en la que pueden sentir tranquilidad en la selecci\u00f3n&#8230; y para eso tienes que transmitirla t\u00fa\u201d, coment\u00f3 Rodri, quien jug\u00f3 el Mundial y conquist\u00f3 un triplete de t\u00edtulos hist\u00f3ricos con el Manchester City.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando el tiempo extra parec\u00eda inevitable, Rodri realiz\u00f3 un disparo que fue desviado y le qued\u00f3 a Joselu, quien ingres\u00f3 como suplente. El delantero del espa\u00f1ol, quien se salv\u00f3 apenas del fuera de juego en la acci\u00f3n, marc\u00f3 unos pasos del arco a los 88 minutos del duelo en el estadio del FC Twente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cConsist\u00eda en fe. Creo que todo el equipo ha hecho un partidazo, hemos dominado en la segunda parte. Faltaba que entrase un bal\u00f3n y yo he estado ah\u00ed p\u00edcaro, esperando a ver qu\u00e9 pasaba con ese tiro de Rodri\u201d, dijo Joselu a la TV espa\u00f1ola. \u201cYo estaba confiado en que no era fuera de juego, que estaba saliendo un defensa italiano. Supercontento porque estamos en una final y porque creo que hemos hecho todo para merec\u00e9rnoslo\u201d,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 la segunda oportunidad para Espa\u00f1a para consagrarse en un torneo que la UEFA concibi\u00f3 en 2018. Tambi\u00e9n accedi\u00f3 a la final de 2021, imponi\u00e9ndose ante Italia en las semifinales para luego perder ante Francia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSon partidos de sufrimiento natural. Todo cuesta mucho ante un rival como Italia, pero lo m\u00e1s importante son las prestaciones que hemos ofrecido\u201d, dijo el t\u00e9cnico de Espa\u00f1a Luis de la Fuente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Croacia logr\u00f3 la final al derrotar el mi\u00e9rcoles 4-2 a Holanda al cabo de una pr\u00f3rroga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Espa\u00f1a se adelant\u00f3 a los tres minutos con la complicidad de Leonardo Bonucci. Asediado por Gavi, el capit\u00e1n italiano perdi\u00f3 el bal\u00f3n ante Yeremy Pino, quien defini\u00f3 un placer ante Gianluigi Donnarumma para su segundo gol con la selecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9plica italiana lleg\u00f3 r\u00e1pidamente. Ciro Immobile nivel\u00f3 a los 11 minutos tras un penal que fue se\u00f1alado cuando el remate de Nicolo Zaniolo peg\u00f3 en el brazo de Robin Le Normand, el zaguero de la Real Sociedad que naci\u00f3 en Francia y que debut\u00f3 con La Roja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El triunfo marc\u00f3 tambi\u00e9n un vuelco favorable de la fortuna para De la Fuente, quien reemplaz\u00f3 a Luis Enrique tras el Mundial de Qatar. El estratega lleg\u00f3 al partido presionado, luego de sus dos duelos anteriores \u2014una victoria sufrida ante una Noruega sin Erling Haaland y una derrota por 2-0 ante Escocia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl f\u00fatbol es caprichoso, pero confi\u00f3 en el trabajo y la fe. Yo creo que las cosas as\u00ed salen y no es casualidad\u201d, manifest\u00f3 el entrenador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La final se realiza en R\u00f3terdam. Italia se medir\u00e1 con los holandeses por el tercer sitio, tambi\u00e9n en Enschede.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>riel Jr. de 4-0. El venezolano Gabriel Moreno de 4-2 con una anotada y una empujada. Otro fin de semana, otra final europea para Rodri. El mediocampista, cuyo gol en Estambul asegur\u00f3 el s\u00e1bado que el Manchester City consiguiera su primer t\u00edtulo de la Liga de Campeones en Estambul, volvi\u00f3 a desempe\u00f1ar un papel protag\u00f3nico, esta vez con la selecci\u00f3n de Espa\u00f1a, que super\u00f3 el jueves 2-1 a Italia para avanzar a la final de la Liga de Naciones, que disputar\u00e1 el domingo ante la Croacia de Luka Modric. \u201cEstoy emocionado con mi a\u00f1o&#8230; Me quiero emerger como una figura en la que pueden sentir tranquilidad en la selecci\u00f3n&#8230; y para eso tienes que transmitirla t\u00fa\u201d, coment\u00f3 Rodri, quien jug\u00f3 el Mundial y conquist\u00f3 un triplete de t\u00edtulos hist\u00f3ricos con el Manchester City. Cuando el tiempo extra parec\u00eda inevitable, Rodri realiz\u00f3 un disparo que fue desviado y le qued\u00f3 a Joselu, quien ingres\u00f3 como suplente. El delantero del espa\u00f1ol, quien se salv\u00f3 apenas del fuera de juego en la acci\u00f3n, marc\u00f3 unos pasos del arco a los 88 minutos del duelo en el estadio del FC Twente. \u201cConsist\u00eda en fe. Creo que todo el equipo ha hecho un partidazo, hemos dominado en la segunda parte. Faltaba que entrase un bal\u00f3n y yo he estado ah\u00ed p\u00edcaro, esperando a ver qu\u00e9 pasaba con ese tiro de Rodri\u201d, dijo Joselu a la TV espa\u00f1ola. \u201cYo estaba confiado en que no era fuera de juego, que estaba saliendo un defensa italiano. Supercontento porque estamos en una final y porque creo que hemos hecho todo para merec\u00e9rnoslo\u201d, Ser\u00e1 la segunda oportunidad para Espa\u00f1a para consagrarse en un torneo que la UEFA concibi\u00f3 en 2018. Tambi\u00e9n accedi\u00f3 a la final de 2021, imponi\u00e9ndose ante Italia en las semifinales para luego perder ante Francia. \u201cSon partidos de sufrimiento natural. Todo cuesta mucho ante un rival como Italia, pero lo m\u00e1s importante son las prestaciones que hemos ofrecido\u201d, dijo el t\u00e9cnico de Espa\u00f1a Luis de la Fuente. Croacia logr\u00f3 la final al derrotar el mi\u00e9rcoles 4-2 a Holanda al cabo de una pr\u00f3rroga. Espa\u00f1a se adelant\u00f3 a los tres minutos con la complicidad de Leonardo Bonucci. Asediado por Gavi, el capit\u00e1n italiano perdi\u00f3 el bal\u00f3n ante Yeremy Pino, quien defini\u00f3 un placer ante Gianluigi Donnarumma para su segundo gol con la selecci\u00f3n. La r\u00e9plica italiana lleg\u00f3 r\u00e1pidamente. Ciro Immobile nivel\u00f3 a los 11 minutos tras un penal que fue se\u00f1alado cuando el remate de Nicolo Zaniolo peg\u00f3 en el brazo de Robin Le Normand, el zaguero de la Real Sociedad que naci\u00f3 en Francia y que debut\u00f3 con La Roja. El triunfo marc\u00f3 tambi\u00e9n un vuelco favorable de la fortuna para De la Fuente, quien reemplaz\u00f3 a Luis Enrique tras el Mundial de Qatar. El estratega lleg\u00f3 al partido presionado, luego de sus dos duelos anteriores \u2014una victoria sufrida ante una Noruega sin Erling Haaland y una derrota por 2-0 ante Escocia. \u201cEl f\u00fatbol es caprichoso, pero confi\u00f3 en el trabajo y la fe. Yo creo que las cosas as\u00ed salen y no es casualidad\u201d, manifest\u00f3 el entrenador. La final se realiza en R\u00f3terdam. Italia se medir\u00e1 con los holandeses por el tercer sitio, tambi\u00e9n en Enschede.<\/p>\n","protected":false},"author":9,"featured_media":90919,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-90918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=90918"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90918\/revisions"}],"predecessor-version":[{"id":90920,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90918\/revisions\/90920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/90919"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=90918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=90918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=90918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}