{"id":91019,"date":"2023-06-23T08:11:58","date_gmt":"2023-06-23T12:11:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91019"},"modified":"2023-06-23T08:11:59","modified_gmt":"2023-06-23T12:11:59","slug":"ministerios-agricultura-y-educacion-lanzan-programa-huertos-escolares","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ministerios-agricultura-y-educacion-lanzan-programa-huertos-escolares\/","title":{"rendered":"Ministerios Agricultura y Educaci\u00f3n lanzan programa Huertos Escolares"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/ministros-2-300x203-1.jpg\" alt=\"\" class=\"wp-image-91020\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/ministros-2-300x203-1.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/06\/ministros-2-300x203-1-75x52.jpg 75w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- Los ministerios de Agricultura y Educaci\u00f3n lanzaron el programa \u201cHuertos Escolares\u201d para promover la producci\u00f3n de alimentos sanos y mejorar la calidad de vida de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa busca fortalecer la colaboraci\u00f3n entre alumnos, docentes y padres a trav\u00e9s de actividades como siembras, trasplantes, manejo y recolecci\u00f3n de cultivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este se contempla diferentes tipos de estructuras de producci\u00f3n agr\u00edcola, como la producci\u00f3n a campo abierto, invernaderos tipo casa malla y t\u00faneles, para cultivar una variedad de hortalizas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se implementar\u00e1 un sistema de riego por goteo, que permitir\u00e1 optimizar el uso del agua y garantizar un ahorro importante en su consumo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministro de Agricultura, Limber Cruz, al dirigirse a los presentes asegur\u00f3 que este programa es \u201camigable y sostenible con el medioambiente\u201c , con un mensaje a los m\u00e1s j\u00f3venes y llam\u00f3 a los padres a replicar el programa y sembrar sus patios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1ngel Hern\u00e1ndez, ministro de Educaci\u00f3n, anunci\u00f3 que el programa se extender\u00e1 en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre ambos ministerios se estableci\u00f3 un convenio de colaboraci\u00f3n, en el cual se comprometen a brindar asistencia t\u00e9cnica, capacitaci\u00f3n, suministro de materiales y apoyo log\u00edstico para la implementaci\u00f3n y seguimiento de los huertos escolares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les acompa\u00f1aron en el acto el viceministro de Producci\u00f3n y Mercadeo de Agricultura, ingeniero Eulalio Ram\u00edrez; Julio Cordero y Ligia P\u00e9rez viceministros de educaci\u00f3n, Fernando Campos, director Huertos Escolares, y el Padre Wilfredo Monta\u00f1o, coordinador regente del liceo Panamericano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Los ministerios de Agricultura y Educaci\u00f3n lanzaron el programa \u201cHuertos Escolares\u201d para promover la producci\u00f3n de alimentos sanos y mejorar la calidad de vida de la poblaci\u00f3n. El programa busca fortalecer la colaboraci\u00f3n entre alumnos, docentes y padres a trav\u00e9s de actividades como siembras, trasplantes, manejo y recolecci\u00f3n de cultivos. Con este se contempla diferentes tipos de estructuras de producci\u00f3n agr\u00edcola, como la producci\u00f3n a campo abierto, invernaderos tipo casa malla y t\u00faneles, para cultivar una variedad de hortalizas. Se implementar\u00e1 un sistema de riego por goteo, que permitir\u00e1 optimizar el uso del agua y garantizar un ahorro importante en su consumo. El ministro de Agricultura, Limber Cruz, al dirigirse a los presentes asegur\u00f3 que este programa es \u201camigable y sostenible con el medioambiente\u201c , con un mensaje a los m\u00e1s j\u00f3venes y llam\u00f3 a los padres a replicar el programa y sembrar sus patios. \u00c1ngel Hern\u00e1ndez, ministro de Educaci\u00f3n, anunci\u00f3 que el programa se extender\u00e1 en todo el pa\u00eds. Entre ambos ministerios se estableci\u00f3 un convenio de colaboraci\u00f3n, en el cual se comprometen a brindar asistencia t\u00e9cnica, capacitaci\u00f3n, suministro de materiales y apoyo log\u00edstico para la implementaci\u00f3n y seguimiento de los huertos escolares. Les acompa\u00f1aron en el acto el viceministro de Producci\u00f3n y Mercadeo de Agricultura, ingeniero Eulalio Ram\u00edrez; Julio Cordero y Ligia P\u00e9rez viceministros de educaci\u00f3n, Fernando Campos, director Huertos Escolares, y el Padre Wilfredo Monta\u00f1o, coordinador regente del liceo Panamericano.<\/p>\n","protected":false},"author":9,"featured_media":91020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-91019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91019"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91019\/revisions"}],"predecessor-version":[{"id":91021,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91019\/revisions\/91021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91020"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}