{"id":91133,"date":"2023-07-01T17:49:28","date_gmt":"2023-07-01T21:49:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91133"},"modified":"2023-07-01T17:49:29","modified_gmt":"2023-07-01T21:49:29","slug":"ve-irresponsables-organismos-que-quieren-rd-asuma-crisis-haiti","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ve-irresponsables-organismos-que-quieren-rd-asuma-crisis-haiti\/","title":{"rendered":"Ve \u201cirresponsables\u201d organismos que quieren RD asuma crisis Hait\u00ed"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/b6b7fa28-3f0a-474f-8d7d-af0c1ba72e49.jpeg\" alt=\"\" class=\"wp-image-91134\" width=\"192\" height=\"117\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/b6b7fa28-3f0a-474f-8d7d-af0c1ba72e49.jpeg 1023w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/b6b7fa28-3f0a-474f-8d7d-af0c1ba72e49-300x183.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/b6b7fa28-3f0a-474f-8d7d-af0c1ba72e49-768x468.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/b6b7fa28-3f0a-474f-8d7d-af0c1ba72e49-600x365.jpeg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/b6b7fa28-3f0a-474f-8d7d-af0c1ba72e49-440x270.jpeg 440w\" sizes=\"auto, (max-width: 192px) 100vw, 192px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">PUERTO PLATA.- EL presidente Luis Abinader tild\u00f3 este s\u00e1bado de \u201c irresponsables \u201c a algunos organismos multilaterales internacionales, que -seg\u00fan dijo- nunca han actuado a favor de Hait\u00ed y ahora quieren que rep\u00fablica Dominicana asuma este compromiso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQue act\u00faen con responsabilidad como debieron de actuar ya que, &nbsp;si est\u00e1n tan preocupados por los derechos humanos, deben estarlo por todos los problemas que est\u00e1n sufriendo los ciudadanos pobres de Hait\u00ed en Hait\u00ed, a quienes se les afecta sus Derechos Humanos todos los d\u00edas all\u00ed\u00bb, enfatiz\u00f3. No identific\u00f3 a esos organismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas declaraciones las ofreci\u00f3 el Mandatario durante la inauguraci\u00f3n del destacamento General Juan Nouesit de la segunda brigada &nbsp;de infanter\u00eda del Ej\u00e9rcito, &nbsp;en el municipio de Imbert de la provincia de Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que \u00abla irresponsabilidad de los que no han actuado no se le puede pedir que la asuma la Rep\u00fablica Dominicana\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que respecto al tema migratorio no se le puede solicitar a Rep\u00fablica Dominicana que renuncie a su derechos de aplicar su Constituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQue quede claro que la politica migratoria s\u00f3lo la hacen los dominicanos y por el inter\u00e9s de los dominicanos\u00bb, puntualiz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- EL presidente Luis Abinader tild\u00f3 este s\u00e1bado de \u201c irresponsables \u201c a algunos organismos multilaterales internacionales, que -seg\u00fan dijo- nunca han actuado a favor de Hait\u00ed y ahora quieren que rep\u00fablica Dominicana asuma este compromiso. \u00abQue act\u00faen con responsabilidad como debieron de actuar ya que, &nbsp;si est\u00e1n tan preocupados por los derechos humanos, deben estarlo por todos los problemas que est\u00e1n sufriendo los ciudadanos pobres de Hait\u00ed en Hait\u00ed, a quienes se les afecta sus Derechos Humanos todos los d\u00edas all\u00ed\u00bb, enfatiz\u00f3. No identific\u00f3 a esos organismos. Estas declaraciones las ofreci\u00f3 el Mandatario durante la inauguraci\u00f3n del destacamento General Juan Nouesit de la segunda brigada &nbsp;de infanter\u00eda del Ej\u00e9rcito, &nbsp;en el municipio de Imbert de la provincia de Puerto Plata. Agreg\u00f3 que \u00abla irresponsabilidad de los que no han actuado no se le puede pedir que la asuma la Rep\u00fablica Dominicana\u00bb. Indic\u00f3 que respecto al tema migratorio no se le puede solicitar a Rep\u00fablica Dominicana que renuncie a su derechos de aplicar su Constituci\u00f3n. \u00abQue quede claro que la politica migratoria s\u00f3lo la hacen los dominicanos y por el inter\u00e9s de los dominicanos\u00bb, puntualiz\u00f3.<\/p>\n","protected":false},"author":9,"featured_media":91134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-91133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91133"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91133\/revisions"}],"predecessor-version":[{"id":91135,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91133\/revisions\/91135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91134"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}