{"id":91166,"date":"2023-07-06T06:43:55","date_gmt":"2023-07-06T10:43:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91166"},"modified":"2023-07-06T06:43:58","modified_gmt":"2023-07-06T10:43:58","slug":"desmantelan-red-de-narcotrafico-que-operaba-en-provincias-de-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/desmantelan-red-de-narcotrafico-que-operaba-en-provincias-de-rd\/","title":{"rendered":"Desmantelan red de narcotr\u00e1fico que operaba en provincias de RD"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/carros.jpg\" alt=\"\" class=\"wp-image-91167\" width=\"256\" height=\"143\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/carros.jpg 750w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/carros-300x167.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/carros-600x334.jpg 600w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 6 jul.- Las autoridades desarticularon una estructura criminal dedicada al narcotr\u00e1fico mediante m\u00faltiples allanamientos llevados en el Distrito Nacional, San Crist\u00f3bal y La Vega en una operaci\u00f3n simult\u00e1nea de la Direcci\u00f3n Nacional de Control de Drogas (DNCD), inform\u00f3 este mi\u00e9rcoles la instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agentes antinarc\u00f3ticos y miembros del Ministerio P\u00fablico intervinieron dos compa\u00f1\u00edas de productos agr\u00edcolas, una discoteca, oficinas de pr\u00e9stamos, apartamentos y residencias donde se incautaron de doce veh\u00edculos, diversas prendas, cuatro armas de fuego, 5,234,450 pesos, 3,000 d\u00f3lares, varias computadoras, m\u00e1quinas para prensar, cajas, balanzas, fundas y otros equipos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la operaci\u00f3n para desmantelar esta estructura de narcotr\u00e1fico y lavado de activos, fueron apresadas cuatro personas, nueve est\u00e1n bajo investigaci\u00f3n, mientras otras dos permanecen pr\u00f3fugas, se\u00f1al\u00f3 la DNCD en un comunicado en el que instan a que se entreguen a las autoridades para que respondan por las acusaciones en su contra.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><a href=\"https:\/\/almomento.net\/wp-content\/uploads\/2023\/07\/PHOTO-2023-07-05-16-28-58_7.jpg\"><img decoding=\"async\" src=\"https:\/\/almomento.net\/wp-content\/uploads\/2023\/07\/PHOTO-2023-07-05-16-28-58_7-e1688602904639.jpg\" alt=\"\" class=\"wp-image-885766\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La operaci\u00f3n, que comenz\u00f3 este martes y concluy\u00f3 en la madrugada del mi\u00e9rcoles, supuso la participaci\u00f3n de una decena de fiscales y m\u00e1s de 50 agentes de la DNCD, que realizaron 12 allanamientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Distrito Nacional se intervino la discoteca Silvio Pulpo, dos compa\u00f1\u00edas de inversiones, una residencia en Colinas del Oeste y un apartamento con un taller en el sector Mar\u00eda Auxiliadora, donde fueron sorprendidos varios hombres quemando cajas con l\u00e1minas de una sustancia que se presume es coca\u00edna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En San Crist\u00f3bal se allan\u00f3 la compa\u00f1\u00eda Organic Land, ubicada en Cambita, mientras que en La Vega se intervino una finca en la que se incautaron de diversas cajas con las mismas caracter\u00edsticas que presentaba un reci\u00e9n decomiso de drogas, as\u00ed como equipos y maquinaria para prensar l\u00e1minas de presuntas sustancias narc\u00f3ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El modo de actuar de esta red de narcotr\u00e1fico consist\u00eda en colocar l\u00e1minas con doble fondo rellenas de coca\u00edna en cajas de productos agr\u00edcolas para luego enviarlas a Europa y Estados Unidos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/almomento.net\/wp-content\/uploads\/2023\/07\/droga2222-e1688602168622.jpeg\"><img decoding=\"async\" src=\"https:\/\/almomento.net\/wp-content\/uploads\/2023\/07\/droga2222-e1688602168622.jpeg\" alt=\"\" class=\"wp-image-885764\" \/><\/a><figcaption>Parte de la droga ocupada.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al grupo se le vincula a la incautaci\u00f3n de 270 l\u00e1minas de coca\u00edna con 69.42 kilogramos en el Puerto de Caucedo, que se habr\u00edan enviado en cajas de banano a R\u00f3terdam, entre otros casos que son investigados por los organismos correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades daban seguimiento a esta estructura criminal desde hace seis meses y, tras una ardua labor de inteligencia, se descubri\u00f3 su sistema de operaci\u00f3n, indic\u00f3 la DNCD que junto al Ministerio P\u00fablico contin\u00faa con la investigaci\u00f3n en torno al caso.EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 6 jul.- Las autoridades desarticularon una estructura criminal dedicada al narcotr\u00e1fico mediante m\u00faltiples allanamientos llevados en el Distrito Nacional, San Crist\u00f3bal y La Vega en una operaci\u00f3n simult\u00e1nea de la Direcci\u00f3n Nacional de Control de Drogas (DNCD), inform\u00f3 este mi\u00e9rcoles la instituci\u00f3n. Agentes antinarc\u00f3ticos y miembros del Ministerio P\u00fablico intervinieron dos compa\u00f1\u00edas de productos agr\u00edcolas, una discoteca, oficinas de pr\u00e9stamos, apartamentos y residencias donde se incautaron de doce veh\u00edculos, diversas prendas, cuatro armas de fuego, 5,234,450 pesos, 3,000 d\u00f3lares, varias computadoras, m\u00e1quinas para prensar, cajas, balanzas, fundas y otros equipos. En la operaci\u00f3n para desmantelar esta estructura de narcotr\u00e1fico y lavado de activos, fueron apresadas cuatro personas, nueve est\u00e1n bajo investigaci\u00f3n, mientras otras dos permanecen pr\u00f3fugas, se\u00f1al\u00f3 la DNCD en un comunicado en el que instan a que se entreguen a las autoridades para que respondan por las acusaciones en su contra. La operaci\u00f3n, que comenz\u00f3 este martes y concluy\u00f3 en la madrugada del mi\u00e9rcoles, supuso la participaci\u00f3n de una decena de fiscales y m\u00e1s de 50 agentes de la DNCD, que realizaron 12 allanamientos. En el Distrito Nacional se intervino la discoteca Silvio Pulpo, dos compa\u00f1\u00edas de inversiones, una residencia en Colinas del Oeste y un apartamento con un taller en el sector Mar\u00eda Auxiliadora, donde fueron sorprendidos varios hombres quemando cajas con l\u00e1minas de una sustancia que se presume es coca\u00edna. En San Crist\u00f3bal se allan\u00f3 la compa\u00f1\u00eda Organic Land, ubicada en Cambita, mientras que en La Vega se intervino una finca en la que se incautaron de diversas cajas con las mismas caracter\u00edsticas que presentaba un reci\u00e9n decomiso de drogas, as\u00ed como equipos y maquinaria para prensar l\u00e1minas de presuntas sustancias narc\u00f3ticas. El modo de actuar de esta red de narcotr\u00e1fico consist\u00eda en colocar l\u00e1minas con doble fondo rellenas de coca\u00edna en cajas de productos agr\u00edcolas para luego enviarlas a Europa y Estados Unidos. Al grupo se le vincula a la incautaci\u00f3n de 270 l\u00e1minas de coca\u00edna con 69.42 kilogramos en el Puerto de Caucedo, que se habr\u00edan enviado en cajas de banano a R\u00f3terdam, entre otros casos que son investigados por los organismos correspondientes. Las autoridades daban seguimiento a esta estructura criminal desde hace seis meses y, tras una ardua labor de inteligencia, se descubri\u00f3 su sistema de operaci\u00f3n, indic\u00f3 la DNCD que junto al Ministerio P\u00fablico contin\u00faa con la investigaci\u00f3n en torno al caso.EFE<\/p>\n","protected":false},"author":9,"featured_media":91167,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-91166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91166"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91166\/revisions"}],"predecessor-version":[{"id":91168,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91166\/revisions\/91168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91167"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}