{"id":91172,"date":"2023-07-06T06:47:53","date_gmt":"2023-07-06T10:47:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91172"},"modified":"2023-07-06T06:47:54","modified_gmt":"2023-07-06T10:47:54","slug":"shakira-llama-atencion-por-un-no-en-desfile-de-moda-en-paris-y-el-fao-se-le-pega-a-pique","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/shakira-llama-atencion-por-un-no-en-desfile-de-moda-en-paris-y-el-fao-se-le-pega-a-pique\/","title":{"rendered":"Shakira llama atenci\u00f3n por un \u00abno\u00bb en desfile de moda en Par\u00eds y el fao se le pega a Piqu\u00e9"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/ssaa.jpg\" alt=\"\" class=\"wp-image-91173\" width=\"223\" height=\"153\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/ssaa.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/ssaa-300x206.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/07\/ssaa-75x52.jpg 75w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Shakira asisti\u00f3 por primera vez a la Paris Fashion Week este mi\u00e9rcoles, donde luci\u00f3 un look que desde el primer instante acapar\u00f3 la atenci\u00f3n de todos. La cantante colombiana fue al evento de Alta Costura como invitada de la marca Viktor &amp; Rolf, que pretend\u00eda rememorar los conjuntos m\u00e1s ic\u00f3nicos de sus pasarelas, incluido el que la artista llevaba puesto.&nbsp;<strong>Pero lo m\u00e1s comentado en redes fue un detalle aparentemente relacionado con Gerard Piqu\u00e9,<\/strong>&nbsp;su exmarido, ya que algunos fans insinuaron que ten\u00eda una indirecta para \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La int\u00e9rprete de \u201cAntolog\u00eda\u201d caus\u00f3 sensaci\u00f3n en el recinto La Salle Wagram, a donde lleg\u00f3 para presenciar el desfile de la propuesta oto\u00f1o-invierno 2023 de la firma.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cautiv\u00f3 con un abrigo de la colecci\u00f3n&nbsp;<\/strong>oto\u00f1o-invierno 2008 de la misma empresa, que est\u00e1 liderada por Viktor Horsting y Rolf Snoeren. Lo que m\u00e1s llam\u00f3 la atenci\u00f3n fue que su atuendo ten\u00eda como foco central enormes pliegues que formaban la palabra \u201cno\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Shakira luci\u00f3 una prenda blanca con apliques dorados que destacaron a\u00fan m\u00e1s el contorno de la palabra \u201cno\u201d, ubicada en la parte superior del abrigo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n ten\u00eda un cintur\u00f3n de tela hecho con los mismos materiales que marc\u00f3 la cintura de la estrella latina.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cantante complement\u00f3 su vestido con un bolso de mano brillante, unos tacos con plataforma de Aquazzura en el mismo color y unos anteojos de sol marrones de Y2K, seg\u00fan describi\u00f3 Vogue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Respecto a por qu\u00e9 ser\u00eda una indirecta para Piqu\u00e9,<\/strong>&nbsp;algunos usuarios de redes sociales consideraron que se debe a que Shakira tiene una canci\u00f3n que se llama \u201cNo\u201d, que habla de un rechazo sentimental. El tema tiene versos como \u201cno intentes disculparte, no juegues a insistir, las excusas ya exist\u00edan antes de ti\u201d y \u201cvoy a pedirte que no vuelvas m\u00e1s\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los fan\u00e1ticos no dudaron en expresarle estas teor\u00edas en un posteo que hizo la originaria de Barranquilla. Comparti\u00f3 en Instagram una foto junto a la cantante Camila Cabello, en la que se las ve decir que no con el dedo \u00edndice de la mano, lo que aument\u00f3 las especulaciones de sus seguidores: \u201cLa letra de tu canci\u00f3n est\u00e1 m\u00e1s vigente que nunca\u201d; \u201c\u00bfQu\u00e9 mensaje le estar\u00e1 queriendo enviar Shakira al mundo con este look?\u201d; \u201cShakira no hace nada sin planificar\u201d. No obstante, otros tambi\u00e9n lo relacionaron a que podr\u00eda ser el anuncio de su pr\u00f3xima canci\u00f3n. \u201c\u00bfHar\u00e1s algo junto a Camila?\u201d, le preguntaron.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">UN VIAJE FUGAZ A BARCELONA<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de llegar a la Paris Fashion Week, la celebridad colombiana estuvo algunas horas en Espa\u00f1a para dejar a sus hijos Milan y Sasha junto a su padre. De acuerdo con informaci\u00f3n de la periodista Laura V\u00e1zquez, quien ha seguido la pol\u00e9mica separaci\u00f3n durante varios meses, asegur\u00f3 en su programa Mamarazzis que esto se debi\u00f3 a que Shakira y Piqu\u00e9 llegaron a un nuevo acuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El convenio que firmaron en diciembre de 2022 estipulaba que el exdefensor del FC Barcelona ten\u00eda derecho a estar con sus hijos gran parte del verano, pero parece que ahora esa regla cambi\u00f3. La nueva informaci\u00f3n dicta que los peque\u00f1os estar\u00edan 15 d\u00edas con su padre y 15 d\u00edas junto a su madre, as\u00ed hasta volver al colegio en Miami.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shakira asisti\u00f3 por primera vez a la Paris Fashion Week este mi\u00e9rcoles, donde luci\u00f3 un look que desde el primer instante acapar\u00f3 la atenci\u00f3n de todos. La cantante colombiana fue al evento de Alta Costura como invitada de la marca Viktor &amp; Rolf, que pretend\u00eda rememorar los conjuntos m\u00e1s ic\u00f3nicos de sus pasarelas, incluido el que la artista llevaba puesto.&nbsp;Pero lo m\u00e1s comentado en redes fue un detalle aparentemente relacionado con Gerard Piqu\u00e9,&nbsp;su exmarido, ya que algunos fans insinuaron que ten\u00eda una indirecta para \u00e9l. La int\u00e9rprete de \u201cAntolog\u00eda\u201d caus\u00f3 sensaci\u00f3n en el recinto La Salle Wagram, a donde lleg\u00f3 para presenciar el desfile de la propuesta oto\u00f1o-invierno 2023 de la firma.&nbsp; Cautiv\u00f3 con un abrigo de la colecci\u00f3n&nbsp;oto\u00f1o-invierno 2008 de la misma empresa, que est\u00e1 liderada por Viktor Horsting y Rolf Snoeren. Lo que m\u00e1s llam\u00f3 la atenci\u00f3n fue que su atuendo ten\u00eda como foco central enormes pliegues que formaban la palabra \u201cno\u201d. Shakira luci\u00f3 una prenda blanca con apliques dorados que destacaron a\u00fan m\u00e1s el contorno de la palabra \u201cno\u201d, ubicada en la parte superior del abrigo.&nbsp; Tambi\u00e9n ten\u00eda un cintur\u00f3n de tela hecho con los mismos materiales que marc\u00f3 la cintura de la estrella latina.&nbsp; La cantante complement\u00f3 su vestido con un bolso de mano brillante, unos tacos con plataforma de Aquazzura en el mismo color y unos anteojos de sol marrones de Y2K, seg\u00fan describi\u00f3 Vogue. Respecto a por qu\u00e9 ser\u00eda una indirecta para Piqu\u00e9,&nbsp;algunos usuarios de redes sociales consideraron que se debe a que Shakira tiene una canci\u00f3n que se llama \u201cNo\u201d, que habla de un rechazo sentimental. El tema tiene versos como \u201cno intentes disculparte, no juegues a insistir, las excusas ya exist\u00edan antes de ti\u201d y \u201cvoy a pedirte que no vuelvas m\u00e1s\u201d. Los fan\u00e1ticos no dudaron en expresarle estas teor\u00edas en un posteo que hizo la originaria de Barranquilla. Comparti\u00f3 en Instagram una foto junto a la cantante Camila Cabello, en la que se las ve decir que no con el dedo \u00edndice de la mano, lo que aument\u00f3 las especulaciones de sus seguidores: \u201cLa letra de tu canci\u00f3n est\u00e1 m\u00e1s vigente que nunca\u201d; \u201c\u00bfQu\u00e9 mensaje le estar\u00e1 queriendo enviar Shakira al mundo con este look?\u201d; \u201cShakira no hace nada sin planificar\u201d. No obstante, otros tambi\u00e9n lo relacionaron a que podr\u00eda ser el anuncio de su pr\u00f3xima canci\u00f3n. \u201c\u00bfHar\u00e1s algo junto a Camila?\u201d, le preguntaron. UN VIAJE FUGAZ A BARCELONA Antes de llegar a la Paris Fashion Week, la celebridad colombiana estuvo algunas horas en Espa\u00f1a para dejar a sus hijos Milan y Sasha junto a su padre. De acuerdo con informaci\u00f3n de la periodista Laura V\u00e1zquez, quien ha seguido la pol\u00e9mica separaci\u00f3n durante varios meses, asegur\u00f3 en su programa Mamarazzis que esto se debi\u00f3 a que Shakira y Piqu\u00e9 llegaron a un nuevo acuerdo. El convenio que firmaron en diciembre de 2022 estipulaba que el exdefensor del FC Barcelona ten\u00eda derecho a estar con sus hijos gran parte del verano, pero parece que ahora esa regla cambi\u00f3. La nueva informaci\u00f3n dicta que los peque\u00f1os estar\u00edan 15 d\u00edas con su padre y 15 d\u00edas junto a su madre, as\u00ed hasta volver al colegio en Miami.<\/p>\n","protected":false},"author":9,"featured_media":91173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-91172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91172"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91172\/revisions"}],"predecessor-version":[{"id":91174,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91172\/revisions\/91174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91173"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}