{"id":9139,"date":"2014-10-07T07:46:09","date_gmt":"2014-10-07T11:46:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9139"},"modified":"2014-10-07T07:46:09","modified_gmt":"2014-10-07T11:46:09","slug":"fallece-la-madre-del-merenguero-pena-suazo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fallece-la-madre-del-merenguero-pena-suazo\/","title":{"rendered":"Fallece la madre del merenguero Pe\u00f1a Suazo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/fallece-madre-de-pena-suazo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9140 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/fallece-madre-de-pena-suazo.jpg\" alt=\"fallece madre de pena suazo\" width=\"348\" height=\"232\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/fallece-madre-de-pena-suazo.jpg 348w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/fallece-madre-de-pena-suazo-300x200.jpg 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/a>SANTO DOMINGO.- Falleci\u00f3 en la tarde de hoy, a la edad de 79 a\u00f1os, la se\u00f1ora Sonia Alejandrina viuda Suazo (Do\u00f1a Nina), madre del merenguero Jos\u00e9 Pe\u00f1a Suazo.<!--more--><\/p>\n<p>La dama muri\u00f3 en la Unidad de Cuidados Intensivos de la Plaza de la Salud, donde estaba internada por complicaciones renales, en su condici\u00f3n de paciente diab\u00e9tica.<\/p>\n<p>Pe\u00f1a Suazo inform\u00f3 que su madre hace tiempo venia confrontando problemas cr\u00f3nicos de salud y que hoy en su lecho el cant\u00f3 varias canciones, antes de su fallecimiento. Los restos fueron trasladados a Cotu\u00ed, aunque no se inform\u00f3 la hora de su sepelio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Falleci\u00f3 en la tarde de hoy, a la edad de 79 a\u00f1os, la se\u00f1ora Sonia Alejandrina viuda Suazo (Do\u00f1a Nina), madre del merenguero Jos\u00e9 Pe\u00f1a Suazo.<\/p>\n","protected":false},"author":3,"featured_media":9140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9139"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9139\/revisions"}],"predecessor-version":[{"id":9141,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9139\/revisions\/9141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9140"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}