{"id":91690,"date":"2023-08-05T21:36:59","date_gmt":"2023-08-06T01:36:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91690"},"modified":"2023-08-08T12:46:09","modified_gmt":"2023-08-08T16:46:09","slug":"copa-de-softbol-intermunicipal-se-desborda-de-publico-incluyendo-a-politicos-ofertando-sus-candidaturas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/copa-de-softbol-intermunicipal-se-desborda-de-publico-incluyendo-a-politicos-ofertando-sus-candidaturas\/","title":{"rendered":"Copa de S\u00f3ftbol Intermunicipal se desborda de p\u00fablico, incluyendo a pol\u00edticos ofertando sus candidaturas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/20230805_112134-1024x461.jpg\" alt=\"\" class=\"wp-image-91691\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/20230805_112134-1024x461.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/20230805_112134-300x135.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/20230805_112134-768x346.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/20230805_112134-600x270.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">RANDALLS ISLAND PARK, New York.-La Copa Intermunicipal de S\u00f3ftbol efectuada el pasado s\u00e1bado, la cual gan\u00f3 la novena de Montellano por segundo a\u00f1o consecutivo se convirti\u00f3 en encuentro de jugadores, familiares y amigos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras se realizaba el re\u00f1ido torneo donde todo el mundo pugnaba por llevarse la copa,  fuera de los tres terrenos de juego donde se disputaba la justa cientos de personas se recreaban a todo dar en sus alrededores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unos se deleitaban aupando a sus equipos favoritos, otros jugando domin\u00f3, compartiendo saludos, conversando, escuchando m\u00fasica, bailando, comiendo,  tomando, tirados en el c\u00e9sped y saludando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los pol\u00edticos que aspiran a reelegirse con los alcaldes Mar\u00eda Elena Ramos, Roque Garc\u00eda, Johnny Medina, varios regidores reeleccionistas, otros que aspiran retornar, como es el caso de Carlos Troche y nuevos aspirantes realizaron un procelitismo fren\u00e9tico incesante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se congregaron tantas personas en la locaci\u00f3n 5, donde se jug\u00f3 la copa de s\u00f3ftbol que muchos pensaron que se trataba, un poco m\u00e1s disminuido. del XVII Encuentro de los Puertoplate\u00f1os Residentes en USA y Canad\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De seguir increment\u00e1ndose el n\u00famero de asistentes, en poco tiempo en vez de uno ser\u00e1n dos encuentros, ya que son muchos los que prefieren ir a la Copa de S\u00f3ftbol Intermunicipal que se realiza en Randalls Island Park.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RANDALLS ISLAND PARK, New York.-La Copa Intermunicipal de S\u00f3ftbol efectuada el pasado s\u00e1bado, la cual gan\u00f3 la novena de Montellano por segundo a\u00f1o consecutivo se convirti\u00f3 en encuentro de jugadores, familiares y amigos. Mientras se realizaba el re\u00f1ido torneo donde todo el mundo pugnaba por llevarse la copa, fuera de los tres terrenos de juego donde se disputaba la justa cientos de personas se recreaban a todo dar en sus alrededores. Unos se deleitaban aupando a sus equipos favoritos, otros jugando domin\u00f3, compartiendo saludos, conversando, escuchando m\u00fasica, bailando, comiendo, tomando, tirados en el c\u00e9sped y saludando. Los pol\u00edticos que aspiran a reelegirse con los alcaldes Mar\u00eda Elena Ramos, Roque Garc\u00eda, Johnny Medina, varios regidores reeleccionistas, otros que aspiran retornar, como es el caso de Carlos Troche y nuevos aspirantes realizaron un procelitismo fren\u00e9tico incesante. Se congregaron tantas personas en la locaci\u00f3n 5, donde se jug\u00f3 la copa de s\u00f3ftbol que muchos pensaron que se trataba, un poco m\u00e1s disminuido. del XVII Encuentro de los Puertoplate\u00f1os Residentes en USA y Canad\u00e1. De seguir increment\u00e1ndose el n\u00famero de asistentes, en poco tiempo en vez de uno ser\u00e1n dos encuentros, ya que son muchos los que prefieren ir a la Copa de S\u00f3ftbol Intermunicipal que se realiza en Randalls Island Park.<\/p>\n","protected":false},"author":12,"featured_media":91691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,3],"tags":[],"class_list":["post-91690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91690"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91690\/revisions"}],"predecessor-version":[{"id":91692,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91690\/revisions\/91692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91691"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}