{"id":91742,"date":"2023-08-09T06:50:17","date_gmt":"2023-08-09T10:50:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91742"},"modified":"2023-08-09T06:50:19","modified_gmt":"2023-08-09T10:50:19","slug":"abogados-acusan-3-funcionarios-de-irregularidades-en-pensiones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/abogados-acusan-3-funcionarios-de-irregularidades-en-pensiones\/","title":{"rendered":"Abogados acusan 3 funcionarios de irregularidades en pensiones"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/Miguel-surum-hern\u00e1ndez-.jpg\" alt=\"\" class=\"wp-image-91744\" width=\"219\" height=\"134\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/Miguel-surum-hern\u00e1ndez-.jpg 631w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/Miguel-surum-hern\u00e1ndez--300x185.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/Miguel-surum-hern\u00e1ndez--600x370.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/Miguel-surum-hern\u00e1ndez--440x270.jpg 440w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 9 ago (EFE).- El Colegio de Abogados de la Rep\u00fablica Dominicana (CARD) pidi\u00f3 este martes a la Procuradur\u00eda General de la Rep\u00fablica (PGR) abrir una investigaci\u00f3n penal contra tres funcionarios por supuestas irregularidades en el otorgamiento de pensiones por parte del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los funcionarios son el ministro Administrativo de la Presidencia, Jos\u00e9 Ignacio Paliza; el consultor Jur\u00eddico del Poder Ejecutivo, Antoliano Peralta, y el director General de Jubilaciones y Pensiones, Juan Rosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al hacer su denuncia ante periodistas, el presidente del CARD, Miguel Surun Hern\u00e1ndez, calific\u00f3 de \u00abdolosa\u00bb la atribuci\u00f3n de miles de pensiones estatales, que, a su juicio, \u00abse asignan sin cumplir con los procedimientos establecidos con el expreso prop\u00f3sito de favorecer a relacionados y activistas pol\u00edticos, en perfecta salud y en edad productiva\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno ha otorgado pensiones, en muchos casos, \u00aba personas que nunca han laborado para el sector p\u00fablico y a personas muy por debajo de 60 a\u00f1os de edad y en plena salud, con montos que en muchos casos rondan los 100,000 pesos mensuales\u00bb, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras esto ocurre, afirm\u00f3 el abogado, \u00abservidores p\u00fablicos que dedicaron su vida al Estado dominicano languidecen con pensiones de 10,000 pesos mensuales\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciertamente la ley sobre pensiones contempla este beneficio a personas que no han prestado servicios al Estado, bajo la condici\u00f3n de que padezcan de incapacidad laboral por enfermedad severas y vejez, pero \u00abnunca en favor de activistas pol\u00edticos j\u00f3venes y aptos para trabajar\u00bb como ocurre actualmente, afirm\u00f3. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 9 ago (EFE).- El Colegio de Abogados de la Rep\u00fablica Dominicana (CARD) pidi\u00f3 este martes a la Procuradur\u00eda General de la Rep\u00fablica (PGR) abrir una investigaci\u00f3n penal contra tres funcionarios por supuestas irregularidades en el otorgamiento de pensiones por parte del Estado. Los funcionarios son el ministro Administrativo de la Presidencia, Jos\u00e9 Ignacio Paliza; el consultor Jur\u00eddico del Poder Ejecutivo, Antoliano Peralta, y el director General de Jubilaciones y Pensiones, Juan Rosa. Al hacer su denuncia ante periodistas, el presidente del CARD, Miguel Surun Hern\u00e1ndez, calific\u00f3 de \u00abdolosa\u00bb la atribuci\u00f3n de miles de pensiones estatales, que, a su juicio, \u00abse asignan sin cumplir con los procedimientos establecidos con el expreso prop\u00f3sito de favorecer a relacionados y activistas pol\u00edticos, en perfecta salud y en edad productiva\u00bb. El Gobierno ha otorgado pensiones, en muchos casos, \u00aba personas que nunca han laborado para el sector p\u00fablico y a personas muy por debajo de 60 a\u00f1os de edad y en plena salud, con montos que en muchos casos rondan los 100,000 pesos mensuales\u00bb, dijo. Mientras esto ocurre, afirm\u00f3 el abogado, \u00abservidores p\u00fablicos que dedicaron su vida al Estado dominicano languidecen con pensiones de 10,000 pesos mensuales\u00bb. Ciertamente la ley sobre pensiones contempla este beneficio a personas que no han prestado servicios al Estado, bajo la condici\u00f3n de que padezcan de incapacidad laboral por enfermedad severas y vejez, pero \u00abnunca en favor de activistas pol\u00edticos j\u00f3venes y aptos para trabajar\u00bb como ocurre actualmente, afirm\u00f3. EFE<\/p>\n","protected":false},"author":9,"featured_media":91744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-91742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91742"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91742\/revisions"}],"predecessor-version":[{"id":91745,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91742\/revisions\/91745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91744"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}