{"id":91897,"date":"2023-08-17T07:01:43","date_gmt":"2023-08-17T11:01:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91897"},"modified":"2023-08-17T07:01:44","modified_gmt":"2023-08-17T11:01:44","slug":"danny-rivera-jochy-cuquin-y-boruga-este-viernes-en-santiago","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/danny-rivera-jochy-cuquin-y-boruga-este-viernes-en-santiago\/","title":{"rendered":"Danny Rivera, Jochy, Cuqu\u00edn y Boruga este viernes en Santiago"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/carlos-300x212-1.png\" alt=\"\" class=\"wp-image-91898\" width=\"228\" height=\"161\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/carlos-300x212-1.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/carlos-300x212-1-75x52.png 75w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTIAGO DE LOS CABALLEROS.-&nbsp;&nbsp;El reconocido cantautor puertorrique\u00f1o Danny Rivera llega a la sala principal del Gran Teatro del Cibao de esta ciudad con su gira \u201cSoy como quiero ser\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este viernes 18 de agosto a las 8:00 de la noche se presentar\u00e1 Rivera con su dilatado repertorio de hermosas canciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llegar\u00e1 acompa\u00f1ado de los humoristas Jochy Santos, Felipe Polanco Boruga y Cuqu\u00edn Victoria, quienes abrir\u00e1n el \u201cshow\u201d con rutinas de humor, cuentos y ocurrencias para sacar carcajadas al auditorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo la producci\u00f3n de la empresa Carlos Santos Manager y la direcci\u00f3n musical del maestro Leo Pimentel, el espect\u00e1culo promete ser una combinaci\u00f3n de humor, buena m\u00fasica, recuerdos y nostalgia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDespu\u00e9s de tres a\u00f1os de ausencia de Danny, estamos listos para ofrecer el mejor espect\u00e1culo que se ha presentado en los \u00faltimos tiempos para Santiago y todo el Cibao\u201d, explic\u00f3 Santos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi pueblo es mi pueblo\u201d, \u201cMadrigal\u201d, \u201cTanto deseo de ella\u201d, \u201cQue dar\u00eda yo\u201d, \u201cLuc\u00eda\u201d, \u201cAmar o morir\u201d, \u201cAmada amante\u201d, \u201cPara decir adi\u00f3s \u201c, entre otras formar\u00e1n parte de la propuesta musical que presentar\u00e1 Danny Rivera en el Gran Teatro del Cibao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las boletas est\u00e1n a la venta en Uepa Tickets y en la boleter\u00eda del Gran Teatro del Cibao.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTIAGO DE LOS CABALLEROS.-&nbsp;&nbsp;El reconocido cantautor puertorrique\u00f1o Danny Rivera llega a la sala principal del Gran Teatro del Cibao de esta ciudad con su gira \u201cSoy como quiero ser\u201d. Este viernes 18 de agosto a las 8:00 de la noche se presentar\u00e1 Rivera con su dilatado repertorio de hermosas canciones. Llegar\u00e1 acompa\u00f1ado de los humoristas Jochy Santos, Felipe Polanco Boruga y Cuqu\u00edn Victoria, quienes abrir\u00e1n el \u201cshow\u201d con rutinas de humor, cuentos y ocurrencias para sacar carcajadas al auditorio. Bajo la producci\u00f3n de la empresa Carlos Santos Manager y la direcci\u00f3n musical del maestro Leo Pimentel, el espect\u00e1culo promete ser una combinaci\u00f3n de humor, buena m\u00fasica, recuerdos y nostalgia. \u201cDespu\u00e9s de tres a\u00f1os de ausencia de Danny, estamos listos para ofrecer el mejor espect\u00e1culo que se ha presentado en los \u00faltimos tiempos para Santiago y todo el Cibao\u201d, explic\u00f3 Santos. \u201cMi pueblo es mi pueblo\u201d, \u201cMadrigal\u201d, \u201cTanto deseo de ella\u201d, \u201cQue dar\u00eda yo\u201d, \u201cLuc\u00eda\u201d, \u201cAmar o morir\u201d, \u201cAmada amante\u201d, \u201cPara decir adi\u00f3s \u201c, entre otras formar\u00e1n parte de la propuesta musical que presentar\u00e1 Danny Rivera en el Gran Teatro del Cibao. Las boletas est\u00e1n a la venta en Uepa Tickets y en la boleter\u00eda del Gran Teatro del Cibao.<\/p>\n","protected":false},"author":9,"featured_media":91898,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-91897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91897"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91897\/revisions"}],"predecessor-version":[{"id":91899,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91897\/revisions\/91899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91898"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}