{"id":9192,"date":"2014-10-08T01:12:40","date_gmt":"2014-10-08T05:12:40","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9192"},"modified":"2014-10-08T01:12:40","modified_gmt":"2014-10-08T05:12:40","slug":"robert-downey-jr-confirma-que-marvel-esta-preparando-iron-man-4","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/robert-downey-jr-confirma-que-marvel-esta-preparando-iron-man-4\/","title":{"rendered":"Robert Downey Jr. confirma que Marvel est\u00e1 preparando Iron Man 4"},"content":{"rendered":"<p data-textannotation-id=\"fb0e789a10a84b55dcf195c987c5095d\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Robert-Downey-Jr.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9194 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Robert-Downey-Jr.jpg\" alt=\"Robert Downey Jr\" width=\"636\" height=\"264\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Robert-Downey-Jr.jpg 636w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Robert-Downey-Jr-300x124.jpg 300w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/a><br \/>\nHace poco m\u00e1s de un mes, Robert Downey Jr. aseguraba que no hab\u00eda ning\u00fan plan para rodar una cuarta parte de Iron Man. Hoy parece que s\u00ed que hab\u00eda un plan despu\u00e9s de todo, porque el actor acaba de confirmar que Iron Man 4 s\u00ed est\u00e1 en camino.<!--more--><\/p>\n<p data-textannotation-id=\"6b7d194419c4fb865bf2f7ae000a1613\">Downey Jr. ha explicado en el programa de TV The Ellen Show que Marvel y \u00e9l est\u00e1n en plenas conversaciones para su participaci\u00f3n en Iron Man 4. \u00abSe que hay un mont\u00f3n de pel\u00edculas a\u00fan por llegar, y que tienen un mont\u00f3n de ideas para el personaje. Estamos ahora mismo en mitad de una negociaci\u00f3n\u00bb ha explicado el actor.<\/p>\n<p data-textannotation-id=\"00501accdaf5515fbbcfaeaa8b052fcf\">Lo que Downey Jr. no ha especificado es si volver\u00e1 a repetir como protagonista absoluto en el papel del millonario Tony Stark, o su presencia se ver\u00e1 limitada a un rol menor y dejar\u00e1 que sea otro el que vista la armadura. Probablemente esta cuesti\u00f3n se dirima a golpe de talonario. [v\u00eda<a href=\"https:\/\/www.youtube.com\/channel\/UCp0hYYBW6IMayGgR-WeoCvQ\" target=\"_blank\">The Ellen Show<\/a>]<\/p>\n<p class=\"has-media media-640\" data-textannotation-id=\"73831b38eae99bf51b6a3ae083d70ada\"><span class=\"clear-both flex-video widescreen\"><iframe loading=\"lazy\" id=\"youtube-s-xMtOBSBAI\" class=\"youtube\" src=\"http:\/\/www.youtube.com\/embed\/s-xMtOBSBAI?wmode=transparent&amp;rel=0&amp;autohide=1&amp;showinfo=0&amp;enablejsapi=1\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-chomp-id=\"s-xMtOBSBAI\"><\/iframe><\/span><\/p>\n<p data-textannotation-id=\"288e4eebc2440f498347f7b8a76e9469\">\n","protected":false},"excerpt":{"rendered":"<p>Hace poco m\u00e1s de un mes, Robert Downey Jr. aseguraba que no hab\u00eda ning\u00fan plan para rodar una cuarta parte de Iron Man. Hoy parece que s\u00ed que hab\u00eda un plan despu\u00e9s de todo, porque el actor acaba de confirmar que Iron Man 4 s\u00ed est\u00e1 en camino.<\/p>\n","protected":false},"author":3,"featured_media":9194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9192"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9192\/revisions"}],"predecessor-version":[{"id":9195,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9192\/revisions\/9195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9194"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}