{"id":91931,"date":"2023-08-19T08:14:45","date_gmt":"2023-08-19T12:14:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=91931"},"modified":"2023-08-19T08:14:48","modified_gmt":"2023-08-19T12:14:48","slug":"gobierno-llama-a-funcionarios-a-no-utilizar-recursos-del-estado-para-la-campana-electoral","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gobierno-llama-a-funcionarios-a-no-utilizar-recursos-del-estado-para-la-campana-electoral\/","title":{"rendered":"Gobierno llama a funcionarios a no utilizar recursos del Estado para la campa\u00f1a electoral"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e010c266c58.jpeg\" alt=\"\" class=\"wp-image-91932\" width=\"258\" height=\"125\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e010c266c58.jpeg 950w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e010c266c58-300x147.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e010c266c58-768x376.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e010c266c58-600x294.jpeg 600w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno Dominicano hizo un llamado a los funcionarios del Estado a qu\u00e9 no utilicen los recursos del Estado para el proceso de campa\u00f1a electoral tanto interno como externo de cara a los pr\u00f3ximos torneos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a declaraciones otorgadas por el ministro Administrativo de la Presidencia, Jos\u00e9 Ignacio Paliza, el presidente Luis Abinader manifest\u00f3 \u00abmuy claro\u00bb su compromiso con la \u00abtransparencia\u00bb de todas las instituciones durante este proceso de proselitismo electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab(El Presidente) fue enf\u00e1tico en el hecho de que nosotros, cada uno de los funcionarios p\u00fablicos, tenemos que ser celadores, tenemos que ser vigilantes, tenemos que ser cuidadosos y no solo con nuestras actuaciones si no tambi\u00e9n con las actuaciones de aquellos que son dependientes de nuestros ministros y nuestros directores\u00bb, expres\u00f3 Paliza, quien fue el encargado de hablar a la prensa tras la finalizaci\u00f3n de una reuni\u00f3n del Consejo de Gobierno que se extendi\u00f3 por m\u00e1s de una hora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MAP emitir\u00e1 circular<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paliza agreg\u00f3 que el Ministerio de Administraci\u00f3n P\u00fablica (MAP) estar\u00eda emitiendo una circular el pr\u00f3ximo lunes con relaci\u00f3n a la participaci\u00f3n de funcionarios en las contiendas electorales, aunque no confirm\u00f3 que la misma ser\u00eda para \u00absugerirles licencias\u00bb a los funcionarios del gobierno central que ostenten un cargo electivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se recuerda que el art\u00edculo 80 de la ley 41-08 sobre Funci\u00f3n P\u00fablica se\u00f1ala que os funcionarios p\u00fablicos tienen prohibido servir a intereses de partidos en el ejercicio de sus funciones y, en consecuencia, organizar o dirigir demostraciones, pronunciar discursos partidistas, distribuir propaganda de car\u00e1cter pol\u00edtico, o solicitar fondos para los mismos fines, as\u00ed como utilizar con este objetivo los bienes y fondos de la instituci\u00f3n; adem\u00e1s de inducir u obligar a sus subalternos a participar en actividades pol\u00edticas o partidistas, sea en su provecho o en provecho de terceros; las mismas son catalogadas en primer lugar como faltas de segundo grado, las cuales de acuerdo a la misma ley, conlleva la suspensi\u00f3n de funciones por 90 d\u00edas, sin disfrute de sueldo como sanci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que el art\u00edculo 25 de la ley 33-18 sobre Partidos, Movimientos y Agrupaciones Pol\u00edticas proh\u00edbe que se impongan requerimientos o deducciones; el uso en \u00abcualquier forma\u00bb de los bienes y los fondos p\u00fablicos pertenecientes a cualesquiera de los niveles o instancias del Estado, en provecho propio o de los candidatos por ellos postulados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las declaraciones se producen luego de que a inicios del mes de junio, el Gobierno anunci\u00f3 que los mecanismos de control de gastos ser\u00e1n endurecidos durante la \u00e9poca de proselitismo electoral.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno Dominicano hizo un llamado a los funcionarios del Estado a qu\u00e9 no utilicen los recursos del Estado para el proceso de campa\u00f1a electoral tanto interno como externo de cara a los pr\u00f3ximos torneos. De acuerdo a declaraciones otorgadas por el ministro Administrativo de la Presidencia, Jos\u00e9 Ignacio Paliza, el presidente Luis Abinader manifest\u00f3 \u00abmuy claro\u00bb su compromiso con la \u00abtransparencia\u00bb de todas las instituciones durante este proceso de proselitismo electoral. \u00ab(El Presidente) fue enf\u00e1tico en el hecho de que nosotros, cada uno de los funcionarios p\u00fablicos, tenemos que ser celadores, tenemos que ser vigilantes, tenemos que ser cuidadosos y no solo con nuestras actuaciones si no tambi\u00e9n con las actuaciones de aquellos que son dependientes de nuestros ministros y nuestros directores\u00bb, expres\u00f3 Paliza, quien fue el encargado de hablar a la prensa tras la finalizaci\u00f3n de una reuni\u00f3n del Consejo de Gobierno que se extendi\u00f3 por m\u00e1s de una hora. MAP emitir\u00e1 circular Paliza agreg\u00f3 que el Ministerio de Administraci\u00f3n P\u00fablica (MAP) estar\u00eda emitiendo una circular el pr\u00f3ximo lunes con relaci\u00f3n a la participaci\u00f3n de funcionarios en las contiendas electorales, aunque no confirm\u00f3 que la misma ser\u00eda para \u00absugerirles licencias\u00bb a los funcionarios del gobierno central que ostenten un cargo electivo. Se recuerda que el art\u00edculo 80 de la ley 41-08 sobre Funci\u00f3n P\u00fablica se\u00f1ala que os funcionarios p\u00fablicos tienen prohibido servir a intereses de partidos en el ejercicio de sus funciones y, en consecuencia, organizar o dirigir demostraciones, pronunciar discursos partidistas, distribuir propaganda de car\u00e1cter pol\u00edtico, o solicitar fondos para los mismos fines, as\u00ed como utilizar con este objetivo los bienes y fondos de la instituci\u00f3n; adem\u00e1s de inducir u obligar a sus subalternos a participar en actividades pol\u00edticas o partidistas, sea en su provecho o en provecho de terceros; las mismas son catalogadas en primer lugar como faltas de segundo grado, las cuales de acuerdo a la misma ley, conlleva la suspensi\u00f3n de funciones por 90 d\u00edas, sin disfrute de sueldo como sanci\u00f3n. Mientras que el art\u00edculo 25 de la ley 33-18 sobre Partidos, Movimientos y Agrupaciones Pol\u00edticas proh\u00edbe que se impongan requerimientos o deducciones; el uso en \u00abcualquier forma\u00bb de los bienes y los fondos p\u00fablicos pertenecientes a cualesquiera de los niveles o instancias del Estado, en provecho propio o de los candidatos por ellos postulados. Las declaraciones se producen luego de que a inicios del mes de junio, el Gobierno anunci\u00f3 que los mecanismos de control de gastos ser\u00e1n endurecidos durante la \u00e9poca de proselitismo electoral.&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":91932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-91931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=91931"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91931\/revisions"}],"predecessor-version":[{"id":91933,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/91931\/revisions\/91933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/91932"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=91931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=91931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=91931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}