{"id":92071,"date":"2023-08-29T07:19:05","date_gmt":"2023-08-29T11:19:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=92071"},"modified":"2023-08-29T07:19:19","modified_gmt":"2023-08-29T11:19:19","slug":"whatsapp-planea-facilitar-el-envio-de-imagenes-y-videos-con-calidad-original-en-formato-de-documento","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/whatsapp-planea-facilitar-el-envio-de-imagenes-y-videos-con-calidad-original-en-formato-de-documento\/","title":{"rendered":"WhatsApp planea facilitar el env\u00edo de im\u00e1genes y v\u00eddeos con calidad original en formato de documento"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e670b5ce6d4.jpeg\" alt=\"\" class=\"wp-image-92072\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e670b5ce6d4.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e670b5ce6d4-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e670b5ce6d4-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/08\/64e670b5ce6d4-600x400.jpeg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">WhatsApp est\u00e1 trabajando en la<strong>&nbsp;implementaci\u00f3n de una opci\u00f3n de env\u00edo de fotograf\u00edas y v\u00eddeos&nbsp;<\/strong>en su calidad original, es decir, sin compresi\u00f3n en el archivo, que se compartir\u00e1n en formato de documento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plataforma de mensajer\u00eda instant\u00e1nea ya lanz\u00f3 el env\u00edo de im\u00e1genes con calidad HD el pasado 17 de agosto, lo que permit\u00eda a los usuarios enviar fotos sin perder resoluci\u00f3n tanto en dispositivos Android como en iOS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, tal y como se pudo conocer la semana pasada, la red social propiedad de Meta ha comenzado a implementar la\u00a0<strong>misma opci\u00f3n para el env\u00edo de v\u00eddeos,<\/strong>\u00a0que ya pueden ser compartidos en calidad HD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque estas opciones facilitan la transmisi\u00f3n de archivos con una mayor resoluci\u00f3n,&nbsp;<strong>la plataforma sigue realizando una ligera compresi\u00f3n en el archivo,&nbsp;<\/strong>que evita que sea el contenido en su calidad original.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, WhatsApp sigue en mejorar las opciones de env\u00edo y facilitar el proceso a los usuarios, con una nueva opci\u00f3n con la que permitir\u00e1 compartir im\u00e1genes y v\u00eddeos en su calidad original, sin comprimir el documento independientemente de su tama\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo ha podido comprobar WaBetaInfo, que ha detectado que la plataforma est\u00e1 trabajando en un nuevo bot\u00f3n del men\u00fa de documentos que permite seleccionar directamente fotos y v\u00eddeos de la galer\u00eda del dispositivo para enviarlos en un chat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta opci\u00f3n, las im\u00e1genes o v\u00eddeos seleccionados se compartir\u00e1n con<strong>&nbsp;su calidad original en formato de documento,<\/strong>&nbsp;algo que ya se pod\u00eda hacer previamente, pero que ahora es m\u00e1s sencillo al facilitar el acceso a las fotograf\u00edas y v\u00eddeos directamente desde la galer\u00eda, sin tener que acceder a trav\u00e9s de carpetas de archivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el momento, este mismo medio ha se\u00f1alado que se trata de una funci\u00f3n en desarrollo identificada en la \u00faltima actualizaci\u00f3n beta de la aplicaci\u00f3n para Android versi\u00f3n 2.23.18.12, por lo que a\u00fan no est\u00e1 disponible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WhatsApp est\u00e1 trabajando en la&nbsp;implementaci\u00f3n de una opci\u00f3n de env\u00edo de fotograf\u00edas y v\u00eddeos&nbsp;en su calidad original, es decir, sin compresi\u00f3n en el archivo, que se compartir\u00e1n en formato de documento. La plataforma de mensajer\u00eda instant\u00e1nea ya lanz\u00f3 el env\u00edo de im\u00e1genes con calidad HD el pasado 17 de agosto, lo que permit\u00eda a los usuarios enviar fotos sin perder resoluci\u00f3n tanto en dispositivos Android como en iOS. Asimismo, tal y como se pudo conocer la semana pasada, la red social propiedad de Meta ha comenzado a implementar la\u00a0misma opci\u00f3n para el env\u00edo de v\u00eddeos,\u00a0que ya pueden ser compartidos en calidad HD. Aunque estas opciones facilitan la transmisi\u00f3n de archivos con una mayor resoluci\u00f3n,&nbsp;la plataforma sigue realizando una ligera compresi\u00f3n en el archivo,&nbsp;que evita que sea el contenido en su calidad original. Sin embargo, WhatsApp sigue en mejorar las opciones de env\u00edo y facilitar el proceso a los usuarios, con una nueva opci\u00f3n con la que permitir\u00e1 compartir im\u00e1genes y v\u00eddeos en su calidad original, sin comprimir el documento independientemente de su tama\u00f1o. As\u00ed lo ha podido comprobar WaBetaInfo, que ha detectado que la plataforma est\u00e1 trabajando en un nuevo bot\u00f3n del men\u00fa de documentos que permite seleccionar directamente fotos y v\u00eddeos de la galer\u00eda del dispositivo para enviarlos en un chat. Con esta opci\u00f3n, las im\u00e1genes o v\u00eddeos seleccionados se compartir\u00e1n con&nbsp;su calidad original en formato de documento,&nbsp;algo que ya se pod\u00eda hacer previamente, pero que ahora es m\u00e1s sencillo al facilitar el acceso a las fotograf\u00edas y v\u00eddeos directamente desde la galer\u00eda, sin tener que acceder a trav\u00e9s de carpetas de archivos. Por el momento, este mismo medio ha se\u00f1alado que se trata de una funci\u00f3n en desarrollo identificada en la \u00faltima actualizaci\u00f3n beta de la aplicaci\u00f3n para Android versi\u00f3n 2.23.18.12, por lo que a\u00fan no est\u00e1 disponible.<\/p>\n","protected":false},"author":9,"featured_media":92072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-92071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=92071"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92071\/revisions"}],"predecessor-version":[{"id":92073,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92071\/revisions\/92073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/92072"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=92071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=92071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=92071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}