{"id":92149,"date":"2023-09-03T07:29:26","date_gmt":"2023-09-03T11:29:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=92149"},"modified":"2023-09-03T07:29:28","modified_gmt":"2023-09-03T11:29:28","slug":"hospital-hugo-mendoza-habilita-mas-camas-para-atender-pacientes-con-dengue-tiene-62-ingresados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hospital-hugo-mendoza-habilita-mas-camas-para-atender-pacientes-con-dengue-tiene-62-ingresados\/","title":{"rendered":"Hospital Hugo Mendoza habilita m\u00e1s camas para atender pacientes con dengue; tiene 62 ingresados"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/64f0a570ca1c5.jpeg\" alt=\"\" class=\"wp-image-92150\" width=\"206\" height=\"100\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/64f0a570ca1c5.jpeg 950w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/64f0a570ca1c5-300x147.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/64f0a570ca1c5-768x376.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/64f0a570ca1c5-600x294.jpeg 600w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En el hospital pedi\u00e1trico Hugo Mendoza habilitaron m\u00e1s camas por el incremento de casos de dengue en el pa\u00eds, y el s\u00e1bado&nbsp;<strong>ten\u00edan 62 pacientes ingresados con sospecha de dengue<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n la ofreci\u00f3 a List\u00edn Diario la pediatra Francia Lapaix, gerente de emergencia de ese centro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl hospital Hugo Mendoza se ha preparado en habilitar m\u00e1s camas para poder darle respuesta a la demanda de la poblaci\u00f3n\u201d, detall\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que&nbsp;<strong>regularmente tienen una media de 20 ingresos diarios<\/strong>&nbsp;y que en los pr\u00f3ximos d\u00edas podr\u00eda aumentar por las lluvias dejadas por la tormenta Franklin y los criaderos del mosquito transmisor de la enfermedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos una media. Ingresamos hasta 20 pacientes diarios con dengue. El hospital cuenta con las pruebas para hacer un diagn\u00f3stico m\u00e1s temprano\u201d, explic\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dijo que los ingresos m\u00e1s frecuentes son los casos de dengue con signos de alarma<\/strong>, que son hidratados y se les administra paracetamol para la fiebre y se dan las atenciones que ameritan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEst\u00e1n los casos espor\u00e1dicos, son choques por dengue, que son dengues graves que es la minor\u00eda, afortunadamente\u201d, dijo la especialista.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al preguntarle si se trata de dengue hemorr\u00e1gico, respondi\u00f3: \u201cYa no hay dengue hemorr\u00e1gico, la nueva clasificaci\u00f3n es dengue con signos de alarma, sin signos de alarma se manejan en la casa y choque por dengue\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor incidencia de dengue est\u00e1 entre pacientes de 6 a 16 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se\u00f1ales que hay que prestarle atenci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ales que hay que prestar atenci\u00f3n, cuando el paciente presenta&nbsp;<strong>fiebre, dolor de cabeza, dolor en el cuerpo, dolor abdominal y v\u00f3mito<\/strong>&nbsp;hay que acudir inmediatamente al centro m\u00e1s cercano para que sea evaluado por el personal m\u00e9dico y que se determine si tiene un probable dengue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se trata espec\u00edficamente de dolor abdominal y v\u00f3mito, deben ser hospitalizados, porque son signos de alarma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Cuando confunden dengue con otra enfermedad<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Rep\u00fablica Dominicana en&nbsp;<strong>2022 murieron 39 pacientes por dengue y hasta la semana epidemiol\u00f3gica 32<\/strong>, que abarca hasta el 12 de agosto del a\u00f1o en curso, se hab\u00edan registrado cinco defunciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Otro diagn\u00f3stico que se parece al del dengue<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfCon qu\u00e9 diagn\u00f3stico se puede confundir o hacer diagn\u00f3stico diferencial? A la leptospirosis y la malaria, son diagn\u00f3sticos que debemos hacer diferencial y tambi\u00e9n sepsis. Es importante diferenciar si es un dengue o<strong>&nbsp;que est\u00e1 cruzando con una sepsis infeccioso bacteriano\u201d, concluy\u00f3.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recomendaciones<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Evitar almacenamiento de agua y si tienen que hacerlo mantener los envases tapados, porque el mosquito se reproduce en agua limpia.&nbsp;<strong>Fumigar es importante la zona donde viven y evitar acumular<\/strong>&nbsp;objetos que sirvan de criaderos, como son las gomas viejas en los patios y otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el hospital pedi\u00e1trico Hugo Mendoza habilitaron m\u00e1s camas por el incremento de casos de dengue en el pa\u00eds, y el s\u00e1bado&nbsp;ten\u00edan 62 pacientes ingresados con sospecha de dengue. La informaci\u00f3n la ofreci\u00f3 a List\u00edn Diario la pediatra Francia Lapaix, gerente de emergencia de ese centro.&nbsp; \u201cEl hospital Hugo Mendoza se ha preparado en habilitar m\u00e1s camas para poder darle respuesta a la demanda de la poblaci\u00f3n\u201d, detall\u00f3.&nbsp; Indic\u00f3 que&nbsp;regularmente tienen una media de 20 ingresos diarios&nbsp;y que en los pr\u00f3ximos d\u00edas podr\u00eda aumentar por las lluvias dejadas por la tormenta Franklin y los criaderos del mosquito transmisor de la enfermedad. \u201cTenemos una media. Ingresamos hasta 20 pacientes diarios con dengue. El hospital cuenta con las pruebas para hacer un diagn\u00f3stico m\u00e1s temprano\u201d, explic\u00f3.&nbsp; Dijo que los ingresos m\u00e1s frecuentes son los casos de dengue con signos de alarma, que son hidratados y se les administra paracetamol para la fiebre y se dan las atenciones que ameritan. \u201cEst\u00e1n los casos espor\u00e1dicos, son choques por dengue, que son dengues graves que es la minor\u00eda, afortunadamente\u201d, dijo la especialista.&nbsp; Al preguntarle si se trata de dengue hemorr\u00e1gico, respondi\u00f3: \u201cYa no hay dengue hemorr\u00e1gico, la nueva clasificaci\u00f3n es dengue con signos de alarma, sin signos de alarma se manejan en la casa y choque por dengue\u201d. La mayor incidencia de dengue est\u00e1 entre pacientes de 6 a 16 a\u00f1os. Se\u00f1ales que hay que prestarle atenci\u00f3n Se\u00f1ales que hay que prestar atenci\u00f3n, cuando el paciente presenta&nbsp;fiebre, dolor de cabeza, dolor en el cuerpo, dolor abdominal y v\u00f3mito&nbsp;hay que acudir inmediatamente al centro m\u00e1s cercano para que sea evaluado por el personal m\u00e9dico y que se determine si tiene un probable dengue. Cuando se trata espec\u00edficamente de dolor abdominal y v\u00f3mito, deben ser hospitalizados, porque son signos de alarma. Cuando confunden dengue con otra enfermedad En Rep\u00fablica Dominicana en&nbsp;2022 murieron 39 pacientes por dengue y hasta la semana epidemiol\u00f3gica 32, que abarca hasta el 12 de agosto del a\u00f1o en curso, se hab\u00edan registrado cinco defunciones. Otro diagn\u00f3stico que se parece al del dengue \u201c\u00bfCon qu\u00e9 diagn\u00f3stico se puede confundir o hacer diagn\u00f3stico diferencial? A la leptospirosis y la malaria, son diagn\u00f3sticos que debemos hacer diferencial y tambi\u00e9n sepsis. Es importante diferenciar si es un dengue o&nbsp;que est\u00e1 cruzando con una sepsis infeccioso bacteriano\u201d, concluy\u00f3. Recomendaciones Evitar almacenamiento de agua y si tienen que hacerlo mantener los envases tapados, porque el mosquito se reproduce en agua limpia.&nbsp;Fumigar es importante la zona donde viven y evitar acumular&nbsp;objetos que sirvan de criaderos, como son las gomas viejas en los patios y otros.<\/p>\n","protected":false},"author":9,"featured_media":92150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-92149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=92149"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92149\/revisions"}],"predecessor-version":[{"id":92151,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92149\/revisions\/92151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/92150"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=92149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=92149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=92149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}