{"id":9232,"date":"2014-10-10T01:52:39","date_gmt":"2014-10-10T05:52:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9232"},"modified":"2014-10-08T08:15:50","modified_gmt":"2014-10-08T12:15:50","slug":"7-maneras-efectivas-para-retrasar-el-paso-del-tiempo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/7-maneras-efectivas-para-retrasar-el-paso-del-tiempo\/","title":{"rendered":"7 maneras efectivas para retrasar el paso del tiempo"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/hombres-belleza-tratamientos-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9233 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/hombres-belleza-tratamientos-2.jpg\" alt=\"hombres-belleza-tratamientos-2\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/hombres-belleza-tratamientos-2.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/hombres-belleza-tratamientos-2-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>Encontrar la clave de la juventud eterna ha sido durante a\u00f1os el reto de los cient\u00edficos y el anhelo de millones de personas. Y aunque a\u00fan no aparece, si se sabe que hay diversas maneras para retrasar el paso del tiempo, que de hecho, est\u00e1n m\u00e1s al alcance de tu <label>mano<\/label> de lo que parece.<!--more--><\/p>\n<p>De acuerdo con Kelly Traver, m\u00e9dico y profesora de la Universidad de Stanford, las personas tenemos mucho m\u00e1s control del que pensamos en los factores que afectan el envejecimiento.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>\u00abUnos pocos <label>cambios<\/label> de <label>estilo<\/label> de <label>vida<\/label> simples y podr\u00e1s lucir diez a\u00f1os m\u00e1s joven, sentirte mejor, y obtener tu energ\u00eda de vuelta\u201d.<\/p>\n<p>Claves de la <label>fuente<\/label> de la juventud<\/p>\n<p>As\u00ed que en vista de que retrasar el envejecimiento est\u00e1s m\u00e1s en tus manos que de la ciencia, te presentamos las maneras m\u00e1s efectivas que nos encontramos, para que comiences a implementarlas desde este momento.<\/p>\n<p>1. Hacer ejercicio. Si a\u00fan no lo haces, no esperes, 30 minutos al d\u00eda de actividad f\u00edsica es la recomendaci\u00f3n. Jes\u00fas del Pozo-Cruz, investigador de la Universidad Pablo de Olavide, Espa\u00f1a, indica que el ejercicio tiene un impacto en los niveles de la coenzima Q10.<\/p>\n<p>\u00abLa actividad f\u00edsica puede utilizarse como terapia frente al descenso de la actividad antioxidante asociada con el envejecimiento y en la prevenci\u00f3n de las complicaciones cardiovasculares o cr\u00f3nicas que lo acompa\u00f1an\u201d.<\/p>\n<p>2. Ser feliz. Penny Kendall-Reed, directora de terapias naturales del Urban Wellness Clinic, afirma que una de las mejores maneras de retrasar el paso de los a\u00f1os es sonre\u00edr, ser feliz y libre de estr\u00e9s. Las sustancias que salen del cuerpo cuando est\u00e1s estresado y triste causan estragos.<\/p>\n<p>3. Reducir el az\u00facar. Cynthia Kenyon, directora del centro sobre la biolog\u00eda del envejecimiento de la Universidad de California, indica que una dieta baja en calor\u00edas y az\u00facar ayuda a vivir m\u00e1s y mejor, porque est\u00e1 comprobado que los niveles altos de glucosa reducen la esperanza de vida.<\/p>\n<p>4. Comer m\u00e1s pescados y verduras. La baja carga gluc\u00e9mica de las verduras sin almid\u00f3n, como la alcachofa, apio o el pepino, y los \u00e1cidos grasos Omega 3 del pescado son algunos de los elementos que interact\u00faan para retrasar el envejecimiento de la piel, afirma Berry Sears, cient\u00edfico autor de \u201dLa Dieta de la Zona\u201d.<\/p>\n<p>5. Cocinar con aceite de oliva. Y si de evitar sufrir enfermedades se trata, diversos estudios han demostrado que los fuertes antioxidantes de este aceite pueden ayudar contra los infartos de miocardio y otros padecimientos relacionados con la edad.<\/p>\n<p>Un estudio publicado en el New England Journal of Medicine, indica que incluso una dieta mediterr\u00e1nea rica en aceite de oliva reduce el riesgo de ataque card\u00edaco ya accidente cerebrovascular hasta en 30%.<\/p>\n<p>6. Viajar lo m\u00e1s posible. Francisco Mora Teruel, profesor de fisiolog\u00eda humana de la Universidad Complutense de Madrid, indica que para prevenir el envejecimiento cerebral es viajar, esto permite romper la rutina, aprender, memorizar, modificar el cerebro para que est\u00e9 activo y joven.<\/p>\n<p>7. Tener m\u00e1s sexo. Un estudio de 10 a\u00f1os realizado por David Weeks, sic\u00f3logo cl\u00ednico y ex jefe de la sicolog\u00eda de la vejez del Royal Edinburgh Hospital, revela que las personas de entre 40 y 50 a\u00f1os que reportaron tener relaciones sexuales 50% m\u00e1s veces que otros encuestados, luc\u00edan de cinco a siete a\u00f1os m\u00e1s j\u00f3venes.<\/p>\n<p>Esto puede deberse a que el cuerpo libera hormona del crecimiento humano durante las relaciones sexuales, lo que hace que la piel se vea m\u00e1s el\u00e1stica.<\/p>\n<p>En la medida de tus posibilidades trata de implementar la mayor\u00eda de estas maneras para retrasar el paso del tiempo, ver\u00e1s que con esfuerzo y consistencia, comenzar\u00e1s a ver resultados favorables para tu salud.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/bienestar.salud180.com\/bienestar180\/7-maneras-efectivas-para-retrasar-el-paso-del-tiempo\">Salud 180<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Encontrar la clave de la juventud eterna ha sido durante a\u00f1os el reto de los cient\u00edficos y el anhelo de millones de personas. Y aunque a\u00fan no aparece, si se sabe que hay diversas maneras para retrasar el paso del tiempo, que de hecho, est\u00e1n m\u00e1s al alcance de tu mano de lo que parece.<\/p>\n","protected":false},"author":3,"featured_media":9233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9232"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9232\/revisions"}],"predecessor-version":[{"id":9234,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9232\/revisions\/9234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9233"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}