{"id":9241,"date":"2014-10-10T17:00:25","date_gmt":"2014-10-10T21:00:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9241"},"modified":"2014-10-08T08:34:05","modified_gmt":"2014-10-08T12:34:05","slug":"los-mejores-alimentos-anti-inflamatorios","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-mejores-alimentos-anti-inflamatorios\/","title":{"rendered":"Los mejores alimentos anti-inflamatorios"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Torcedura-inflamacion-500x325.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9245 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Torcedura-inflamacion-500x325.jpg\" alt=\"Torcedura-inflamacion-500x325\" width=\"500\" height=\"325\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Torcedura-inflamacion-500x325.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Torcedura-inflamacion-500x325-300x195.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/Torcedura-inflamacion-500x325-400x260.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>Es bien sabido que junto con los medicamentos vienen aparejadas varias advertencias y efectos secundarios en la mayor\u00eda de los casos. Hablando en espec\u00edfico de los antiinflamatorios, los principales efectos adversos ser\u00edan la irritaci\u00f3n de la mucosa g\u00e1strica y trastornos en la digesti\u00f3n (pesadez, ardor), entre otros. Aunque algunos, si se usan de forma continua, pueden producir otros problemas m\u00e1s serios.<!--more--><\/p>\n<p>Este tipo de medicamentos se utiliza generalmente para aliviar el dolor, reducir la inflamaci\u00f3n y bajar la fiebre. Por lo cual son muy requeridos, si bien en caso de utilizarlos bajo la supervisi\u00f3n m\u00e9dica y prestando atenci\u00f3n a las indicaciones que acompa\u00f1an al producto no deber\u00edan presentarse inconvenientes.<\/p>\n<h2>Causas de dolor e inflamaci\u00f3n m\u00e1s comunes<\/h2>\n<p>Los casos m\u00e1s comunes en los cu\u00e1les generalmente utilizamos antiinflamatorios son:<\/p>\n<ul>\n<li>Dolores de cabeza<\/li>\n<li>Golpes y contusiones<\/li>\n<li>Artrosis<\/li>\n<li>Artritis<\/li>\n<li>Inflamaci\u00f3n de tendones<\/li>\n<li>Dolores menstruales<\/li>\n<li>Torceduras, etc.<\/li>\n<\/ul>\n<p>El peligro radica en el uso indiscriminado de este u otro tipo de medicamento. Siempre debes respetar las dosis, el tiempo entre tomas, el periodo de tratamiento y las condiciones en qu\u00e9 tomarlo (normalmente, no debe ser estando en ayunas), comentar a tu m\u00e9dico sobre las enfermedades o alteraciones de salud que padezcas, de esa manera \u00e9l sabr\u00e1 recomendar en cada caso la medicaci\u00f3n espec\u00edfica evitando da\u00f1os colaterales.<\/p>\n<p>Usualmente, ante la primera manifestaci\u00f3n de dolor o inflamaci\u00f3n vamos a la farmacia a pedir alg\u00fan medicamento que calme nuestro malestar lo m\u00e1s r\u00e1pido posible, pero si eres de las personas que prefieres los remedios naturales antes que los qu\u00edmicos, debes seguir leyendo esta informaci\u00f3n en la que mencionaremos ciertos alimentos y hierbas medicinales que poseen efectos desinflamantes, los puedes consumir en caso de estar sufriendo de alg\u00fan dolor o inflamaci\u00f3n y tambi\u00e9n de manera preventiva. Si la inflamaci\u00f3n es severa consulta tu m\u00e9dico de confianza.<\/p>\n<h2>Alimentos anti-inflamatorios<\/h2>\n<ol>\n<li>Pescados: sardinas, salm\u00f3n, caballa, trucha son algunos de los pescados con propiedades para reducir la inflamaci\u00f3n, gracias a su alto contenido en Omega 3, cuyo consumo diario act\u00faa como antiinflamatorio, sobre todo, en caso de dolencias cr\u00f3nicas y\/o asociadas a la edad.<\/li>\n<li>Aceite de oliva extra virgen<\/li>\n<li>Frutos secos: nueces, avellanas, almendras<\/li>\n<li>Papaya<\/li>\n<li>Ar\u00e1ndanos<\/li>\n<li>Pi\u00f1a<\/li>\n<li>Pl\u00e1tanos<\/li>\n<li>Br\u00f3coli<\/li>\n<li>Berro<\/li>\n<\/ol>\n<p><strong>Para que los alimentos puedan actuar de manera positiva disminuyendo la inflamaci\u00f3n y el dolor debes consumirlos con regularidad.<\/strong> Recuerda siempre incluirlos en tu mesa diaria, de manera variada a fin de abastecer tus requerimientos. Aseg\u00farate de adquirirlos en un lugar de confianza.<\/p>\n<h2>Hierbas medicinales \u00fatiles<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"imagen-redonda aligncenter wp-image-17601 size-full\" src=\"http:\/\/cdn.mejorconsalud.com\/wp-content\/uploads\/2014\/01\/Jengibre.jpg\" alt=\"Jengibre\" width=\"500\" height=\"327\" \/><\/p>\n<p><strong>Dentro de las hierbas medicinales aliadas contra el dolor y la inflamaci\u00f3n podemos mencionar a:<\/strong><\/p>\n<ul>\n<li>Manzanilla: el t\u00e9 de manzanilla resulta oportuno para aliviar procesos inflamatorios y dolorosos. Excelente para aliviar dolores menstruales.<\/li>\n<li>Cal\u00e9ndula: muy utilizada para tratar inflamaciones de garganta, de las enc\u00edas. Puedes realizar gargarismos con una infusi\u00f3n de las flores. Sobre golpes e inflamaciones aplicar hojas y flores machacadas.<\/li>\n<li>Jengibre: planta antiinflamatoria por excelencia. Puedes beber su infusi\u00f3n o incluirla directamente en tu alimentaci\u00f3n como condimento si es de tu agrado su sabor.<\/li>\n<li>Salvia: se utiliza principalmente para realizar gargarismos en caso de dolor de garganta, tambi\u00e9n como enjuague para molestias en la boca. \u00a0Muy \u00fatil en dolores menstruales, pues adem\u00e1s ayuda a regular los trastornos hormonales de la mujer.<\/li>\n<li>Malva: muy \u00fatil para inflamaciones en general, en especial las de la boca. Puedes beber la infusi\u00f3n de esta planta.<\/li>\n<\/ul>\n<p><strong>Nunca suspendas tu medicaci\u00f3n para sustituirla por remedios naturales.<\/strong> Siempre comenta con tu m\u00e9dico sobre tu intenci\u00f3n de consumir plantas medicinales para evitar interacciones con los medicamentos.<\/p>\n<p>En caso de que la inflamaci\u00f3n que sufras no disminuya o empeore, se presentefiebre, consulta con un profesional. <strong>Los tratamientos naturales tambi\u00e9n presentan contraindicaciones y precauciones que debes conocer.<\/strong><\/p>\n<p>Una alimentaci\u00f3n saludable es vital para que tu organismo logre defenderse de las agresiones y enfermedades a las que estamos expuestos d\u00eda a d\u00eda. Un cuerpo bien nutrido contar\u00e1 con un sistema inmune fuerte y capaz de ser una barrera exitosa frente a diferentes microorganismos causantes de las afecciones de salud.<\/p>\n<blockquote><p><strong>Nota:<\/strong> La automedicaci\u00f3n no es para nada recomendada, consumir indiscriminadamente cualquier tipo de medicamentos ocasionar\u00e1 efectos negativos en tu salud. Elige mejor preservar tu salud con alimentos nutritivos y buenos h\u00e1bitos de vida.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Es bien sabido que junto con los medicamentos vienen aparejadas varias advertencias y efectos secundarios en la mayor\u00eda de los casos. Hablando en espec\u00edfico de los antiinflamatorios, los principales efectos adversos ser\u00edan la irritaci\u00f3n de la mucosa g\u00e1strica y trastornos en la digesti\u00f3n (pesadez, ardor), entre otros. Aunque algunos, si se usan de forma continua, pueden producir otros problemas m\u00e1s serios.<\/p>\n","protected":false},"author":3,"featured_media":9245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9241"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9241\/revisions"}],"predecessor-version":[{"id":9246,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9241\/revisions\/9246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9245"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}