{"id":92470,"date":"2023-09-26T06:55:47","date_gmt":"2023-09-26T10:55:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=92470"},"modified":"2023-09-26T06:55:48","modified_gmt":"2023-09-26T10:55:48","slug":"multan-millonaria-a-clinica-cobro-anticipo-afiliados-a-sistema-salud","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/multan-millonaria-a-clinica-cobro-anticipo-afiliados-a-sistema-salud\/","title":{"rendered":"Multan millonaria a cl\u00ednica cobr\u00f3 anticipo afiliados a Sistema Salud"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"179\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/sisaril-300x179-1.png\" alt=\"\" class=\"wp-image-92471\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- La Superintendencia de Salud y Riesgos Laborales (SISALRIL) sancion\u00f3 con el pago de m\u00e1s de un mill\u00f3n 642 mil pesos al&nbsp;Centro M\u00e9dico Vista del Jard\u00edn&nbsp;por cobro indebido de dep\u00f3sito o anticipo a dos afiliados al&nbsp;Sistema de Seguridad Social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La SISALRIL explic\u00f3 que&nbsp;se otorg\u00f3 un plazo de 10 d\u00edas h\u00e1biles&nbsp;para que el centro de salud proceda a realizar el pago total de la multa ante la Tesorer\u00eda de la Seguridad Social (TSS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jes\u00fas Feris Iglesias, superintendente de Salud y Riesgos Laborales, hab\u00eda informado que ese organismo procedi\u00f3 a sancionar, por primera vez desde su creaci\u00f3n, a un centro m\u00e9dico del Distrito Nacional,&nbsp;con una multa ascendente a 101 salarios m\u00ednimos, por cobro indebido de dep\u00f3sito o anticipo a dos afiliados al Sistema de Seguridad Social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que la sanci\u00f3n se estableci\u00f3 mediante la resoluci\u00f3n DJ-GIS No. 0022-2023, tras encontrar hallazgos suficientes que tipifican la pr\u00e1ctica prohibida de cobros indebidos a dos afiliados, mediante la solicitud de dep\u00f3sitos o pagos anticipados como requisito de acceso a la atenci\u00f3n m\u00e9dica, violando as\u00ed la ley de Seguridad Social y sus normas complementarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>UNA PRACTICA DENUNCIADA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cobro de dep\u00f3sito o anticipo para ofrecer atenciones m\u00e9dicas de emergencia es una pr\u00e1ctica que tiene a\u00f1os denunci\u00e1ndose en el pa\u00eds y una causa de queja frecuente entre los afiliados al Seguro Familiar de Salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que es la primera vez que la Sisalril&nbsp;sanciona un centro m\u00e9dico reconocido en todo su per\u00edodo de funcionamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que ello se hizo en cumplimiento de las funciones otorgadas por la Ley No. 87-01 y la Res. No.563 del Consejo Nacional de la Seguridad Social (CNSS), la Superintendencia de Salud y Riesgos Laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que durante el per\u00edodo 2022-2023 se han presentado la mayor cantidad de sanciones en la historia de la instituci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- La Superintendencia de Salud y Riesgos Laborales (SISALRIL) sancion\u00f3 con el pago de m\u00e1s de un mill\u00f3n 642 mil pesos al&nbsp;Centro M\u00e9dico Vista del Jard\u00edn&nbsp;por cobro indebido de dep\u00f3sito o anticipo a dos afiliados al&nbsp;Sistema de Seguridad Social. La SISALRIL explic\u00f3 que&nbsp;se otorg\u00f3 un plazo de 10 d\u00edas h\u00e1biles&nbsp;para que el centro de salud proceda a realizar el pago total de la multa ante la Tesorer\u00eda de la Seguridad Social (TSS). Jes\u00fas Feris Iglesias, superintendente de Salud y Riesgos Laborales, hab\u00eda informado que ese organismo procedi\u00f3 a sancionar, por primera vez desde su creaci\u00f3n, a un centro m\u00e9dico del Distrito Nacional,&nbsp;con una multa ascendente a 101 salarios m\u00ednimos, por cobro indebido de dep\u00f3sito o anticipo a dos afiliados al Sistema de Seguridad Social. Explic\u00f3 que la sanci\u00f3n se estableci\u00f3 mediante la resoluci\u00f3n DJ-GIS No. 0022-2023, tras encontrar hallazgos suficientes que tipifican la pr\u00e1ctica prohibida de cobros indebidos a dos afiliados, mediante la solicitud de dep\u00f3sitos o pagos anticipados como requisito de acceso a la atenci\u00f3n m\u00e9dica, violando as\u00ed la ley de Seguridad Social y sus normas complementarias. UNA PRACTICA DENUNCIADA El cobro de dep\u00f3sito o anticipo para ofrecer atenciones m\u00e9dicas de emergencia es una pr\u00e1ctica que tiene a\u00f1os denunci\u00e1ndose en el pa\u00eds y una causa de queja frecuente entre los afiliados al Seguro Familiar de Salud. Dijo que es la primera vez que la Sisalril&nbsp;sanciona un centro m\u00e9dico reconocido en todo su per\u00edodo de funcionamiento. Explic\u00f3 que ello se hizo en cumplimiento de las funciones otorgadas por la Ley No. 87-01 y la Res. No.563 del Consejo Nacional de la Seguridad Social (CNSS), la Superintendencia de Salud y Riesgos Laborales. Destac\u00f3 que durante el per\u00edodo 2022-2023 se han presentado la mayor cantidad de sanciones en la historia de la instituci\u00f3n.<\/p>\n","protected":false},"author":9,"featured_media":92471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-92470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=92470"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92470\/revisions"}],"predecessor-version":[{"id":92472,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92470\/revisions\/92472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/92471"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=92470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=92470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=92470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}