{"id":92524,"date":"2023-09-29T08:20:41","date_gmt":"2023-09-29T12:20:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=92524"},"modified":"2023-09-29T08:20:42","modified_gmt":"2023-09-29T12:20:42","slug":"junior-lake-enfocado-para-darle-campeonato-beisbol-a-los-leones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/junior-lake-enfocado-para-darle-campeonato-beisbol-a-los-leones\/","title":{"rendered":"Junior Lake enfocado para darle campeonato beisbol a los Leones"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/Junior-Lake-9.jpg\" alt=\"\" class=\"wp-image-92525\" width=\"224\" height=\"149\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/Junior-Lake-9.jpg 444w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/09\/Junior-Lake-9-300x200.jpg 300w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BOCA CHICA.-&nbsp;<\/strong>Junior Lake, una de las principales adquisiciones de los Leones del Escogido en la nueva agencia libre de la Lidom, declar\u00f3 que est\u00e1 dispuesto a hacer lo que sea necesario para que el equipo rojo se corone campe\u00f3n en la temporada 2023-24 de la Lidom.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jardinero se report\u00f3 este jueves a la concentraci\u00f3n del Escogido que se realiza en la academia de los Yankees de Nueva York y expres\u00f3 su felicidad y agradecimiento hacia Dios y los Leones por la oportunidad que le ha brindado el equipo de la capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi disposici\u00f3n siempre estar\u00e1 para ganar. No me importan los resultados a mi favor. Si el equipo sale victorioso, me sentir\u00e9 satisfecho\u201d, indic\u00f3 el oriundo de San Pedro de Macor\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn cualquier cosa que pueda ayudar, sea tocando la bola, robando una base o defendiendo, ah\u00ed estar\u00e9 para cualquier situaci\u00f3n en la que el m\u00e1nager (V\u00edctor Est\u00e9vez) me necesite\u201d, sigui\u00f3 diciendo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lake, de 33 a\u00f1os, ha sido uno de los peloteros m\u00e1s productivos del b\u00e9isbol dominicano desde su debut con las Estrellas Orientales en el campeonato 2009-10. Acumula 31 cuadrangulares, 169 producidas, 97 bases robadas y un OPS de .742 en 429 encuentros de Serie Regular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n ha sido ganador de seis premios Guante de Oro y ha sido miembro de los equipos campeones de las \u00c1guilas Cibae\u00f1as (2017-18), las Estrellas (2018-19) y los Toros del Este (2019-20).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junior insisti\u00f3 en que su presencia en el Escogido es con el prop\u00f3sito de que en el venidero torneo el equipo levante el trofeo de campeones nacionales, algo que no se logra desde el 2015-16.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el ambiente en el Escogido, Lake se\u00f1al\u00f3 que se siente como en casa, ya que conoce a muchos de los peloteros que integran la n\u00f3mina escarlata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHe jugado con la mayor\u00eda, Jimmy (Paredes), Asencio (Yeison), Rijo (Wendell), Sandber (Pimentel), con muchos de ellos. Tenemos una relaci\u00f3n de compa\u00f1eros y estoy contento de estar aqu\u00ed junto a ellos\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Santos tambi\u00e9n se report\u00f3<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de Lake, el lanzador V\u00edctor Santos se report\u00f3 a las pr\u00e1cticas de los Leones. El derecho ha sido un lanzador muy \u00fatil para el Escogido en las \u00faltimas dos campa\u00f1as, con rendimiento de 4-1, 2.32 de efectividad, 1.26 de WHIP y 32 ponches en 31.0 episodios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Juegos Pretemporada<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Leones del Escogido jugar\u00e1n siete partidos de preparaci\u00f3n previo al inicio de la temporada 2023-24 de la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos de ellos ser\u00e1n contra las \u00c1guilas Cibae\u00f1as, dos frente a los Toros del Este, uno ante los Tigres del Licey y otros dos contra universidades de primera divisi\u00f3n de los Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gerencia de Operaciones de los Leones inform\u00f3 que el lunes 2 de octubre el club jugar\u00e1 contra la Universidad de Dallas Baptist a las 11:00 de la ma\u00f1ana, en el complejo de los Yankees de Nueva York.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la academia de los Yankees, que sirve como base de entrenamiento del Escogido, los Leones se medir\u00e1n el s\u00e1bado 7 a la Universidad de Louisville, el martes 10 contra los Toros y el mi\u00e9rcoles 11 frente a los Tigres, en encuentros que tambi\u00e9n comenzar\u00e1n a las 11:00 de la ma\u00f1ana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego el equipo capitalino chocar\u00e1 con las \u00c1guilas el viernes 13 a las 12:00 del medio d\u00eda, tambi\u00e9n en el complejo de los Yankees.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El s\u00e1bado 14, el Escogido visitar\u00e1 el estadio Francisco A. Micheli para enfrentar a los Toros a las 11:00 de la ma\u00f1ana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00faltimo juego de pretemporada ser\u00e1 el lunes 16 de octubre a las 12:00 del mediod\u00eda en el estadio Cibao, frente a las \u00c1guilas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Leones abrir\u00e1n su temporada regular el pr\u00f3ximo 19 de octubre en el estadio Quisqueya Juan Marichal, donde jugar\u00e1n como equipo visitante contra el Licey.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOCA CHICA.-&nbsp;Junior Lake, una de las principales adquisiciones de los Leones del Escogido en la nueva agencia libre de la Lidom, declar\u00f3 que est\u00e1 dispuesto a hacer lo que sea necesario para que el equipo rojo se corone campe\u00f3n en la temporada 2023-24 de la Lidom. El jardinero se report\u00f3 este jueves a la concentraci\u00f3n del Escogido que se realiza en la academia de los Yankees de Nueva York y expres\u00f3 su felicidad y agradecimiento hacia Dios y los Leones por la oportunidad que le ha brindado el equipo de la capital. \u201cMi disposici\u00f3n siempre estar\u00e1 para ganar. No me importan los resultados a mi favor. Si el equipo sale victorioso, me sentir\u00e9 satisfecho\u201d, indic\u00f3 el oriundo de San Pedro de Macor\u00eds. \u201cEn cualquier cosa que pueda ayudar, sea tocando la bola, robando una base o defendiendo, ah\u00ed estar\u00e9 para cualquier situaci\u00f3n en la que el m\u00e1nager (V\u00edctor Est\u00e9vez) me necesite\u201d, sigui\u00f3 diciendo. Lake, de 33 a\u00f1os, ha sido uno de los peloteros m\u00e1s productivos del b\u00e9isbol dominicano desde su debut con las Estrellas Orientales en el campeonato 2009-10. Acumula 31 cuadrangulares, 169 producidas, 97 bases robadas y un OPS de .742 en 429 encuentros de Serie Regular. Tambi\u00e9n ha sido ganador de seis premios Guante de Oro y ha sido miembro de los equipos campeones de las \u00c1guilas Cibae\u00f1as (2017-18), las Estrellas (2018-19) y los Toros del Este (2019-20). Junior insisti\u00f3 en que su presencia en el Escogido es con el prop\u00f3sito de que en el venidero torneo el equipo levante el trofeo de campeones nacionales, algo que no se logra desde el 2015-16. Sobre el ambiente en el Escogido, Lake se\u00f1al\u00f3 que se siente como en casa, ya que conoce a muchos de los peloteros que integran la n\u00f3mina escarlata. \u201cHe jugado con la mayor\u00eda, Jimmy (Paredes), Asencio (Yeison), Rijo (Wendell), Sandber (Pimentel), con muchos de ellos. Tenemos una relaci\u00f3n de compa\u00f1eros y estoy contento de estar aqu\u00ed junto a ellos\u201d, explic\u00f3. Santos tambi\u00e9n se report\u00f3 Adem\u00e1s de Lake, el lanzador V\u00edctor Santos se report\u00f3 a las pr\u00e1cticas de los Leones. El derecho ha sido un lanzador muy \u00fatil para el Escogido en las \u00faltimas dos campa\u00f1as, con rendimiento de 4-1, 2.32 de efectividad, 1.26 de WHIP y 32 ponches en 31.0 episodios. Juegos Pretemporada Los Leones del Escogido jugar\u00e1n siete partidos de preparaci\u00f3n previo al inicio de la temporada 2023-24 de la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana. Dos de ellos ser\u00e1n contra las \u00c1guilas Cibae\u00f1as, dos frente a los Toros del Este, uno ante los Tigres del Licey y otros dos contra universidades de primera divisi\u00f3n de los Estados Unidos. La gerencia de Operaciones de los Leones inform\u00f3 que el lunes 2 de octubre el club jugar\u00e1 contra la Universidad de Dallas Baptist a las 11:00 de la ma\u00f1ana, en el complejo de los Yankees de Nueva York. En la academia de los Yankees, que sirve como base de entrenamiento del Escogido, los Leones se medir\u00e1n el s\u00e1bado 7 a la Universidad de Louisville, el martes 10 contra los Toros y el mi\u00e9rcoles 11 frente a los Tigres, en encuentros que tambi\u00e9n comenzar\u00e1n a las 11:00 de la ma\u00f1ana. Luego el equipo capitalino chocar\u00e1 con las \u00c1guilas el viernes 13 a las 12:00 del medio d\u00eda, tambi\u00e9n en el complejo de los Yankees. El s\u00e1bado 14, el Escogido visitar\u00e1 el estadio Francisco A. Micheli para enfrentar a los Toros a las 11:00 de la ma\u00f1ana. El \u00faltimo juego de pretemporada ser\u00e1 el lunes 16 de octubre a las 12:00 del mediod\u00eda en el estadio Cibao, frente a las \u00c1guilas. Los Leones abrir\u00e1n su temporada regular el pr\u00f3ximo 19 de octubre en el estadio Quisqueya Juan Marichal, donde jugar\u00e1n como equipo visitante contra el Licey.<\/p>\n","protected":false},"author":9,"featured_media":92525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-92524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=92524"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92524\/revisions"}],"predecessor-version":[{"id":92526,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92524\/revisions\/92526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/92525"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=92524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=92524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=92524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}