{"id":92620,"date":"2023-10-04T07:01:06","date_gmt":"2023-10-04T11:01:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=92620"},"modified":"2023-10-04T07:01:08","modified_gmt":"2023-10-04T11:01:08","slug":"luis-abinader-destaca-madurez-y-liderazgo-precandidatos-del-prm","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/luis-abinader-destaca-madurez-y-liderazgo-precandidatos-del-prm\/","title":{"rendered":"Luis Abinader destaca madurez y liderazgo precandidatos del PRM"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/Untitled-10.jpg\" alt=\"\" class=\"wp-image-92622\" width=\"213\" height=\"123\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/Untitled-10.jpg 810w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/Untitled-10-300x175.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/Untitled-10-768x448.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/Untitled-10-600x350.jpg 600w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El presidente Luis Abinader destac\u00f3 este martes la madurez y el liderazgo que demostraron los precandidatos a la presidencia de la Rep\u00fablica Dominicana Guido G\u00f3mez Mazara, Ram\u00f3n Alburquerque y Delia Josefina Ortiz en las reci\u00e9n celebradas primarias del gubernamental Partido Revolucionario Moderno (PRD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, asegur\u00f3 que \u00abtodos los precandidatos van a trabajar juntos para realizar los cambios que necesita la Rep\u00fablica Dominicana\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 tambi\u00e9n el trabajo que realiz\u00f3 la Junta Central Electoral (JCE) en el proceso. \u00abEso es un ejemplo favorable para la democracia\u00bb, expres\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El presidente Luis Abinader destac\u00f3 este martes la madurez y el liderazgo que demostraron los precandidatos a la presidencia de la Rep\u00fablica Dominicana Guido G\u00f3mez Mazara, Ram\u00f3n Alburquerque y Delia Josefina Ortiz en las reci\u00e9n celebradas primarias del gubernamental Partido Revolucionario Moderno (PRD). Asimismo, asegur\u00f3 que \u00abtodos los precandidatos van a trabajar juntos para realizar los cambios que necesita la Rep\u00fablica Dominicana\u00bb. Destac\u00f3 tambi\u00e9n el trabajo que realiz\u00f3 la Junta Central Electoral (JCE) en el proceso. \u00abEso es un ejemplo favorable para la democracia\u00bb, expres\u00f3.<\/p>\n","protected":false},"author":9,"featured_media":92622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-92620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=92620"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92620\/revisions"}],"predecessor-version":[{"id":92623,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92620\/revisions\/92623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/92622"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=92620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=92620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=92620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}