{"id":92805,"date":"2023-10-16T06:54:56","date_gmt":"2023-10-16T10:54:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=92805"},"modified":"2023-10-16T06:54:58","modified_gmt":"2023-10-16T10:54:58","slug":"marileidy-paulino-entre-grandes-estrellas-de-panamericanos-2023","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/marileidy-paulino-entre-grandes-estrellas-de-panamericanos-2023\/","title":{"rendered":"Marileidy Paulino entre grandes estrellas de Panamericanos 2023"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/marip.jpeg\" alt=\"\" class=\"wp-image-92806\" width=\"218\" height=\"145\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/marip.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/marip-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/marip-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/marip-600x400.jpeg 600w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">CHILE.- Los vaticinios no pueden ser mejores, seg\u00fan los organizadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSantiago 2023 ser\u00e1n unos Juegos muy competidos, espero que quede en el recuerdo como una gran fiesta\u00bb, seg\u00fan Jaime Pizarro, presidente del Comit\u00e9 Organizador de los Panamericanos 2023.A ello ayuda la presencia de<strong>&nbsp;grandes campeones ol\u00edmpicos<\/strong>&nbsp;y mundiales que dar\u00e1n mayor brillo a la competici\u00f3n continental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nombres como Richard Carapaz, Marileidy Paulino, Rebeca Andrade, Maggie MacNeil, Julio C\u00e9sar La Cruz o Alejandra Orozco animan a seguir los Juegos, m\u00e1xime cuando estamos a nueve meses de los Juegos Ol\u00edmpicos de Par\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MARILEYDY PAULINO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toda una&nbsp;<strong>campeona mundial en Santiago de Chile.<\/strong>&nbsp;La dominicana lucir\u00e1 el oro conseguido en los 400 metros en el reciente&nbsp;<strong>Mundial de Budapest&nbsp;<\/strong>en la capital chilena, donde competir\u00e1 en las pruebas de 200 metros y en la vuelta a la pista, donde pretende superar su marca de 48,76 segundos conseguida en tierras h\u00fangaras el pasado agosto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el historial de esta dominicana, que durante la competici\u00f3n cumplir\u00e1 27 a\u00f1os, luce las medallas de plata ol\u00edmpicas conseguidas en Tokio 2020 en los 400 metros y en el relevo 4\u00d7400.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La brasile\u00f1a se presenta como una de las estrellas del tapiz en Santiago 2023 de las pruebas de gimnasia art\u00edstica, m\u00e1s tras su medalla de oro en salto conseguida en los Mundiales de Amberes (B\u00e9lgica) venciendo ni m\u00e1s ni menos que a la megaestrella estadounidense Simone Biles. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gimnasta brasile\u00f1a Rebeca Andrade durante los ejercicios de suelo en el pasado Mundial de Amberes, el 4 de octubre.EFE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrade, de 24 a\u00f1os, tambi\u00e9n&nbsp;<strong>alcanz\u00f3 la plata en el ejercicio de suelo y el bronce en la prueba individual<\/strong>. La brasile\u00f1a tendr\u00e1 como grandes rivales al equipo estadounidense, formado por Jordan Chiles, campeona del mundo y subcampeona ol\u00edmpica por equipos, Kayla DiCello, Kaliya Lincoln, Zoe Miller y Tiana Sumanasekera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RICHARD CARAPAZ<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ciclista ecuatoriano, ganador del Giro de Italia 2019 y oro en la prueba de ruta de los Juegos Ol\u00edmpicos de Tokio 2020 -m\u00e1s su segundo puesto en la Vuelta a Espa\u00f1a 2020 y el tercero en el Tour de Francia 2021-, busca la presea dorada en los Panamericanos de Chile, donde se presenta como el gran favorito.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2023\/10\/14\/652b173f3b5e9.jpeg\" alt=\"El ecuatoriano Richard Carapaz busca las medallas de oro en las pruebas de contrarreloj y ruta en Santiago 2023.\" \/><figcaption>El ecuatoriano Richard Carapaz busca las medallas de oro en las pruebas de contrarreloj y ruta en Santiago 2023.EFE&nbsp;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>\u201cLocomotora de Carchi\u201d,&nbsp;<\/strong>de 30 a\u00f1os, como es conocido, tendr\u00e1 una doble opci\u00f3n de medalla en las pruebas de contrarreloj y de ruta en las que participar\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>JULIO C\u00c9SAR LA CRUZ&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstoy listo para ir a Chile para brindar lo mejor en nuestras presentaciones y tratar de lograr la mayor cantidad de t\u00edtulos para nuestro pa\u00eds\u201d, explica el boxeador cubano Julio C\u00e9sar La Cruz en declaraciones recogidas por el sitio oficial de los Panamericanos de Santiago de Chile, santiago2023.org.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A sus dos campeonatos ol\u00edmpicos de los pesos pesados en R\u00edo de Janeiro 2016 y Tokio 2020, se a\u00f1aden las medallas de oro en la misma categor\u00eda de los Panamericanos de Guadalajara 2011, Toronto 2015 y Lima 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conocido como&nbsp;<strong>\u201cLa Sombra\u201d<\/strong>, a sus 34 a\u00f1os, es el m\u00e1ximo favorito al colgarse el oro en el Centro de Entrenamiento Ol\u00edmpico en \u00d1u\u00f1oa, escenario de las pruebas de boxeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ALEJANDRA OROZCO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clavadista mexicana, plata en los Juegos Ol\u00edmpicos de Londres 2012 -junto a Paola Espinosa- y bronce en Tokio 2020 -al lado de Gabriela Ag\u00fandez-, las dos veces en saltos sincronizados de 10 metros, asegura que va \u201ca por el oro\u201d en Santiago de Chile, a pesar de que su cuerpo tiene fallas, como asegura.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2023\/10\/14\/652b176b422e2.jpeg\" alt=\"La mexicana Alejandra Orozco\" \/><figcaption>La mexicana Alejandra Orozco busca el oro en los clavados de Santiago 2023. EFE\/ Fernando BizerraEFE&nbsp;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLlevo tres ciclos, mi cuerpo tiene fallitas, pero mantengo la ilusi\u00f3n y el nivel para luchar por oro en los Panamericanos de Santiago 2023 y por otra medalla ol\u00edmpica en Par\u00eds 2024\u00bb, dijo a EFE. Orozco, de 26 a\u00f1os, asegura que \u00abvoy por el oro que no he conseguido en Panamericanos\u201d, tras el bronce por parejas conseguido en Toronto 2015, y la plata en individual y el bronce en sincronizada en Lima 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo veo posible, aunque ser\u00e1 una dura competencia contra rivales de calidad mundial de Estados Unidos, Canad\u00e1, Brasil, Cuba y otros pa\u00edses\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MAGGIE MACNEIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La canadiense, medallista ol\u00edmpica en Tokio 2020, es una&nbsp;<strong>de las grandes estrellas de la nataci\u00f3n<\/strong>&nbsp;panamericana de Santiago 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Campeona ol\u00edmpica de los 100 metros mariposa en los Ol\u00edmpicos de 2020 y campeona mundial de la misma distancia en Gwangju 2019, MacNeil une el oro en los mundiales de piscina corta de Melbourne 2022 en 50 metros mariposa, 50 espalda y 100 mariposa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un historial de altura que la canadiense de 23 a\u00f1os espera agrandar en la cita panamericana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHILE.- Los vaticinios no pueden ser mejores, seg\u00fan los organizadores. \u00abSantiago 2023 ser\u00e1n unos Juegos muy competidos, espero que quede en el recuerdo como una gran fiesta\u00bb, seg\u00fan Jaime Pizarro, presidente del Comit\u00e9 Organizador de los Panamericanos 2023.A ello ayuda la presencia de&nbsp;grandes campeones ol\u00edmpicos&nbsp;y mundiales que dar\u00e1n mayor brillo a la competici\u00f3n continental. Nombres como Richard Carapaz, Marileidy Paulino, Rebeca Andrade, Maggie MacNeil, Julio C\u00e9sar La Cruz o Alejandra Orozco animan a seguir los Juegos, m\u00e1xime cuando estamos a nueve meses de los Juegos Ol\u00edmpicos de Par\u00eds. MARILEYDY PAULINO Toda una&nbsp;campeona mundial en Santiago de Chile.&nbsp;La dominicana lucir\u00e1 el oro conseguido en los 400 metros en el reciente&nbsp;Mundial de Budapest&nbsp;en la capital chilena, donde competir\u00e1 en las pruebas de 200 metros y en la vuelta a la pista, donde pretende superar su marca de 48,76 segundos conseguida en tierras h\u00fangaras el pasado agosto. En el historial de esta dominicana, que durante la competici\u00f3n cumplir\u00e1 27 a\u00f1os, luce las medallas de plata ol\u00edmpicas conseguidas en Tokio 2020 en los 400 metros y en el relevo 4\u00d7400. La brasile\u00f1a se presenta como una de las estrellas del tapiz en Santiago 2023 de las pruebas de gimnasia art\u00edstica, m\u00e1s tras su medalla de oro en salto conseguida en los Mundiales de Amberes (B\u00e9lgica) venciendo ni m\u00e1s ni menos que a la megaestrella estadounidense Simone Biles. La gimnasta brasile\u00f1a Rebeca Andrade durante los ejercicios de suelo en el pasado Mundial de Amberes, el 4 de octubre.EFE Andrade, de 24 a\u00f1os, tambi\u00e9n&nbsp;alcanz\u00f3 la plata en el ejercicio de suelo y el bronce en la prueba individual. La brasile\u00f1a tendr\u00e1 como grandes rivales al equipo estadounidense, formado por Jordan Chiles, campeona del mundo y subcampeona ol\u00edmpica por equipos, Kayla DiCello, Kaliya Lincoln, Zoe Miller y Tiana Sumanasekera. RICHARD CARAPAZ El ciclista ecuatoriano, ganador del Giro de Italia 2019 y oro en la prueba de ruta de los Juegos Ol\u00edmpicos de Tokio 2020 -m\u00e1s su segundo puesto en la Vuelta a Espa\u00f1a 2020 y el tercero en el Tour de Francia 2021-, busca la presea dorada en los Panamericanos de Chile, donde se presenta como el gran favorito. La&nbsp;\u201cLocomotora de Carchi\u201d,&nbsp;de 30 a\u00f1os, como es conocido, tendr\u00e1 una doble opci\u00f3n de medalla en las pruebas de contrarreloj y de ruta en las que participar\u00e1. JULIO C\u00c9SAR LA CRUZ&nbsp; \u201cEstoy listo para ir a Chile para brindar lo mejor en nuestras presentaciones y tratar de lograr la mayor cantidad de t\u00edtulos para nuestro pa\u00eds\u201d, explica el boxeador cubano Julio C\u00e9sar La Cruz en declaraciones recogidas por el sitio oficial de los Panamericanos de Santiago de Chile, santiago2023.org. A sus dos campeonatos ol\u00edmpicos de los pesos pesados en R\u00edo de Janeiro 2016 y Tokio 2020, se a\u00f1aden las medallas de oro en la misma categor\u00eda de los Panamericanos de Guadalajara 2011, Toronto 2015 y Lima 2019. Conocido como&nbsp;\u201cLa Sombra\u201d, a sus 34 a\u00f1os, es el m\u00e1ximo favorito al colgarse el oro en el Centro de Entrenamiento Ol\u00edmpico en \u00d1u\u00f1oa, escenario de las pruebas de boxeo. ALEJANDRA OROZCO La clavadista mexicana, plata en los Juegos Ol\u00edmpicos de Londres 2012 -junto a Paola Espinosa- y bronce en Tokio 2020 -al lado de Gabriela Ag\u00fandez-, las dos veces en saltos sincronizados de 10 metros, asegura que va \u201ca por el oro\u201d en Santiago de Chile, a pesar de que su cuerpo tiene fallas, como asegura. \u00abLlevo tres ciclos, mi cuerpo tiene fallitas, pero mantengo la ilusi\u00f3n y el nivel para luchar por oro en los Panamericanos de Santiago 2023 y por otra medalla ol\u00edmpica en Par\u00eds 2024\u00bb, dijo a EFE. Orozco, de 26 a\u00f1os, asegura que \u00abvoy por el oro que no he conseguido en Panamericanos\u201d, tras el bronce por parejas conseguido en Toronto 2015, y la plata en individual y el bronce en sincronizada en Lima 2019. \u201cLo veo posible, aunque ser\u00e1 una dura competencia contra rivales de calidad mundial de Estados Unidos, Canad\u00e1, Brasil, Cuba y otros pa\u00edses\u00bb. MAGGIE MACNEIL La canadiense, medallista ol\u00edmpica en Tokio 2020, es una&nbsp;de las grandes estrellas de la nataci\u00f3n&nbsp;panamericana de Santiago 2023. Campeona ol\u00edmpica de los 100 metros mariposa en los Ol\u00edmpicos de 2020 y campeona mundial de la misma distancia en Gwangju 2019, MacNeil une el oro en los mundiales de piscina corta de Melbourne 2022 en 50 metros mariposa, 50 espalda y 100 mariposa. Un historial de altura que la canadiense de 23 a\u00f1os espera agrandar en la cita panamericana.<\/p>\n","protected":false},"author":9,"featured_media":92806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-92805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=92805"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92805\/revisions"}],"predecessor-version":[{"id":92807,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92805\/revisions\/92807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/92806"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=92805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=92805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=92805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}