{"id":92827,"date":"2023-10-18T07:48:42","date_gmt":"2023-10-18T11:48:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=92827"},"modified":"2023-10-18T07:48:55","modified_gmt":"2023-10-18T11:48:55","slug":"muerte-por-dengue-de-hijos-de-galenos-sacude-la-clase-medica","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muerte-por-dengue-de-hijos-de-galenos-sacude-la-clase-medica\/","title":{"rendered":"Muerte por dengue de hijos de galenos sacude la clase m\u00e9dica"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/652f40851bad9.jpeg\" alt=\"\" class=\"wp-image-92828\" width=\"204\" height=\"124\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/652f40851bad9.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/652f40851bad9-300x183.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/652f40851bad9-768x468.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/652f40851bad9-600x366.jpeg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/652f40851bad9-440x270.jpeg 440w\" sizes=\"auto, (max-width: 204px) 100vw, 204px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Las muertes por dengue de ni\u00f1os de diferentes edades, dos de ellos de 13 y ocho a\u00f1os, hijos de facultativos, ocurridas en las \u00faltimas semanas, ha sacudido la clase m\u00e9dica nacional y evidencia que el pa\u00eds est\u00e1 ante un estado de emergencia sanitaria, advierte el presidente del Colegio M\u00e9dico Dominicano (CMD) en la Regional del Distrito Nacional, Juan Pablo Lagos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que en los actuales momentos el pa\u00eds est\u00e1 siendo impactado por una real epidemia de dengue, situaci\u00f3n altamente preocupante a nivel nacional, llevando la naci\u00f3n a un estado de emergencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dirigente gremial dijo que miles de hogares est\u00e1n siendo afectados por el virus del dengue y que a decenas de ellos ha llegado el dolor y el luto a causa de la enfermedad, que es transmitida por la picadura del mosquito Aedes aegypti, el cual se cr\u00eda en aguas limpias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTan s\u00f3lo en esta \u00faltima semana hemos visto morir por dengue varios ni\u00f1os que estaban totalmente sanos antes de enfermarse por esta patolog\u00eda. Incluyendo dos hijos de m\u00e9dicos. Una ni\u00f1a de 13 a\u00f1os y un ni\u00f1o de 8 a\u00f1os. Noticia \u00e9sta que ha sacudido a la clase m\u00e9dica a nacional\u201d, se\u00f1ala Lagos en declaraciones escritas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente falleci\u00f3 a causa del dengue la ni\u00f1a Mar\u00eda P\u00e9rez Serrata, de 13 a\u00f1os, hija del ur\u00f3logo Jos\u00e9 Ezequiel P\u00e9rez Vidal, quien en medio del dolor pidi\u00f3 a las autoridades adoptar medidas y declarar estado de emergencia por dengue, mientras ayer fueron sepultados los restos del ni\u00f1o V\u00edctor Manuel M\u00e9ndez P\u00e9rez, de ocho a\u00f1os, hijo del doctor V\u00edctor M\u00e9ndez, con el mismo diagn\u00f3stico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Emergencia sanitaria<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dirigente del CMD dijo que el gobierno no ha querido reconocer que el pa\u00eds est\u00e1 en una real epidemia y que se encuentra en un estado de semi schok.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lagos agreg\u00f3 que las emergencias de casi todos los hospitales p\u00fablicos pedi\u00e1tricos del pa\u00eds se encuentran abarrotadas de ni\u00f1os enfermos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A esto se suma, indic\u00f3, que los m\u00e9dicos comienzan a agotarse y las autoridades est\u00e1n tratando este gran problema t\u00edmidamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entiende que el presidente de la Rep\u00fablica, Luis Abinader, no est\u00e1 siendo debidamente informado sobre esa penosa realidad y que a eso se suma un gran subregistro, no s\u00f3lo de los enfermos por dengue, sino tambi\u00e9n de las muertes, al entender que no son nueve los fallecidos como reporta el Ministerio de Salud P\u00fablica, sino que van decenas y decenas de decesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que el Ministerio de Salud P\u00fablica, junto a todas las instituciones sanitarias y las fuerzas vivas del pa\u00eds, deben sentarse seriamente a enfrentar esta epidemia, a fin de coordinar acciones para enfrentar y frenar esta enfermedad que est\u00e1 llevando luto y dolor al pueblo dominicano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las muertes por dengue de ni\u00f1os de diferentes edades, dos de ellos de 13 y ocho a\u00f1os, hijos de facultativos, ocurridas en las \u00faltimas semanas, ha sacudido la clase m\u00e9dica nacional y evidencia que el pa\u00eds est\u00e1 ante un estado de emergencia sanitaria, advierte el presidente del Colegio M\u00e9dico Dominicano (CMD) en la Regional del Distrito Nacional, Juan Pablo Lagos. Dijo que en los actuales momentos el pa\u00eds est\u00e1 siendo impactado por una real epidemia de dengue, situaci\u00f3n altamente preocupante a nivel nacional, llevando la naci\u00f3n a un estado de emergencia. El dirigente gremial dijo que miles de hogares est\u00e1n siendo afectados por el virus del dengue y que a decenas de ellos ha llegado el dolor y el luto a causa de la enfermedad, que es transmitida por la picadura del mosquito Aedes aegypti, el cual se cr\u00eda en aguas limpias. \u201cTan s\u00f3lo en esta \u00faltima semana hemos visto morir por dengue varios ni\u00f1os que estaban totalmente sanos antes de enfermarse por esta patolog\u00eda. Incluyendo dos hijos de m\u00e9dicos. Una ni\u00f1a de 13 a\u00f1os y un ni\u00f1o de 8 a\u00f1os. Noticia \u00e9sta que ha sacudido a la clase m\u00e9dica a nacional\u201d, se\u00f1ala Lagos en declaraciones escritas. Recientemente falleci\u00f3 a causa del dengue la ni\u00f1a Mar\u00eda P\u00e9rez Serrata, de 13 a\u00f1os, hija del ur\u00f3logo Jos\u00e9 Ezequiel P\u00e9rez Vidal, quien en medio del dolor pidi\u00f3 a las autoridades adoptar medidas y declarar estado de emergencia por dengue, mientras ayer fueron sepultados los restos del ni\u00f1o V\u00edctor Manuel M\u00e9ndez P\u00e9rez, de ocho a\u00f1os, hijo del doctor V\u00edctor M\u00e9ndez, con el mismo diagn\u00f3stico. Emergencia sanitaria El dirigente del CMD dijo que el gobierno no ha querido reconocer que el pa\u00eds est\u00e1 en una real epidemia y que se encuentra en un estado de semi schok. Lagos agreg\u00f3 que las emergencias de casi todos los hospitales p\u00fablicos pedi\u00e1tricos del pa\u00eds se encuentran abarrotadas de ni\u00f1os enfermos. A esto se suma, indic\u00f3, que los m\u00e9dicos comienzan a agotarse y las autoridades est\u00e1n tratando este gran problema t\u00edmidamente. Entiende que el presidente de la Rep\u00fablica, Luis Abinader, no est\u00e1 siendo debidamente informado sobre esa penosa realidad y que a eso se suma un gran subregistro, no s\u00f3lo de los enfermos por dengue, sino tambi\u00e9n de las muertes, al entender que no son nueve los fallecidos como reporta el Ministerio de Salud P\u00fablica, sino que van decenas y decenas de decesos. Se\u00f1al\u00f3 que el Ministerio de Salud P\u00fablica, junto a todas las instituciones sanitarias y las fuerzas vivas del pa\u00eds, deben sentarse seriamente a enfrentar esta epidemia, a fin de coordinar acciones para enfrentar y frenar esta enfermedad que est\u00e1 llevando luto y dolor al pueblo dominicano.<\/p>\n","protected":false},"author":9,"featured_media":92828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-92827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=92827"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92827\/revisions"}],"predecessor-version":[{"id":92829,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/92827\/revisions\/92829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/92828"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=92827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=92827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=92827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}