{"id":93003,"date":"2023-10-31T07:59:39","date_gmt":"2023-10-31T11:59:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=93003"},"modified":"2023-10-31T07:59:42","modified_gmt":"2023-10-31T11:59:42","slug":"rd-logra-oro-en-atletismo-y-cuatro-preseas-de-bronce-en-judo-en-los-panam","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/rd-logra-oro-en-atletismo-y-cuatro-preseas-de-bronce-en-judo-en-los-panam\/","title":{"rendered":"RD logra oro en atletismo y cuatro preseas de bronce en judo en los Panam"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/unnamed-6-1024x632.jpg\" alt=\"\" class=\"wp-image-93004\" width=\"241\" height=\"148\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/unnamed-6-1024x632.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/unnamed-6-300x185.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/unnamed-6-768x474.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/unnamed-6-600x370.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/unnamed-6-440x270.jpg 440w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/10\/unnamed-6.jpg 1600w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTIAGO, Chile.- La Rep\u00fablica Dominicana obtuvo cinco medallas para mantenerse en la novena posici\u00f3n en el medallero de los XIX Juegos Panamericanos que se desarrollan en esta ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El oro de la cuarteta 4\u00d7400 mixta, as\u00ed como los cuatro metales de los judocas Robert Florentino, Eiraima Silvestre, Jos\u00e9 Nova y Moira Morillo, permiti\u00f3 que el pa\u00eds tenga en total 20 preseas, incluidas seis doradas, cuatro de plata y 10 de bronce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del oro del atletismo, tambi\u00e9n sobresalieron las actuaciones de Liranyi Alonzo y Jos\u00e9 Gonz\u00e1lez, quienes avanzaron a la final en la especialidad de los 100 metros planos, las cuales se realizar\u00e1n este martes en la noche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ATLETISMO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rep\u00fablica Dominicana obtuvo este lunes la medalla de oro en la modalidad 4\u00d7400 mixta del atletismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un cierre con elegancia de la velocista Marileidy Paulino coron\u00f3 la gran actuaci\u00f3n de Anabel Medina, quien inici\u00f3 Ezequiel Su\u00e1rez, seguido por Anabel Medina, y Robert King mantuvo cerrada la distancia que permiti\u00f3 que Paulino se luciera al final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reloj para el primer lugar del relevo quisqueyano se detuvo en 3:16.05, para dejar el segundo puesto a la representaci\u00f3n de Brasil, que cronometr\u00f3 3:18.55, y el bronce fue para la cuarteta de Estados Unidos, que hizo un tiempo de 3:19.41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el resultado, la cuarteta mixta dominicana impone una marca con los 3:16.05, al ser la primera vez que la modalidad del atletismo se corre en unos Juegos Panamericanos. La especialidad se estren\u00f3 en la cita ol\u00edmpica de Tokio, donde la Rep\u00fablica Dominicana se alz\u00f3 con la presea de plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El atletismo comenz\u00f3 bien en la cita continental de Chile, con su primer oro. En Lima 2019, este deporte obtuvo un bronce en los 200 metros lisos con el velocista Yancarlos Mart\u00ednez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>100 METROS LISOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los velocistas Jos\u00e9 Gonz\u00e1lez Soto y Liranyi Alonzo avanzaron a la final en los 100 metros masculino y femenino, respectivamente, en el atletismo de los Juegos Panamericanos de Chile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gonz\u00e1lez Soto hizo el mejor tiempo de los tres heat en la semifinal de los 100 metros masculinos. El quisqueyano recorri\u00f3 la distancia en 10.30 segundos en la primera serie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alonzo, por su parte, termin\u00f3 en la segunda posici\u00f3n en la segunda carrera clasificatoria, con 11.69 segundos, detr\u00e1s de la mexicana Cecilia Tamayo, quien arrib\u00f3 primero con 11.06 segundos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro resultado, Anabel Medina qued\u00f3 descalificada en la semifinal de la serie dos tras una falsa salida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos atletas correr\u00e1n sus respectivas finales este martes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>JUDO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Robert Florentino, Jos\u00e9 Nova, Eiraima Silvestre y Moira Morillo alzaron con medallas de bronce en sus respectivas categor\u00edas en el pen\u00faltimo d\u00eda del torneo de judo de los Panamericanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la actuaci\u00f3n de los judocas, la Rep\u00fablica Dominicana suma un total de 19 preseas, incluidas cinco de oro, cuatro de plata y 10 de bronce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Robert obtuvo el bronce al imponerse por ippon, a los 0.35 segundos, ante Daniel Paz, de Colombia, en la categor\u00eda -90 kilos del torneo de judo de los Panamericanos de Chile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Florentino gan\u00f3 su primera pelea por ippon, al minuto y 55 segundos, ante Alexander Knauf, de Estados Unidos, y en la semifinal perdi\u00f3 por ippon, a los 41 segundos, de Rafael Macedo, de Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Nova, en m\u00e1s de 100 kilos, se llev\u00f3 el bronce ante Freddy Figueroa, de Ecuador, quien recibi\u00f3 una penalizaci\u00f3n directa de tres shidos por razones de seguridad, despu\u00e9s de que lastim\u00f3 el brazo izquierdo de Nova, quien gan\u00f3 por Hansoku-make (razones de seguridad) apenas iniciando el combate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nova super\u00f3 en los cuartos de final a Sergio Del Sol, de M\u00e9xico, a quien le propin\u00f3 un ippon a los dos minutos de iniciado el combate. En la semifinal, el peleador quisqueyano fue superado por Andy Granda, de Cuba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eiraima Silvestre se colg\u00f3 su primera medalla en Juegos Panamericos, al derrotar por ippon a los 0.14 segundos, a Lianet Cardona, de Cuba, en el pleito de la categor\u00eda -78 kilos por la presea de bronce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el metal de tercer lugar, Silvestre ha ganado presea de bronce en los Centroamericanos y del Caribe de Barranquilla, as\u00ed como plata en la cita regional de El Salvador, y el bronce en los Panamericanos de Chile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los cuartos de final, Eiraima Silvestre le gan\u00f3 por waza-ari (1-0) a los cuatro minutos, a la canadiense Coralice Godbout, y en la semifinal fue superada por la boricua Sairy Col\u00f3n, por ippon al minuto y 12 segundos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Moira Morillo, en m\u00e1s de 78 kilos femeninos, dobleg\u00f3 a Izayama Marenco, de Nicaragua, en la batalla por la presea de bronce. Izayama fue penalizada por tres shido, el \u00faltimo de ellos a los 4:37 minutos, que decret\u00f3 el triunfo por 1-0 para la dominicana, que logra su primera presea Panamericana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Morillo despach\u00f3 en los cuartos de final a Yuliana Bol\u00edvar Gonz\u00e1lez, de Per\u00fa, quien fue penalizada por tres shidos a los dos minutos y 44 segundos de la pelea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la semifinal, Moira enfrent\u00f3 a la doble campeona ol\u00edmpica y mundial, Idalys Ortiz, de Cuba, quien se llev\u00f3 el triunfo por ippon a los dos minutos y 26 segundos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>VELA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adeuri Corniel se ubica en el tercer lugar, con 24 puntos tras ocho carreras, en la modalidad F\u00f3rmula Kite de las competencias de Vela, mientras que Samuel P\u00e9rez, con 62 tantos acumulados en cinco carreras, figura en el quinto puesto en la modalidad IQFOIL, en tanto que Esneiry P\u00e9rez, en Sunfish, se mantiene en el sexto pelda\u00f1o con un total de 27 unidades en 9 carreras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las competencias continuar\u00e1n hasta el viernes, cuando se llevar\u00e1n a cabo las series que entregar\u00e1n las medallas en cada modalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TENIS DE MESA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En sencillos femeninos, Eva Brito perdi\u00f3 su partido de la ronda de los 32 en seis sets (2-4) ante la chilena Zhiying Zeng. Brito gan\u00f3 los dos primeros parciales 11-7, 11-5, y luego cay\u00f3 en los siguientes cuatro con anotaciones de 7-11, 6-11, 5-11 y 8-11.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esmerlyn Castro tambi\u00e9n perdi\u00f3 en cinco sets (1-4) ante Amy Wang, de Estados Unidos. Los parciales finalizaron 11-13, 8-11, 3-11, 11-6, 5-11 a favor de Wang, quien avanz\u00f3 a los octavos de final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jiaji Wu fue superado en seis sets (2-4) por el argentino Horacio Cifuentes, quien se recuper\u00f3 despu\u00e9s de haber perdido los dos primeros parciales 6-11, 9-11 para ganar los siguientes cuatro con anotaci\u00f3n de 11-2, 11-6, 11-5 y 11-4.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BALONMANO MASCULINO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El seleccionado dominicano perdi\u00f3 21-30 ante la representaci\u00f3n de Chile en el inicio este lunes del torneo de balonmano masculino que tiene lugar en el Gimnasio Polideportivo Vi\u00f1a del Mar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Danilo Salgado, con 7 goles, y Daniel Ayala, con 5, encabezaron el ataque de Chile, mientras que por dominicana, Maikol Beras anot\u00f3 seis tantos, y Luis Tejada termin\u00f3 con tres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTIAGO, Chile.- La Rep\u00fablica Dominicana obtuvo cinco medallas para mantenerse en la novena posici\u00f3n en el medallero de los XIX Juegos Panamericanos que se desarrollan en esta ciudad. El oro de la cuarteta 4\u00d7400 mixta, as\u00ed como los cuatro metales de los judocas Robert Florentino, Eiraima Silvestre, Jos\u00e9 Nova y Moira Morillo, permiti\u00f3 que el pa\u00eds tenga en total 20 preseas, incluidas seis doradas, cuatro de plata y 10 de bronce. Adem\u00e1s del oro del atletismo, tambi\u00e9n sobresalieron las actuaciones de Liranyi Alonzo y Jos\u00e9 Gonz\u00e1lez, quienes avanzaron a la final en la especialidad de los 100 metros planos, las cuales se realizar\u00e1n este martes en la noche. ATLETISMO Rep\u00fablica Dominicana obtuvo este lunes la medalla de oro en la modalidad 4\u00d7400 mixta del atletismo. Un cierre con elegancia de la velocista Marileidy Paulino coron\u00f3 la gran actuaci\u00f3n de Anabel Medina, quien inici\u00f3 Ezequiel Su\u00e1rez, seguido por Anabel Medina, y Robert King mantuvo cerrada la distancia que permiti\u00f3 que Paulino se luciera al final. El reloj para el primer lugar del relevo quisqueyano se detuvo en 3:16.05, para dejar el segundo puesto a la representaci\u00f3n de Brasil, que cronometr\u00f3 3:18.55, y el bronce fue para la cuarteta de Estados Unidos, que hizo un tiempo de 3:19.41. Con el resultado, la cuarteta mixta dominicana impone una marca con los 3:16.05, al ser la primera vez que la modalidad del atletismo se corre en unos Juegos Panamericanos. La especialidad se estren\u00f3 en la cita ol\u00edmpica de Tokio, donde la Rep\u00fablica Dominicana se alz\u00f3 con la presea de plata. El atletismo comenz\u00f3 bien en la cita continental de Chile, con su primer oro. En Lima 2019, este deporte obtuvo un bronce en los 200 metros lisos con el velocista Yancarlos Mart\u00ednez. 100 METROS LISOS Los velocistas Jos\u00e9 Gonz\u00e1lez Soto y Liranyi Alonzo avanzaron a la final en los 100 metros masculino y femenino, respectivamente, en el atletismo de los Juegos Panamericanos de Chile. Gonz\u00e1lez Soto hizo el mejor tiempo de los tres heat en la semifinal de los 100 metros masculinos. El quisqueyano recorri\u00f3 la distancia en 10.30 segundos en la primera serie. Alonzo, por su parte, termin\u00f3 en la segunda posici\u00f3n en la segunda carrera clasificatoria, con 11.69 segundos, detr\u00e1s de la mexicana Cecilia Tamayo, quien arrib\u00f3 primero con 11.06 segundos. En otro resultado, Anabel Medina qued\u00f3 descalificada en la semifinal de la serie dos tras una falsa salida. Ambos atletas correr\u00e1n sus respectivas finales este martes. JUDO Robert Florentino, Jos\u00e9 Nova, Eiraima Silvestre y Moira Morillo alzaron con medallas de bronce en sus respectivas categor\u00edas en el pen\u00faltimo d\u00eda del torneo de judo de los Panamericanos. Con la actuaci\u00f3n de los judocas, la Rep\u00fablica Dominicana suma un total de 19 preseas, incluidas cinco de oro, cuatro de plata y 10 de bronce. Robert obtuvo el bronce al imponerse por ippon, a los 0.35 segundos, ante Daniel Paz, de Colombia, en la categor\u00eda -90 kilos del torneo de judo de los Panamericanos de Chile. Florentino gan\u00f3 su primera pelea por ippon, al minuto y 55 segundos, ante Alexander Knauf, de Estados Unidos, y en la semifinal perdi\u00f3 por ippon, a los 41 segundos, de Rafael Macedo, de Brasil. Jos\u00e9 Nova, en m\u00e1s de 100 kilos, se llev\u00f3 el bronce ante Freddy Figueroa, de Ecuador, quien recibi\u00f3 una penalizaci\u00f3n directa de tres shidos por razones de seguridad, despu\u00e9s de que lastim\u00f3 el brazo izquierdo de Nova, quien gan\u00f3 por Hansoku-make (razones de seguridad) apenas iniciando el combate. Nova super\u00f3 en los cuartos de final a Sergio Del Sol, de M\u00e9xico, a quien le propin\u00f3 un ippon a los dos minutos de iniciado el combate. En la semifinal, el peleador quisqueyano fue superado por Andy Granda, de Cuba. Eiraima Silvestre se colg\u00f3 su primera medalla en Juegos Panamericos, al derrotar por ippon a los 0.14 segundos, a Lianet Cardona, de Cuba, en el pleito de la categor\u00eda -78 kilos por la presea de bronce. En el metal de tercer lugar, Silvestre ha ganado presea de bronce en los Centroamericanos y del Caribe de Barranquilla, as\u00ed como plata en la cita regional de El Salvador, y el bronce en los Panamericanos de Chile. En los cuartos de final, Eiraima Silvestre le gan\u00f3 por waza-ari (1-0) a los cuatro minutos, a la canadiense Coralice Godbout, y en la semifinal fue superada por la boricua Sairy Col\u00f3n, por ippon al minuto y 12 segundos. Moira Morillo, en m\u00e1s de 78 kilos femeninos, dobleg\u00f3 a Izayama Marenco, de Nicaragua, en la batalla por la presea de bronce. Izayama fue penalizada por tres shido, el \u00faltimo de ellos a los 4:37 minutos, que decret\u00f3 el triunfo por 1-0 para la dominicana, que logra su primera presea Panamericana. Morillo despach\u00f3 en los cuartos de final a Yuliana Bol\u00edvar Gonz\u00e1lez, de Per\u00fa, quien fue penalizada por tres shidos a los dos minutos y 44 segundos de la pelea. En la semifinal, Moira enfrent\u00f3 a la doble campeona ol\u00edmpica y mundial, Idalys Ortiz, de Cuba, quien se llev\u00f3 el triunfo por ippon a los dos minutos y 26 segundos. VELA Adeuri Corniel se ubica en el tercer lugar, con 24 puntos tras ocho carreras, en la modalidad F\u00f3rmula Kite de las competencias de Vela, mientras que Samuel P\u00e9rez, con 62 tantos acumulados en cinco carreras, figura en el quinto puesto en la modalidad IQFOIL, en tanto que Esneiry P\u00e9rez, en Sunfish, se mantiene en el sexto pelda\u00f1o con un total de 27 unidades en 9 carreras. Las competencias continuar\u00e1n hasta el viernes, cuando se llevar\u00e1n a cabo las series que entregar\u00e1n las medallas en cada modalidad. TENIS DE MESA En sencillos femeninos, Eva Brito perdi\u00f3 su partido de la ronda de los 32 en seis sets (2-4) ante la chilena Zhiying Zeng. Brito gan\u00f3 los dos primeros parciales 11-7, 11-5, y luego cay\u00f3 en los siguientes cuatro con anotaciones de 7-11, 6-11, 5-11 y 8-11. Esmerlyn Castro tambi\u00e9n perdi\u00f3 en cinco sets (1-4) ante Amy Wang, de Estados Unidos. Los parciales finalizaron 11-13, 8-11, 3-11, 11-6, 5-11 a favor de Wang, quien [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":93004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-93003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=93003"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93003\/revisions"}],"predecessor-version":[{"id":93005,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93003\/revisions\/93005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/93004"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=93003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=93003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=93003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}