{"id":93358,"date":"2023-11-22T07:01:08","date_gmt":"2023-11-22T11:01:08","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=93358"},"modified":"2023-11-22T07:01:33","modified_gmt":"2023-11-22T11:01:33","slug":"fernando-tatis-jr-ya-practica-para-entrar-a-juego-con-las-estrellas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fernando-tatis-jr-ya-practica-para-entrar-a-juego-con-las-estrellas\/","title":{"rendered":"Fernando Tatis Jr. ya practica para entrar a juego con las Estrellas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/11\/TATIS-300x168-1.jpg\" alt=\"\" class=\"wp-image-93359\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El dirigente de las Estrellas Orientales, Fernando Tatis, indic\u00f3 este martes que su hijo, el estelar jugador de los Padres de San Diego, Fernando Tatis Jr., defender\u00e1 el campocorto una vez se una al equipo por tercera vez para disputar el campeonato de b\u00e9isbol invernal dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsa es su posici\u00f3n, es la posici\u00f3n que realmente lo ha creado\u00bb, dijo el dirigente de los orientales, previo al partido en el que su equipo enfrenta a los Leones del Escogido en el estadio Quisqueya Juan Marichal, de Santo Domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la llegada del arube\u00f1o Xander Bogaerts al equipo, los Padres movieron a Tatis Jr. al jard\u00edn derecho, posici\u00f3n en la que en la reci\u00e9n finalizada temporada de Grandes Ligas conquist\u00f3 el Guante de Oro y el Guante de Platino, que lo distinguen como el mejor jugador defensivo de esa posici\u00f3n y como el mejor jugador defensivo a nivel global en la Liga Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>JUGARA EN EL CAMPO CORTO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con todo y esto, Tatis padre insiste en que la posici\u00f3n original del toletero de los Padres es el campocorto y que el jard\u00edn derecho es algo nuevo para su hijo y que en dado caso, ser\u00eda una segunda opci\u00f3n para tenerlo en el terreno de juego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl jard\u00edn derecho es algo nuevo para m\u00ed y para \u00e9l (Tatis Jr.) tambi\u00e9n, o sea, ya aquello ser\u00eda lo segundo, pero esa es su posici\u00f3n, el campocorto\u00bb, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tatis Jr. recibi\u00f3 el permiso de los Padres para participar con las Estrellas en 20 partidos de la temporada de la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana (Lidom) y aunque ha estado entrenando con ese objetivo, Tatis padre precis\u00f3 que a\u00fan no est\u00e1 listo para ingresar a juego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abApenas esta fue su segunda pr\u00e1ctica, vamos a necesitar un poquito m\u00e1s de tiempo para que \u00e9l se ponga listo\u00bb, sostuvo el veterano estratega y exjugador de Grandes Ligas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El dirigente de las Estrellas Orientales, Fernando Tatis, indic\u00f3 este martes que su hijo, el estelar jugador de los Padres de San Diego, Fernando Tatis Jr., defender\u00e1 el campocorto una vez se una al equipo por tercera vez para disputar el campeonato de b\u00e9isbol invernal dominicano. \u00abEsa es su posici\u00f3n, es la posici\u00f3n que realmente lo ha creado\u00bb, dijo el dirigente de los orientales, previo al partido en el que su equipo enfrenta a los Leones del Escogido en el estadio Quisqueya Juan Marichal, de Santo Domingo. Con la llegada del arube\u00f1o Xander Bogaerts al equipo, los Padres movieron a Tatis Jr. al jard\u00edn derecho, posici\u00f3n en la que en la reci\u00e9n finalizada temporada de Grandes Ligas conquist\u00f3 el Guante de Oro y el Guante de Platino, que lo distinguen como el mejor jugador defensivo de esa posici\u00f3n y como el mejor jugador defensivo a nivel global en la Liga Nacional. JUGARA EN EL CAMPO CORTO Con todo y esto, Tatis padre insiste en que la posici\u00f3n original del toletero de los Padres es el campocorto y que el jard\u00edn derecho es algo nuevo para su hijo y que en dado caso, ser\u00eda una segunda opci\u00f3n para tenerlo en el terreno de juego. \u00abEl jard\u00edn derecho es algo nuevo para m\u00ed y para \u00e9l (Tatis Jr.) tambi\u00e9n, o sea, ya aquello ser\u00eda lo segundo, pero esa es su posici\u00f3n, el campocorto\u00bb, explic\u00f3. Tatis Jr. recibi\u00f3 el permiso de los Padres para participar con las Estrellas en 20 partidos de la temporada de la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana (Lidom) y aunque ha estado entrenando con ese objetivo, Tatis padre precis\u00f3 que a\u00fan no est\u00e1 listo para ingresar a juego. \u00abApenas esta fue su segunda pr\u00e1ctica, vamos a necesitar un poquito m\u00e1s de tiempo para que \u00e9l se ponga listo\u00bb, sostuvo el veterano estratega y exjugador de Grandes Ligas.<\/p>\n","protected":false},"author":9,"featured_media":93359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-93358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=93358"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93358\/revisions"}],"predecessor-version":[{"id":93360,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93358\/revisions\/93360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/93359"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=93358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=93358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=93358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}