{"id":93401,"date":"2023-11-24T07:19:20","date_gmt":"2023-11-24T11:19:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=93401"},"modified":"2023-11-24T07:19:22","modified_gmt":"2023-11-24T11:19:22","slug":"aerodom-aumentaria-tarifa-a-los-pasajeros","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aerodom-aumentaria-tarifa-a-los-pasajeros\/","title":{"rendered":"Aerodom aumentar\u00eda tarifa a los pasajeros"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El nuevo que contrato que entrar\u00eda en vigencia luego de promulgado por el Poder Ejecutivo tras su aprobaci\u00f3n en ambas c\u00e1maras, se\u00f1ala adem\u00e1s que el Estado indemnizar\u00e1 a la concesionaria Aerodom por todos los costos o p\u00e9rdidas en que \u00e9sta hubiera incurrido en el caso de que cualquiera de los ajustes por inflaci\u00f3n acordados no pueda ser aplicado a tiempo.<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/11\/jopujopn.jpg\" alt=\"\" class=\"wp-image-93402\" width=\"241\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/11\/jopujopn.jpg 736w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/11\/jopujopn-300x150.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/11\/jopujopn-600x301.jpg 600w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Se establece en el art\u00edculo 6 del contrato que la construcci\u00f3n de la nueva terminal de pasajeros en el Aeropuerto Internacional Las Am\u00e9ricas, contemplada en la renovaci\u00f3n del contrato, depender\u00e1 de que se cobren \u201cestos ajustes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Puedes leer:&nbsp;<\/strong><a href=\"https:\/\/elnacional.com.do\/?p=1644401\">Acuerdo Aerodom llega a C\u00e1mara Baja<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA partir del primero de noviembre de 2024, las tasas aeroportuarias descritas en la Secci\u00f3n 6.2.2 (pago de salida y llegada y manejo de equipajes) del presente contrato ser\u00e1n ajustadas conforme al aumento del \u00cdndice de Precios del Consumidor (IPC) en el periodo comprendido entre el primero de enero de 2023 y el 31 de diciembre del 2023, m\u00e1s un aumento de 2.7% d\u00f3lares, correspondiente a una proporci\u00f3n de la inflaci\u00f3n del a\u00f1o dos 2022\u201d, seg\u00fan establece el art\u00edculo 6.2.2 del contrato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Puedes leer:&nbsp;<\/strong><a href=\"https:\/\/elnacional.com.do\/renegociacion-de-contrato-de-aerodom-es-un-nuevo-prestamo-que-toma-abinader\/\">\u201cRenegociaci\u00f3n\u201d de contrato de AERODOM, es un nuevo pr\u00e9stamo que toma Abinader<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el a\u00f1o 2025 contempla que: \u201c\u2026a partir del primero de noviembre 2025, las tasas aeroportuarias descritas en la Secci\u00f3n 6.2.2. del presente contrato ser\u00e1n ajustadas conforme al aumento del \u00edndice de Precios del Consumidor (IPC) en el periodo comprendido entre el primero de enero de 2024) y el 31 de diciembre 2024, m\u00e1s 2.7 % dolares, correspondiente a una proporci\u00f3n de la inflaci\u00f3n del a\u00f1o dos mil 2022, la efectividad del ajuste tarifario 2024 y del ajuste tarifario 2025, son condiciones precedentes al inicio de los trabajos relacionados con la construcci\u00f3n de la Nueva Terminal AILA por parte de la Concesionaria ,en consecuencia, hasta tanto no se cumplan las condiciones precedentes indicadas anteriormente, el inicio de dichos trabajos no ser\u00e1 exigible a la Concesionaria\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9gimen tarifario<\/strong><br \/>El art\u00edculo 6 del contrato est\u00e1 reservado al r\u00e9gimen tarifario y establece que la modificaci\u00f3n de cualquier monto de las tasas aeroportuarias especializadas por Pasajero que no sea por concepto de ajuste por inflaci\u00f3n deber\u00e1 ser sometida por la concesionaria a la aprobaci\u00f3n de la concedente (Estado), para su aprobaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Advierte que la concesionaria deber\u00e1 compensar al Estado dominicano por la aplicaci\u00f3n y cobro de cualquier incremento sobre las tasas aeroportuarias especializadas que no haya sido implementada de conformidad con lo dispuesto en el presente art\u00edculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las bondades<\/strong><br \/>El presidente Luis Abinader anunci\u00f3 la renegociaci\u00f3n del contrato de concesi\u00f3n de Aerodom, que se firm\u00f3 en 1999 y no generaba beneficios para el Estado dominicano, adem\u00e1s de que \u201cno garantizaba las mejores condiciones en las infraestructuras de los aeropuertos\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El mandatario manifest\u00f3 que esta renegociaci\u00f3n \u201crepresenta un beneficio para la Rep\u00fablica Dominicana de entre 1,905 y 2,155 millones de d\u00f3lares. Esa es la diferencia en las negociaciones realizadas por nuestro Gobierno y el anterior\u201d.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Abinader agreg\u00f3 que se arrib\u00f3 a un acuerdo que, al garantizar una mayor participaci\u00f3n del Estado en los beneficios generados por la operaci\u00f3n de los aeropuertos, generar\u00e1 recursos que ser\u00e1n utilizados en beneficio de los dominicanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo que contrato que entrar\u00eda en vigencia luego de promulgado por el Poder Ejecutivo tras su aprobaci\u00f3n en ambas c\u00e1maras, se\u00f1ala adem\u00e1s que el Estado indemnizar\u00e1 a la concesionaria Aerodom por todos los costos o p\u00e9rdidas en que \u00e9sta hubiera incurrido en el caso de que cualquiera de los ajustes por inflaci\u00f3n acordados no pueda ser aplicado a tiempo. Se establece en el art\u00edculo 6 del contrato que la construcci\u00f3n de la nueva terminal de pasajeros en el Aeropuerto Internacional Las Am\u00e9ricas, contemplada en la renovaci\u00f3n del contrato, depender\u00e1 de que se cobren \u201cestos ajustes\u201d. Puedes leer:&nbsp;Acuerdo Aerodom llega a C\u00e1mara Baja \u201cA partir del primero de noviembre de 2024, las tasas aeroportuarias descritas en la Secci\u00f3n 6.2.2 (pago de salida y llegada y manejo de equipajes) del presente contrato ser\u00e1n ajustadas conforme al aumento del \u00cdndice de Precios del Consumidor (IPC) en el periodo comprendido entre el primero de enero de 2023 y el 31 de diciembre del 2023, m\u00e1s un aumento de 2.7% d\u00f3lares, correspondiente a una proporci\u00f3n de la inflaci\u00f3n del a\u00f1o dos 2022\u201d, seg\u00fan establece el art\u00edculo 6.2.2 del contrato. Puedes leer:&nbsp;\u201cRenegociaci\u00f3n\u201d de contrato de AERODOM, es un nuevo pr\u00e9stamo que toma Abinader Para el a\u00f1o 2025 contempla que: \u201c\u2026a partir del primero de noviembre 2025, las tasas aeroportuarias descritas en la Secci\u00f3n 6.2.2. del presente contrato ser\u00e1n ajustadas conforme al aumento del \u00edndice de Precios del Consumidor (IPC) en el periodo comprendido entre el primero de enero de 2024) y el 31 de diciembre 2024, m\u00e1s 2.7 % dolares, correspondiente a una proporci\u00f3n de la inflaci\u00f3n del a\u00f1o dos mil 2022, la efectividad del ajuste tarifario 2024 y del ajuste tarifario 2025, son condiciones precedentes al inicio de los trabajos relacionados con la construcci\u00f3n de la Nueva Terminal AILA por parte de la Concesionaria ,en consecuencia, hasta tanto no se cumplan las condiciones precedentes indicadas anteriormente, el inicio de dichos trabajos no ser\u00e1 exigible a la Concesionaria\u201d. R\u00e9gimen tarifarioEl art\u00edculo 6 del contrato est\u00e1 reservado al r\u00e9gimen tarifario y establece que la modificaci\u00f3n de cualquier monto de las tasas aeroportuarias especializadas por Pasajero que no sea por concepto de ajuste por inflaci\u00f3n deber\u00e1 ser sometida por la concesionaria a la aprobaci\u00f3n de la concedente (Estado), para su aprobaci\u00f3n. Advierte que la concesionaria deber\u00e1 compensar al Estado dominicano por la aplicaci\u00f3n y cobro de cualquier incremento sobre las tasas aeroportuarias especializadas que no haya sido implementada de conformidad con lo dispuesto en el presente art\u00edculo. Las bondadesEl presidente Luis Abinader anunci\u00f3 la renegociaci\u00f3n del contrato de concesi\u00f3n de Aerodom, que se firm\u00f3 en 1999 y no generaba beneficios para el Estado dominicano, adem\u00e1s de que \u201cno garantizaba las mejores condiciones en las infraestructuras de los aeropuertos\u201d. El mandatario manifest\u00f3 que esta renegociaci\u00f3n \u201crepresenta un beneficio para la Rep\u00fablica Dominicana de entre 1,905 y 2,155 millones de d\u00f3lares. Esa es la diferencia en las negociaciones realizadas por nuestro Gobierno y el anterior\u201d. Abinader agreg\u00f3 que se arrib\u00f3 a un acuerdo que, al garantizar una mayor participaci\u00f3n del Estado en los beneficios generados por la operaci\u00f3n de los aeropuertos, generar\u00e1 recursos que ser\u00e1n utilizados en beneficio de los dominicanos.<\/p>\n","protected":false},"author":9,"featured_media":93402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-93401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=93401"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93401\/revisions"}],"predecessor-version":[{"id":93403,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/93401\/revisions\/93403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/93402"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=93401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=93401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=93401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}