{"id":94015,"date":"2024-01-08T08:05:14","date_gmt":"2024-01-08T12:05:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=94015"},"modified":"2024-01-08T08:05:16","modified_gmt":"2024-01-08T12:05:16","slug":"a-palos-limpios-escogido-vence-a-tigres-y-se-acerca-al-segundo-lugar","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/a-palos-limpios-escogido-vence-a-tigres-y-se-acerca-al-segundo-lugar\/","title":{"rendered":"\u00a1A palos limpios! Escogido vence a Tigres y se acerca al segundo lugar"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/659b4c776104e.jpeg\" alt=\"\" class=\"wp-image-94016\" width=\"199\" height=\"132\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/659b4c776104e.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/659b4c776104e-300x201.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/659b4c776104e-768x514.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/659b4c776104e-600x401.jpeg 600w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Con un triunfo 12-8 sobre los Tigres del Licey (5-4) este domingo, producto de 18 imparables, los Leones del Escogido (4-5) se acercaron a solo un partido de la segunda posici\u00f3n del Round Robin que ostentan los azules en su b\u00fasqueda de un pase a la Serie Final del b\u00e9isbol dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los melenudos vapulearon al abridor lice\u00edsta Brooks Hall en la segunda entrada, en la que iniciaron con un triple de Jorge Mateo por la raya del jard\u00edn izquierdo, anotando con un error del campocorto Sergio Alc\u00e1ntara en un batazo de Yamaico Navarro, quien pas\u00f3 a tercera por sencillo de Erik Gonz\u00e1lez al prado derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ataque de los visitantes no par\u00f3, ya que Gonz\u00e1lez se coloc\u00f3 en posici\u00f3n anotadora al robarse la segunda. Un doble de Orlando Calixte al bosque izquierdo trajo dos m\u00e1s para los rojos y otro error de Alc\u00e1ntara en un batazo de Junior Lake puso corredores en las esquinas. Un doble robo sum\u00f3 una m\u00e1s para los escarlatas y llev\u00f3 a Lake a segunda desde donde anot\u00f3 por infield-hit de H\u00e9ctor Rodr\u00edguez a la intermedia, base que luego se estaf\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lisalverto Bonilla entr\u00f3 a lanzar para enfrentar a Elier Hern\u00e1ndez, noveno bateador de ese episodio por los melenudos, quien fue transferido. Otro hit de Mateo por el jard\u00edn izquierdo empuj\u00f3 a Rodr\u00edguez hasta el plato con la sexta escogidista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los bengal\u00edes marcaron tres vueltas ante V\u00edctor Santos en la baja del segundo con jonr\u00f3n solitario de Ram\u00f3n Hern\u00e1ndez por el central y otro vuelacercas con uno a bordo por parte de Dawel Lugo por el bosque izquierdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el cuarto, con corredores en segunda y tercera, el Escogido fabric\u00f3 otras dos rayitas con un error en tiro de Hern\u00e1ndez en un toque a la inicial por parte de Michael P\u00e9rez, quien lleg\u00f3 a la intermedia en la jugada y anot\u00f3 con imparable de Navarro al central.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con dos outs, Calixte sum\u00f3 una vuelta m\u00e1s en el octavo con un infield-hit a segunda que se combin\u00f3 con un error en tiro del intermedista Michael De Le\u00f3n, siendo la quinta pifia de los locales en el juego, internando la pelota en zona foul del jard\u00edn derecho, lo que aprovech\u00f3 el corredor para anotar. El Licey produjo cinco m\u00e1s en la parte baja, tres de ellas gracias a un cuadrangular con dos a bordo de Robel Garc\u00eda por el prado derecho contra Alberto Leyva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santos tir\u00f3 cuatro actos de tres anotaciones, terminando sin decisi\u00f3n. El lanzador ganador fue Lincoln Henzman (1-0) al tirar dos cap\u00edtulos sin libertades. Hall (0-2) carg\u00f3 con la derrota al presentarse en 1.2 actos de seis carreras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los visitantes, Calixte bate\u00f3 de 5-4, con doble, tres empujadas, dos anotadas y una estafa; Mateo de 5-4, con triple, dos anotadas, una producida y una base robada; Navarro, de 3-1, con dos remolcadas, una anotada y transferencia; Rodr\u00edguez, de 6-2, con una impulsada, una anotada y un robo, y Gonz\u00e1lez, de 4-3, con dos anotadas y dos bases robadas. Por los azules, Lugo se fue de 4-1, con cuadrangular, dos producidas y una anotada; Hern\u00e1ndez, de 3-1, con jonr\u00f3n, una anotada y una empujada, y Garc\u00eda, de 1-1, con cuadrangular, tres remolcadas y una anotada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este lunes, el Escogido visitar\u00e1 a los Gigantes del Cibao a las 7:00 de la noche en el estadio Juli\u00e1n Javier, de San Francisco de Macor\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un triunfo 12-8 sobre los Tigres del Licey (5-4) este domingo, producto de 18 imparables, los Leones del Escogido (4-5) se acercaron a solo un partido de la segunda posici\u00f3n del Round Robin que ostentan los azules en su b\u00fasqueda de un pase a la Serie Final del b\u00e9isbol dominicano. Los melenudos vapulearon al abridor lice\u00edsta Brooks Hall en la segunda entrada, en la que iniciaron con un triple de Jorge Mateo por la raya del jard\u00edn izquierdo, anotando con un error del campocorto Sergio Alc\u00e1ntara en un batazo de Yamaico Navarro, quien pas\u00f3 a tercera por sencillo de Erik Gonz\u00e1lez al prado derecho. El ataque de los visitantes no par\u00f3, ya que Gonz\u00e1lez se coloc\u00f3 en posici\u00f3n anotadora al robarse la segunda. Un doble de Orlando Calixte al bosque izquierdo trajo dos m\u00e1s para los rojos y otro error de Alc\u00e1ntara en un batazo de Junior Lake puso corredores en las esquinas. Un doble robo sum\u00f3 una m\u00e1s para los escarlatas y llev\u00f3 a Lake a segunda desde donde anot\u00f3 por infield-hit de H\u00e9ctor Rodr\u00edguez a la intermedia, base que luego se estaf\u00f3. Lisalverto Bonilla entr\u00f3 a lanzar para enfrentar a Elier Hern\u00e1ndez, noveno bateador de ese episodio por los melenudos, quien fue transferido. Otro hit de Mateo por el jard\u00edn izquierdo empuj\u00f3 a Rodr\u00edguez hasta el plato con la sexta escogidista. Los bengal\u00edes marcaron tres vueltas ante V\u00edctor Santos en la baja del segundo con jonr\u00f3n solitario de Ram\u00f3n Hern\u00e1ndez por el central y otro vuelacercas con uno a bordo por parte de Dawel Lugo por el bosque izquierdo. En el cuarto, con corredores en segunda y tercera, el Escogido fabric\u00f3 otras dos rayitas con un error en tiro de Hern\u00e1ndez en un toque a la inicial por parte de Michael P\u00e9rez, quien lleg\u00f3 a la intermedia en la jugada y anot\u00f3 con imparable de Navarro al central. Con dos outs, Calixte sum\u00f3 una vuelta m\u00e1s en el octavo con un infield-hit a segunda que se combin\u00f3 con un error en tiro del intermedista Michael De Le\u00f3n, siendo la quinta pifia de los locales en el juego, internando la pelota en zona foul del jard\u00edn derecho, lo que aprovech\u00f3 el corredor para anotar. El Licey produjo cinco m\u00e1s en la parte baja, tres de ellas gracias a un cuadrangular con dos a bordo de Robel Garc\u00eda por el prado derecho contra Alberto Leyva. Santos tir\u00f3 cuatro actos de tres anotaciones, terminando sin decisi\u00f3n. El lanzador ganador fue Lincoln Henzman (1-0) al tirar dos cap\u00edtulos sin libertades. Hall (0-2) carg\u00f3 con la derrota al presentarse en 1.2 actos de seis carreras. Por los visitantes, Calixte bate\u00f3 de 5-4, con doble, tres empujadas, dos anotadas y una estafa; Mateo de 5-4, con triple, dos anotadas, una producida y una base robada; Navarro, de 3-1, con dos remolcadas, una anotada y transferencia; Rodr\u00edguez, de 6-2, con una impulsada, una anotada y un robo, y Gonz\u00e1lez, de 4-3, con dos anotadas y dos bases robadas. Por los azules, Lugo se fue de 4-1, con cuadrangular, dos producidas y una anotada; Hern\u00e1ndez, de 3-1, con jonr\u00f3n, una anotada y una empujada, y Garc\u00eda, de 1-1, con cuadrangular, tres remolcadas y una anotada. Este lunes, el Escogido visitar\u00e1 a los Gigantes del Cibao a las 7:00 de la noche en el estadio Juli\u00e1n Javier, de San Francisco de Macor\u00eds.<\/p>\n","protected":false},"author":9,"featured_media":94016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-94015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=94015"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94015\/revisions"}],"predecessor-version":[{"id":94017,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94015\/revisions\/94017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/94016"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=94015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=94015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=94015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}