{"id":94215,"date":"2024-01-23T07:01:44","date_gmt":"2024-01-23T11:01:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=94215"},"modified":"2024-01-23T07:01:45","modified_gmt":"2024-01-23T11:01:45","slug":"recomiendan-usar-mascarillas-y-vacunarse-contra-covid-19-en-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/recomiendan-usar-mascarillas-y-vacunarse-contra-covid-19-en-rd\/","title":{"rendered":"Recomiendan usar mascarillas y vacunarse contra Covid-19 en RD"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/mas.jpg\" alt=\"\" class=\"wp-image-94216\" width=\"244\" height=\"137\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/mas.jpg 877w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/mas-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/mas-768x435.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/01\/mas-600x340.jpg 600w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nSANTO DOMINGO.-&nbsp;El presidente de la Sociedad Dominicana de Neumolog\u00eda, Alfredo Matos Hoepelman, report\u00f3 el registro de pacientes adultos con Covid-19 y tambi\u00e9n con tosferina en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que la tosferina se caracteriza por una tos persistente, de hasta 10 semanas de duraci\u00f3n, y tan fuerte que puede causar fracturas costales y hasta la muerte, por lo cual aconsej\u00f3 reforzar la vacuna DT en adultos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CAMBIOS EN LOS S\u00cdNTOMAS DE LA COVID-19<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El neum\u00f3logo alert\u00f3 que se est\u00e1n viendo pacientes sin fiebre y con diarrea que son positivos a la Covid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomend\u00f3 usar la mascarilla en los lugares p\u00fablicos, hospitales, laboratorios, y tambi\u00e9n en la casa si presenta algunos s\u00ecntomas de la dolencia para proteger a los dem\u00e1s integrantes de la familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva variante del Covid-19 que circula en el pa\u00eds JN-1 se transmite r\u00e1pidamente, sus s\u00edntomas se presentan entre las 24 a 48 horas, algunos pacientes presentan tos, dificultad para respirar, diarrea y secreci\u00f3n verdosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PIDEN VACUNARSE CONTRA COVID-19 Y DEJAR EL TABAQUISMO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Sociedad Dominicana de Neumolog\u00eda recomienda a los ciudadanos terminar su esquema de vacunas contra la Covid-19, y tomar vitaminas D3 y C para fortalecer el sistema respiratorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, Matos Hoepelman advirti\u00f3 que ning\u00fan dispositivo que se utilice para fumar es seguro y record\u00f3 que los vapes sin humo, poseen mayor cantidad de nicotina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Revel\u00f3 que a nivel mundial aument\u00f3 el c\u00e1ncer de labios, lengua, garganta y enc\u00edas por el uso de vapes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tendencia en el pa\u00eds se mantiene entre j\u00f3venes de 14 a 24 a\u00f1os de edad que llegan a la consulta peores que cualquier asm\u00e1tico, congestionados y con un da\u00f1o pulmonar incre\u00edble que a veces es irreversible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Urgi\u00f3 a las familias tener ojo visor con los hijos e informarles sobre el da\u00f1o de cualquier cigarrillo para la salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-&nbsp;El presidente de la Sociedad Dominicana de Neumolog\u00eda, Alfredo Matos Hoepelman, report\u00f3 el registro de pacientes adultos con Covid-19 y tambi\u00e9n con tosferina en el pa\u00eds. Record\u00f3 que la tosferina se caracteriza por una tos persistente, de hasta 10 semanas de duraci\u00f3n, y tan fuerte que puede causar fracturas costales y hasta la muerte, por lo cual aconsej\u00f3 reforzar la vacuna DT en adultos. CAMBIOS EN LOS S\u00cdNTOMAS DE LA COVID-19 El neum\u00f3logo alert\u00f3 que se est\u00e1n viendo pacientes sin fiebre y con diarrea que son positivos a la Covid. Recomend\u00f3 usar la mascarilla en los lugares p\u00fablicos, hospitales, laboratorios, y tambi\u00e9n en la casa si presenta algunos s\u00ecntomas de la dolencia para proteger a los dem\u00e1s integrantes de la familia. La nueva variante del Covid-19 que circula en el pa\u00eds JN-1 se transmite r\u00e1pidamente, sus s\u00edntomas se presentan entre las 24 a 48 horas, algunos pacientes presentan tos, dificultad para respirar, diarrea y secreci\u00f3n verdosa. PIDEN VACUNARSE CONTRA COVID-19 Y DEJAR EL TABAQUISMO La Sociedad Dominicana de Neumolog\u00eda recomienda a los ciudadanos terminar su esquema de vacunas contra la Covid-19, y tomar vitaminas D3 y C para fortalecer el sistema respiratorio. Por otro lado, Matos Hoepelman advirti\u00f3 que ning\u00fan dispositivo que se utilice para fumar es seguro y record\u00f3 que los vapes sin humo, poseen mayor cantidad de nicotina. Revel\u00f3 que a nivel mundial aument\u00f3 el c\u00e1ncer de labios, lengua, garganta y enc\u00edas por el uso de vapes. La tendencia en el pa\u00eds se mantiene entre j\u00f3venes de 14 a 24 a\u00f1os de edad que llegan a la consulta peores que cualquier asm\u00e1tico, congestionados y con un da\u00f1o pulmonar incre\u00edble que a veces es irreversible. Urgi\u00f3 a las familias tener ojo visor con los hijos e informarles sobre el da\u00f1o de cualquier cigarrillo para la salud.<\/p>\n","protected":false},"author":9,"featured_media":94216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-94215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=94215"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94215\/revisions"}],"predecessor-version":[{"id":94217,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94215\/revisions\/94217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/94216"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=94215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=94215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=94215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}