{"id":94634,"date":"2024-02-16T07:58:52","date_gmt":"2024-02-16T11:58:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=94634"},"modified":"2024-02-16T07:59:00","modified_gmt":"2024-02-16T11:59:00","slug":"habra-llegado-la-era-de-marco-luciano-como-paracorto-titular-con-gigantes-de-san-francisco","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/habra-llegado-la-era-de-marco-luciano-como-paracorto-titular-con-gigantes-de-san-francisco\/","title":{"rendered":"\u00bfHabr\u00e1 llegado la era de Marco Luciano como paracorto titular con Gigantes de San Francisco?"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/65cea49c2e040.r_d.642-299.jpeg\" alt=\"\" class=\"wp-image-94635\" width=\"229\" height=\"111\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/65cea49c2e040.r_d.642-299.jpeg 950w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/65cea49c2e040.r_d.642-299-300x147.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/65cea49c2e040.r_d.642-299-768x376.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/65cea49c2e040.r_d.642-299-600x294.jpeg 600w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Durante 13 campa\u00f1as Brandon Crawford fue \u201camo y se\u00f1or\u201d del campocorto en los Gigantes de San Francisco, a los 37 a\u00f1os su carrera habr\u00eda llegado a su fin, al menos con esa franquicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la mayor\u00eda de los equipos ya en entrenamientos, el tres veces paracorto Todos Estrellas a\u00fan permanece desempleado y con escaso ruido de que alguna franquicia lo estar\u00eda contratando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras concluir su pacto de 36 millones por seis campa\u00f1as con los Gigantes, al parecer culmina su era con el club y pudiera estar comenzando la de Marco Luciano en el famoso equipo de la Bah\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con las pr\u00e1cticas ya iniciadas, el dominicano est\u00e1 proyectado para apoderarse de la posici\u00f3n que por a\u00f1os Crawford hizo suya y le brind\u00f3 gran personalidad durante el tiempo en que accion\u00f3 con los Gigantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVoy listo a realizar mi trabajo, laborar bien fuerte, brindar lo mejor de m\u00ed, jugar el b\u00e9isbol y tambi\u00e9n a divertirme un poco en el terreno, esos son mis grandes objetivos\u201d, expuso Luciano, quien el a\u00f1o pasado prob\u00f3 su primer sorbo en Grandes Ligas y accion\u00f3 en 14 partidos en los que bate\u00f3 para .231 (39-9) con tres dobles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sereno, confiado de las ejecuciones que puede ser capaz de materializar en el campo, el novel de 22 a\u00f1os reconoce que este 2024 ser\u00eda un a\u00f1o de mucho inter\u00e9s en su carrera y por este futuro se ha preparado lo m\u00e1s fuerte posible para tratar de apoderarse del puesto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe qu\u00e9 las \u00faltimas palabras las tendr\u00e1n la dirigencia y ejecutivo, pero voy a dar todo de mi para tratar de quedarme en el conjunto y ganar la mayor cantidad de tiempo de juego\u201d, sostuvo el nativo de San Pedro de Macor\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luciano ha sido una de las principales joyas firmados por los Gigantes en el draft Internacional. El recibi\u00f3 un bono lucrativo de 2.6 millones de d\u00f3lares en el 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Experiencia con el Escogido<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La campa\u00f1a reci\u00e9n concluida labor\u00f3 por poco m\u00e1s de un mes con el Escogido y narra que fue brillante la experiencia de jugar en un nivel superior como es la Liga Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAprend\u00ed mucho en el invierno, y varias cosas de ese aprendizaje espero ejecutarlas con los Gigantes\u201d, sostuvo el paracorto de 6\u00b41 de estatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con los Leones accion\u00f3 en 18 partidos y tuvo average de .170 (47-8) con un jonr\u00f3n y 4 empujadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHabr\u00e1 llegado su era de establecerse con los Gigantes?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante 13 campa\u00f1as Brandon Crawford fue \u201camo y se\u00f1or\u201d del campocorto en los Gigantes de San Francisco, a los 37 a\u00f1os su carrera habr\u00eda llegado a su fin, al menos con esa franquicia. Con la mayor\u00eda de los equipos ya en entrenamientos, el tres veces paracorto Todos Estrellas a\u00fan permanece desempleado y con escaso ruido de que alguna franquicia lo estar\u00eda contratando. Tras concluir su pacto de 36 millones por seis campa\u00f1as con los Gigantes, al parecer culmina su era con el club y pudiera estar comenzando la de Marco Luciano en el famoso equipo de la Bah\u00eda. Con las pr\u00e1cticas ya iniciadas, el dominicano est\u00e1 proyectado para apoderarse de la posici\u00f3n que por a\u00f1os Crawford hizo suya y le brind\u00f3 gran personalidad durante el tiempo en que accion\u00f3 con los Gigantes. \u201cVoy listo a realizar mi trabajo, laborar bien fuerte, brindar lo mejor de m\u00ed, jugar el b\u00e9isbol y tambi\u00e9n a divertirme un poco en el terreno, esos son mis grandes objetivos\u201d, expuso Luciano, quien el a\u00f1o pasado prob\u00f3 su primer sorbo en Grandes Ligas y accion\u00f3 en 14 partidos en los que bate\u00f3 para .231 (39-9) con tres dobles. Sereno, confiado de las ejecuciones que puede ser capaz de materializar en el campo, el novel de 22 a\u00f1os reconoce que este 2024 ser\u00eda un a\u00f1o de mucho inter\u00e9s en su carrera y por este futuro se ha preparado lo m\u00e1s fuerte posible para tratar de apoderarse del puesto. \u201cSe qu\u00e9 las \u00faltimas palabras las tendr\u00e1n la dirigencia y ejecutivo, pero voy a dar todo de mi para tratar de quedarme en el conjunto y ganar la mayor cantidad de tiempo de juego\u201d, sostuvo el nativo de San Pedro de Macor\u00eds. Luciano ha sido una de las principales joyas firmados por los Gigantes en el draft Internacional. El recibi\u00f3 un bono lucrativo de 2.6 millones de d\u00f3lares en el 2018. Experiencia con el Escogido La campa\u00f1a reci\u00e9n concluida labor\u00f3 por poco m\u00e1s de un mes con el Escogido y narra que fue brillante la experiencia de jugar en un nivel superior como es la Liga Dominicana. \u201cAprend\u00ed mucho en el invierno, y varias cosas de ese aprendizaje espero ejecutarlas con los Gigantes\u201d, sostuvo el paracorto de 6\u00b41 de estatura. Con los Leones accion\u00f3 en 18 partidos y tuvo average de .170 (47-8) con un jonr\u00f3n y 4 empujadas. \u201cHabr\u00e1 llegado su era de establecerse con los Gigantes?<\/p>\n","protected":false},"author":9,"featured_media":94635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-94634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=94634"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94634\/revisions"}],"predecessor-version":[{"id":94636,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94634\/revisions\/94636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/94635"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=94634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=94634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=94634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}