{"id":94693,"date":"2024-02-20T09:39:47","date_gmt":"2024-02-20T13:39:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=94693"},"modified":"2024-02-20T09:39:58","modified_gmt":"2024-02-20T13:39:58","slug":"dominicano-luis-severino-dice-estar-listo-para-los-mets-de-ny","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dominicano-luis-severino-dice-estar-listo-para-los-mets-de-ny\/","title":{"rendered":"Dominicano Luis Severino dice estar listo para los Mets de NY"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/luissev-1024x576.png\" alt=\"\" class=\"wp-image-94694\" width=\"205\" height=\"115\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/luissev-1024x576.png 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/luissev-300x169.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/luissev-768x432.png 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/luissev-600x338.png 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/02\/luissev.png 1920w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NUEVA YORK.- Luis Severino<\/strong>\u00a0est\u00e1 cerca de lanzar junto a<strong>\u00a0New York Mets\u00a0<\/strong>por primera vez en su carrera, tras pasar los primeros ocho a\u00f1os de la misma siendo un jugador de\u00a0<strong>New York Yankees<\/strong>. En esta ocasi\u00f3n y a punto de cumplir 30 a\u00f1os, el lanzador dominicano, quien en un momento fue considerado como uno de los brazos m\u00e1s s\u00f3lidos de\u00a0<strong>Grandes Ligas<\/strong>, tiene mucho que probar y unas altas expectativas sobre sus hombros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de esto, la posible presi\u00f3n de dichas expectativas no parece afectarlo y, muy por el contrario, el propio jugador indica que para \u00e9l esto es un reto que asume de frente, ya que esa misma presi\u00f3n es la que le ha llevado a tener \u00e9xito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Cuando llegu\u00e9 a la agencia libre, hubo muchas personas, familia y amigos que quer\u00edan que fuera a un lugar sin presi\u00f3n y despu\u00e9s pensando m\u00e1s al respecto, lo que me impulsa y me mantiene es la presi\u00f3n. Lo que me mantiene adelante es la presi\u00f3n. Me encanta estar bajo presi\u00f3n. Estuve en Nueva York por mucho tiempo. Estoy feliz de estar con esta organizaci\u00f3n, los Mets, porque quiero seguir sintiendo esa presi\u00f3n<\/em>\u201d, asegur\u00f3&nbsp;<strong>Severino<\/strong>&nbsp;ante los medios de prensa tras sus primeros d\u00edas de entrenamiento con los Mets.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo,&nbsp;<strong>Severino&nbsp;<\/strong>deber\u00e1 darles valor a sus palabras luego de haber tenido un 2023 para el olvido en su \u00faltima campa\u00f1a junto a&nbsp;<strong>Yankees<\/strong>. En 19 salidas,&nbsp;<strong>Severino<\/strong>&nbsp;ostent\u00f3 una efectividad de 6.65 en 89.1 entradas de labor con 79 ponches, 34 bases por bolas, un FIP de 6.14 y un WHIP de 1.646, siento todas estad\u00edsticas algunas de las peores de su carrera, tomando en cuenta el volumen de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los&nbsp;<strong>Mets<\/strong>, por su lado y a pesar del a\u00f1o que tuvo, conf\u00edan en que el dominicano tiene las herramientas para rebotar y verse como el lanzador de antes, lo cual no solo han demostrado al darle un contrato, sino con las palabras del nuevo dirigente del equipo,&nbsp;<strong>Carlos Mendoza<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Mis expectativas es que va a ser un jugador de impacto para nosotros. Todos lo hemos visto antes, especialmente cuando est\u00e1 saludable, sus lanzamientos son electrizantes, esperamos que nos d\u00e9 muchas entradas,<\/em>&nbsp;(especialmente)&nbsp;<em>muchas entradas de calidad. \u00c9l va a ser una gran parte de lo que estamos intentando hacer aqu\u00ed<\/em>\u201d, sentenci\u00f3&nbsp;<strong>Mendoza<\/strong>&nbsp;tras el primer bullpen de&nbsp;<strong>Severino<\/strong>&nbsp;con el equipo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUEVA YORK.- Luis Severino\u00a0est\u00e1 cerca de lanzar junto a\u00a0New York Mets\u00a0por primera vez en su carrera, tras pasar los primeros ocho a\u00f1os de la misma siendo un jugador de\u00a0New York Yankees. En esta ocasi\u00f3n y a punto de cumplir 30 a\u00f1os, el lanzador dominicano, quien en un momento fue considerado como uno de los brazos m\u00e1s s\u00f3lidos de\u00a0Grandes Ligas, tiene mucho que probar y unas altas expectativas sobre sus hombros. A pesar de esto, la posible presi\u00f3n de dichas expectativas no parece afectarlo y, muy por el contrario, el propio jugador indica que para \u00e9l esto es un reto que asume de frente, ya que esa misma presi\u00f3n es la que le ha llevado a tener \u00e9xito. \u201cCuando llegu\u00e9 a la agencia libre, hubo muchas personas, familia y amigos que quer\u00edan que fuera a un lugar sin presi\u00f3n y despu\u00e9s pensando m\u00e1s al respecto, lo que me impulsa y me mantiene es la presi\u00f3n. Lo que me mantiene adelante es la presi\u00f3n. Me encanta estar bajo presi\u00f3n. Estuve en Nueva York por mucho tiempo. Estoy feliz de estar con esta organizaci\u00f3n, los Mets, porque quiero seguir sintiendo esa presi\u00f3n\u201d, asegur\u00f3&nbsp;Severino&nbsp;ante los medios de prensa tras sus primeros d\u00edas de entrenamiento con los Mets. Sin embargo,&nbsp;Severino&nbsp;deber\u00e1 darles valor a sus palabras luego de haber tenido un 2023 para el olvido en su \u00faltima campa\u00f1a junto a&nbsp;Yankees. En 19 salidas,&nbsp;Severino&nbsp;ostent\u00f3 una efectividad de 6.65 en 89.1 entradas de labor con 79 ponches, 34 bases por bolas, un FIP de 6.14 y un WHIP de 1.646, siento todas estad\u00edsticas algunas de las peores de su carrera, tomando en cuenta el volumen de trabajo. Los&nbsp;Mets, por su lado y a pesar del a\u00f1o que tuvo, conf\u00edan en que el dominicano tiene las herramientas para rebotar y verse como el lanzador de antes, lo cual no solo han demostrado al darle un contrato, sino con las palabras del nuevo dirigente del equipo,&nbsp;Carlos Mendoza. \u201cMis expectativas es que va a ser un jugador de impacto para nosotros. Todos lo hemos visto antes, especialmente cuando est\u00e1 saludable, sus lanzamientos son electrizantes, esperamos que nos d\u00e9 muchas entradas,&nbsp;(especialmente)&nbsp;muchas entradas de calidad. \u00c9l va a ser una gran parte de lo que estamos intentando hacer aqu\u00ed\u201d, sentenci\u00f3&nbsp;Mendoza&nbsp;tras el primer bullpen de&nbsp;Severino&nbsp;con el equipo.<\/p>\n","protected":false},"author":9,"featured_media":94694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-94693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=94693"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94693\/revisions"}],"predecessor-version":[{"id":94695,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/94693\/revisions\/94695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/94694"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=94693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=94693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=94693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}