{"id":95164,"date":"2024-03-01T06:52:17","date_gmt":"2024-03-01T10:52:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95164"},"modified":"2024-03-01T06:52:30","modified_gmt":"2024-03-01T10:52:30","slug":"el-presidente-abinader-visita-este-fin-de-semana-cinco-provincias","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-presidente-abinader-visita-este-fin-de-semana-cinco-provincias\/","title":{"rendered":"El Presidente Abinader visita este fin de semana cinco provincias"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luis-Abinader-1024x682.jpeg\" alt=\"\" class=\"wp-image-95165\" width=\"271\" height=\"180\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luis-Abinader-1024x682.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luis-Abinader-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luis-Abinader-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luis-Abinader-600x400.jpeg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luis-Abinader.jpeg 1600w\" sizes=\"auto, (max-width: 271px) 100vw, 271px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El presidente Luis Abinader iniciar\u00e1 este viernes una agenda de trabajo que se extender\u00e1 hasta el domingo y abarcar\u00e1 las provincias de La Altagracia, Monte Plata, Santo Domingo, Saman\u00e1 y Duarte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La agenda del mandatario incluye la inauguraci\u00f3n de varios planteles escolares y deportivos, dos fortalezas del Ej\u00e9rcito, la entrega de 800 t\u00edtulos de propiedad y nuevos apartamentos, entre otros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Viernes 1<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Punta Cana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A las 10:30 de la ma\u00f1ana de este viernes, el mandatario participar\u00e1 en la inauguraci\u00f3n del proyecto tur\u00edstico \u2013 inmobiliario \u201cTorre 7&nbsp;mares\u201d, en Punta Cana.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">S\u00e1bado 2<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Monte Plata<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada del s\u00e1bado iniciar\u00e1 en Sabana Grande de Boy\u00e1, Monte Plata, a las 11:00 de la ma\u00f1ana, con la entrega de 800 t\u00edtulos de propiedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente encabezar\u00e1 la inauguraci\u00f3n de la Escuela B\u00e1sica Sabana Grande de Boy\u00e1 y acto seguido presidir\u00e1 tambi\u00e9n la inauguraci\u00f3n del puente sobre el rio Lim\u00f3n, en la carretera Monte Plata-Bayaguana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gran Santo Domingo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe de Estado se trasladar\u00e1 luego al Gran Santo Domingo donde encabezar\u00e1 la inauguraci\u00f3n del plantel escolar San Felipe Sur Gualey, en Santo Domingo Norte, y m\u00e1s tarde presidir\u00e1 la entrega de nuevos apartamentos en Ciudad&nbsp;Modelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma el presidente Abinader inaugurar\u00e1 un plantel escolar en el km 25 de la Autopista Duarte, pr\u00f3ximo al peaje, y entregar\u00e1 apartamentos del Programa Vivienda Feliz en Hato Nuevo, km 22 de la Autopista Duarte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Domingo 3<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Saman\u00e1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo el gobernante viajar\u00e1 a Saman\u00e1, donde encabezar\u00e1, a las 11 de la ma\u00f1ana, el acto de la \u201cTransformaci\u00f3n y Presentaci\u00f3n de la Construcci\u00f3n del Puerto De Arroyo Barril\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, Abinader presidir\u00e1 la inauguraci\u00f3n de la fortaleza del Ej\u00e9rcito y m\u00e1s tarde, la inauguraci\u00f3n de los polideportivos de Saman\u00e1 y S\u00e1nchez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Duarte<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La agenda concluye en Bajo Yuna, provincia Duarte, con la inauguraci\u00f3n de la fortaleza de esta localidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El presidente Luis Abinader iniciar\u00e1 este viernes una agenda de trabajo que se extender\u00e1 hasta el domingo y abarcar\u00e1 las provincias de La Altagracia, Monte Plata, Santo Domingo, Saman\u00e1 y Duarte. La agenda del mandatario incluye la inauguraci\u00f3n de varios planteles escolares y deportivos, dos fortalezas del Ej\u00e9rcito, la entrega de 800 t\u00edtulos de propiedad y nuevos apartamentos, entre otros. Viernes 1 Punta Cana A las 10:30 de la ma\u00f1ana de este viernes, el mandatario participar\u00e1 en la inauguraci\u00f3n del proyecto tur\u00edstico \u2013 inmobiliario \u201cTorre 7&nbsp;mares\u201d, en Punta Cana. S\u00e1bado 2 Monte Plata La jornada del s\u00e1bado iniciar\u00e1 en Sabana Grande de Boy\u00e1, Monte Plata, a las 11:00 de la ma\u00f1ana, con la entrega de 800 t\u00edtulos de propiedad. Posteriormente encabezar\u00e1 la inauguraci\u00f3n de la Escuela B\u00e1sica Sabana Grande de Boy\u00e1 y acto seguido presidir\u00e1 tambi\u00e9n la inauguraci\u00f3n del puente sobre el rio Lim\u00f3n, en la carretera Monte Plata-Bayaguana. Gran Santo Domingo El jefe de Estado se trasladar\u00e1 luego al Gran Santo Domingo donde encabezar\u00e1 la inauguraci\u00f3n del plantel escolar San Felipe Sur Gualey, en Santo Domingo Norte, y m\u00e1s tarde presidir\u00e1 la entrega de nuevos apartamentos en Ciudad&nbsp;Modelo. De igual forma el presidente Abinader inaugurar\u00e1 un plantel escolar en el km 25 de la Autopista Duarte, pr\u00f3ximo al peaje, y entregar\u00e1 apartamentos del Programa Vivienda Feliz en Hato Nuevo, km 22 de la Autopista Duarte. Domingo 3 Saman\u00e1 El domingo el gobernante viajar\u00e1 a Saman\u00e1, donde encabezar\u00e1, a las 11 de la ma\u00f1ana, el acto de la \u201cTransformaci\u00f3n y Presentaci\u00f3n de la Construcci\u00f3n del Puerto De Arroyo Barril\u201d. Luego, Abinader presidir\u00e1 la inauguraci\u00f3n de la fortaleza del Ej\u00e9rcito y m\u00e1s tarde, la inauguraci\u00f3n de los polideportivos de Saman\u00e1 y S\u00e1nchez. Duarte La agenda concluye en Bajo Yuna, provincia Duarte, con la inauguraci\u00f3n de la fortaleza de esta localidad.<\/p>\n","protected":false},"author":9,"featured_media":95165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-95164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95164"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95164\/revisions"}],"predecessor-version":[{"id":95166,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95164\/revisions\/95166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95165"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}