{"id":95188,"date":"2024-03-02T07:49:11","date_gmt":"2024-03-02T11:49:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95188"},"modified":"2024-03-02T07:49:13","modified_gmt":"2024-03-02T11:49:13","slug":"exposicion-luz-y-vida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/exposicion-luz-y-vida\/","title":{"rendered":"Exposici\u00f3n Luz y Vida"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luz-y-Vida-1-e1706601947107-400x267-1.jpg\" alt=\"\" class=\"wp-image-95189\" width=\"287\" height=\"192\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luz-y-Vida-1-e1706601947107-400x267-1.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Luz-y-Vida-1-e1706601947107-400x267-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 287px) 100vw, 287px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> En 2015 se celebr\u00f3 el A\u00f1o Internacional de la Luz y las Tecnolog\u00edas Basadas en la luz, surgiendo a lo largo del a\u00f1o importantes contactos y colaboraciones entre expertos en tecnolog\u00eda y cient\u00edficos especializados en temas relacionados con la luz. Fue un gran \u00e9xito y para mantener y estimular estas relaciones, la UNESCO acord\u00f3 en noviembre de 2017 declarar el 16 de mayo D\u00eda Internacional de la Luz (Resoluci\u00f3n 39 C\/40), haci\u00e9ndolo coincidir con el d\u00eda en el que por primera vez, en 1960, el f\u00edsico Theodore H. Maiman puso en funcionamiento un l\u00e1ser de rub\u00ed que ten\u00eda capacidad de amplificar la luz por emisi\u00f3n estimulada de radiaci\u00f3n. Para potenciar estas relaciones, se cre\u00f3 en nuestro pa\u00eds el Comit\u00e9 Espa\u00f1ol del D\u00eda Internacional de la luz, que impulsa cada a\u00f1o la celebraci\u00f3n de este d\u00eda en una de nuestras ciudades o Comunidades, como ha sido en este caso la elecci\u00f3n de Andaluc\u00eda (Granada y Sevilla). Como parte de la celebraci\u00f3n de 2023, el Instituto de Academias de Andaluc\u00eda ha organizado esta Exposici\u00f3n, en cuya preparaci\u00f3n han intervenido acad\u00e9micos e investigadores de las Instituciones que se relacionan en este primer panel, con el apoyo de las Universidades de Sevilla y Granada, la Real Sociedad Espa\u00f1ola de F\u00edsica (Divisi\u00f3n de Ense\u00f1anza de la F\u00edsica), El Comit\u00e9 Espa\u00f1ol para el D\u00eda Internacional de la Luz, La Sociedad Espa\u00f1ola de \u00d3ptica y la Fundaci\u00f3n Descubre <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2015 se celebr\u00f3 el A\u00f1o Internacional de la Luz y las Tecnolog\u00edas Basadas en la luz, surgiendo a lo largo del a\u00f1o importantes contactos y colaboraciones entre expertos en tecnolog\u00eda y cient\u00edficos especializados en temas relacionados con la luz. Fue un gran \u00e9xito y para mantener y estimular estas relaciones, la UNESCO acord\u00f3 en noviembre de 2017 declarar el 16 de mayo D\u00eda Internacional de la Luz (Resoluci\u00f3n 39 C\/40), haci\u00e9ndolo coincidir con el d\u00eda en el que por primera vez, en 1960, el f\u00edsico Theodore H. Maiman puso en funcionamiento un l\u00e1ser de rub\u00ed que ten\u00eda capacidad de amplificar la luz por emisi\u00f3n estimulada de radiaci\u00f3n. Para potenciar estas relaciones, se cre\u00f3 en nuestro pa\u00eds el Comit\u00e9 Espa\u00f1ol del D\u00eda Internacional de la luz, que impulsa cada a\u00f1o la celebraci\u00f3n de este d\u00eda en una de nuestras ciudades o Comunidades, como ha sido en este caso la elecci\u00f3n de Andaluc\u00eda (Granada y Sevilla). Como parte de la celebraci\u00f3n de 2023, el Instituto de Academias de Andaluc\u00eda ha organizado esta Exposici\u00f3n, en cuya preparaci\u00f3n han intervenido acad\u00e9micos e investigadores de las Instituciones que se relacionan en este primer panel, con el apoyo de las Universidades de Sevilla y Granada, la Real Sociedad Espa\u00f1ola de F\u00edsica (Divisi\u00f3n de Ense\u00f1anza de la F\u00edsica), El Comit\u00e9 Espa\u00f1ol para el D\u00eda Internacional de la Luz, La Sociedad Espa\u00f1ola de \u00d3ptica y la Fundaci\u00f3n Descubre<\/p>\n","protected":false},"author":9,"featured_media":95189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-95188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95188"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95188\/revisions"}],"predecessor-version":[{"id":95190,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95188\/revisions\/95190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95189"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}