{"id":95250,"date":"2024-03-06T08:12:00","date_gmt":"2024-03-06T12:12:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95250"},"modified":"2024-03-06T08:12:01","modified_gmt":"2024-03-06T12:12:01","slug":"ariel-henry-esta-en-puerto-rico-y-onu-tratara-crisis-a-puerta-cerrada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ariel-henry-esta-en-puerto-rico-y-onu-tratara-crisis-a-puerta-cerrada\/","title":{"rendered":"Ariel Henry est\u00e1 en Puerto Rico y ONU tratar\u00e1 crisis a puerta cerrada"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65e7c5437dd00.r_d.1605-876.jpeg\" alt=\"\" class=\"wp-image-95251\" width=\"249\" height=\"166\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65e7c5437dd00.r_d.1605-876.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65e7c5437dd00.r_d.1605-876-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65e7c5437dd00.r_d.1605-876-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65e7c5437dd00.r_d.1605-876-600x400.jpeg 600w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El avi\u00f3n en que se transportaba el primer ministro de Hait\u00ed, Ariel Henry, aterriz\u00f3 ayer en el Aeropuerto Internacional Luis Mu\u00f1oz Mar\u00edn, de San Juan, Puerto Rico, luego de varios d\u00edas sin que se conociera el paradero del gobernante<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La llegada de Henry a Puerto Rico fue confirmada por la portavoz del Poder Ejecutivo en ese pa\u00eds caribe\u00f1o, Sheila Angler\u00f3, al peri\u00f3dico El Nuevo D\u00eda, quien junto a List\u00edn Diario forman parte del Grupo de Diarios Am\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las esperanzas de Henry de llegar a Hait\u00ed se reducen cada vez m\u00e1s. Seg\u00fan informaci\u00f3n, todos los vuelos a Hait\u00ed est\u00e1n prohibidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque Henry quiere irse a otro pa\u00eds, su situaci\u00f3n complicada porque el seguro de avi\u00f3n actualmente les proh\u00edbe viajar a Hait\u00ed, de lo contrario no ser\u00e1n indemnizados en caso de incidente, seg\u00fan public\u00f3 Radio Tele Metronome<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer ministro sali\u00f3 ayer, sin que se haya confirmado la hora, desde el Aeropuerto de Teterboro en New Jersey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">List\u00edn Diario contact\u00f3 al Aeropuerto de Teterboro para confirmar d\u00f3nde se encontraba el primer ministro haitiano, pero no pudo recibir informaci\u00f3n certera ante la solicitud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesafortunadamente, no podemos compartir ninguna informaci\u00f3n\u201d, indic\u00f3 la autoridad portuaria de Nueva York-New Jersey a la petici\u00f3n de este medio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No lo dejaron aterrizar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de llegar a Puerto Rico, la aeronave habr\u00eda solicitado aterrizar en Aeropuerto Internacional Toussaint Louverture, ubicado en Puerto Pr\u00edncipe, petici\u00f3n que le fue negada, seg\u00fan establece El Nuevo D\u00eda en una nota donde confirmaban el arribo de Henry a su territorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de esta negativa, una fuente inform\u00f3 a List\u00edn Diario que al encontrarse en el espacio a\u00e9reo de Rep\u00fablica Dominicana, la aeronave tambi\u00e9n solicit\u00f3 aterrizar en el pa\u00eds, petici\u00f3n que no le fue otorgada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Henry sali\u00f3 de Hait\u00ed a finales del mes de febrero para participar en la 46\u00b0 Reuni\u00f3n Ordinaria de la Comunidad del Caribe (Caricom), que se celebr\u00f3 del 25 al 28 de febrero de en Georgetown, Guyana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta reuni\u00f3n se inform\u00f3 que el primer ministro hab\u00eda aceptado la celebraci\u00f3n de elecciones generales en agosto de 2025. En Hait\u00ed no se celebran elecciones desde el 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado Caricom indic\u00f3, adem\u00e1s, que Estados Unidos, Canad\u00e1 y Naciones Unidas crear\u00edan un equipo de evaluaci\u00f3n para ayudar a Hait\u00ed a preparar las elecciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de ah\u00ed, Henry viaj\u00f3 a Kenia, donde el 29 de febrero firm\u00f3 junto, al mandatario de ese pa\u00eds, William Ruto, el acuerdo para el env\u00edo de 1, 000 polic\u00edas kenianos a Hait\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe complace informar que el primer ministro interino de Hait\u00ed, Ariel Henry, y yo hemos sido testigos de la firma de este instrumento. Tambi\u00e9n hemos discutido los pr\u00f3ximos pasos para permitir la v\u00eda r\u00e1pida del despliegue\u201d, expres\u00f3 Ruto al tiempo de decir que \u201cest\u00e1 comprometido a contribuir al \u00e9xito de la misi\u00f3n multinacional porque es un deber hist\u00f3rico para la paz en Hait\u00ed\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de su participaci\u00f3n en este acuerdo, se desconoc\u00eda el paradero del primer ministro, aunque se rumoraba que habr\u00eda salido de Kenia el s\u00e1bado 2 de marzo y se encontraba en Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toque de queda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el primer ministro est\u00e1 de forma interina Patrick Michel Boivert, quien el pasado domingo orden\u00f3 un toque de queda desde las 6:00 de la tarde hasta las 5:00 de la ma\u00f1ana, desde el lunes 4 hasta el mi\u00e9rcoles 6 en Puerto Pr\u00edncipe, por la ola de violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Henry asumi\u00f3 el poder tras el asesinato del presidente Jovenel Mo\u00efse en 2021. El mandato de Henry expir\u00f3 el pasado 7 de febrero, seg\u00fan un acuerdo firmado por \u00e9l junto a la oposici\u00f3n de ese pa\u00eds en diciembre de 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auge de violencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La crisis en Hait\u00ed se agudiz\u00f3 desde el pasado jueves, ante la ausencia del primer ministro, con el reporte de varios tiroteos en Puerto Pr\u00edncipe, capital de ese pa\u00eds, y controlada en 80% por las bandas haitianas. Estas bandas han ocasionado el desplazamiento de m\u00e1s de 15,000 personas, de acuerdo al portavoz de la ONU, St\u00e9phane Dujarric.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viernes, al igual que el lunes, se reportaron varios disparos en Puerto Pr\u00edncipe, en especial en el Aeropuerto Toussaint Louverture, cuando bandas haitianas y miembros de la polic\u00eda escenificaron un tiroteo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El s\u00e1bado la violencia se agudiz\u00f3 con la liberaci\u00f3n de m\u00e1s de 3,600 privados de libertad, luego de que las bandas irrumpieran en dos recintos carcelarios m\u00e1s grandes de ese pa\u00eds. Los reportes de los medios haitianos se\u00f1alan que decenas de privados de libertad fueron asesinados en las inmediaciones de las c\u00e1rceles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El avi\u00f3n en que se transportaba el primer ministro de Hait\u00ed, Ariel Henry, aterriz\u00f3 ayer en el Aeropuerto Internacional Luis Mu\u00f1oz Mar\u00edn, de San Juan, Puerto Rico, luego de varios d\u00edas sin que se conociera el paradero del gobernante La llegada de Henry a Puerto Rico fue confirmada por la portavoz del Poder Ejecutivo en ese pa\u00eds caribe\u00f1o, Sheila Angler\u00f3, al peri\u00f3dico El Nuevo D\u00eda, quien junto a List\u00edn Diario forman parte del Grupo de Diarios Am\u00e9rica. Las esperanzas de Henry de llegar a Hait\u00ed se reducen cada vez m\u00e1s. Seg\u00fan informaci\u00f3n, todos los vuelos a Hait\u00ed est\u00e1n prohibidos. Aunque Henry quiere irse a otro pa\u00eds, su situaci\u00f3n complicada porque el seguro de avi\u00f3n actualmente les proh\u00edbe viajar a Hait\u00ed, de lo contrario no ser\u00e1n indemnizados en caso de incidente, seg\u00fan public\u00f3 Radio Tele Metronome El primer ministro sali\u00f3 ayer, sin que se haya confirmado la hora, desde el Aeropuerto de Teterboro en New Jersey. List\u00edn Diario contact\u00f3 al Aeropuerto de Teterboro para confirmar d\u00f3nde se encontraba el primer ministro haitiano, pero no pudo recibir informaci\u00f3n certera ante la solicitud. \u201cDesafortunadamente, no podemos compartir ninguna informaci\u00f3n\u201d, indic\u00f3 la autoridad portuaria de Nueva York-New Jersey a la petici\u00f3n de este medio. No lo dejaron aterrizar Antes de llegar a Puerto Rico, la aeronave habr\u00eda solicitado aterrizar en Aeropuerto Internacional Toussaint Louverture, ubicado en Puerto Pr\u00edncipe, petici\u00f3n que le fue negada, seg\u00fan establece El Nuevo D\u00eda en una nota donde confirmaban el arribo de Henry a su territorio. Adem\u00e1s de esta negativa, una fuente inform\u00f3 a List\u00edn Diario que al encontrarse en el espacio a\u00e9reo de Rep\u00fablica Dominicana, la aeronave tambi\u00e9n solicit\u00f3 aterrizar en el pa\u00eds, petici\u00f3n que no le fue otorgada. Henry sali\u00f3 de Hait\u00ed a finales del mes de febrero para participar en la 46\u00b0 Reuni\u00f3n Ordinaria de la Comunidad del Caribe (Caricom), que se celebr\u00f3 del 25 al 28 de febrero de en Georgetown, Guyana. En esta reuni\u00f3n se inform\u00f3 que el primer ministro hab\u00eda aceptado la celebraci\u00f3n de elecciones generales en agosto de 2025. En Hait\u00ed no se celebran elecciones desde el 2015. En un comunicado Caricom indic\u00f3, adem\u00e1s, que Estados Unidos, Canad\u00e1 y Naciones Unidas crear\u00edan un equipo de evaluaci\u00f3n para ayudar a Hait\u00ed a preparar las elecciones. Luego de ah\u00ed, Henry viaj\u00f3 a Kenia, donde el 29 de febrero firm\u00f3 junto, al mandatario de ese pa\u00eds, William Ruto, el acuerdo para el env\u00edo de 1, 000 polic\u00edas kenianos a Hait\u00ed. \u201cMe complace informar que el primer ministro interino de Hait\u00ed, Ariel Henry, y yo hemos sido testigos de la firma de este instrumento. Tambi\u00e9n hemos discutido los pr\u00f3ximos pasos para permitir la v\u00eda r\u00e1pida del despliegue\u201d, expres\u00f3 Ruto al tiempo de decir que \u201cest\u00e1 comprometido a contribuir al \u00e9xito de la misi\u00f3n multinacional porque es un deber hist\u00f3rico para la paz en Hait\u00ed\u201d. Luego de su participaci\u00f3n en este acuerdo, se desconoc\u00eda el paradero del primer ministro, aunque se rumoraba que habr\u00eda salido de Kenia el s\u00e1bado 2 de marzo y se encontraba en Estados Unidos. Toque de queda Por el primer ministro est\u00e1 de forma interina Patrick Michel Boivert, quien el pasado domingo orden\u00f3 un toque de queda desde las 6:00 de la tarde hasta las 5:00 de la ma\u00f1ana, desde el lunes 4 hasta el mi\u00e9rcoles 6 en Puerto Pr\u00edncipe, por la ola de violencia. Henry asumi\u00f3 el poder tras el asesinato del presidente Jovenel Mo\u00efse en 2021. El mandato de Henry expir\u00f3 el pasado 7 de febrero, seg\u00fan un acuerdo firmado por \u00e9l junto a la oposici\u00f3n de ese pa\u00eds en diciembre de 2022. Auge de violencia La crisis en Hait\u00ed se agudiz\u00f3 desde el pasado jueves, ante la ausencia del primer ministro, con el reporte de varios tiroteos en Puerto Pr\u00edncipe, capital de ese pa\u00eds, y controlada en 80% por las bandas haitianas. Estas bandas han ocasionado el desplazamiento de m\u00e1s de 15,000 personas, de acuerdo al portavoz de la ONU, St\u00e9phane Dujarric. El viernes, al igual que el lunes, se reportaron varios disparos en Puerto Pr\u00edncipe, en especial en el Aeropuerto Toussaint Louverture, cuando bandas haitianas y miembros de la polic\u00eda escenificaron un tiroteo. El s\u00e1bado la violencia se agudiz\u00f3 con la liberaci\u00f3n de m\u00e1s de 3,600 privados de libertad, luego de que las bandas irrumpieran en dos recintos carcelarios m\u00e1s grandes de ese pa\u00eds. Los reportes de los medios haitianos se\u00f1alan que decenas de privados de libertad fueron asesinados en las inmediaciones de las c\u00e1rceles.<\/p>\n","protected":false},"author":9,"featured_media":95251,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-95250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95250"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95250\/revisions"}],"predecessor-version":[{"id":95252,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95250\/revisions\/95252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95251"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}