{"id":95405,"date":"2024-03-16T07:13:05","date_gmt":"2024-03-16T11:13:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95405"},"modified":"2024-03-16T07:13:06","modified_gmt":"2024-03-16T11:13:06","slug":"que-es-la-paralisis-del-sueno-cuando-el-cerebro-despierta-antes-que-el-cuerpo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/que-es-la-paralisis-del-sueno-cuando-el-cerebro-despierta-antes-que-el-cuerpo\/","title":{"rendered":"\u00bfQu\u00e9 es la par\u00e1lisis del sue\u00f1o? Cuando el cerebro despierta antes que el cuerpo"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65f43da6c18ae.png\" alt=\"\" class=\"wp-image-95406\" width=\"262\" height=\"144\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65f43da6c18ae.png 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65f43da6c18ae-768x426.png 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/65f43da6c18ae-600x333.png 600w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La<strong>&nbsp;par\u00e1lisis del sue\u00f1o<\/strong>&nbsp;es un fen\u00f3meno por el que se produce un despertar incompleto de la persona. Aparece en las transiciones entre el&nbsp;<strong>estado de sue\u00f1o<\/strong>&nbsp;y&nbsp;<strong>vigilia<\/strong>, normalmente en el momento de comenzar a dormir o en el de despertarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este trastorno del sue\u00f1o, que se sit\u00faa dentro del grupo de las&nbsp;<strong>parasomnias<\/strong>, seg\u00fan la Clasificaci\u00f3n Internacional de Trastornos del Sue\u00f1o, afecta a 1 de cada 1.000 habitantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una entrevista concedida a EFEsalud, el doctor Diego Garc\u00eda-Borreguero, director del Instituto de Investigaciones del Sue\u00f1o (IIS), y expresidente de la Sociedad Espa\u00f1ola del Sue\u00f1o (SES), explica las caracter\u00edsticas de la par\u00e1lisis del sue\u00f1o; un fen\u00f3meno del que destaca \u00abtal vez sea m\u00e1s frecuente de lo que pensamos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la<strong>&nbsp;fase del sue\u00f1o REM<\/strong>&nbsp;(rapid eye movements) existe una gran&nbsp;<strong>activaci\u00f3n de la corteza cerebral<\/strong>, se producen los sue\u00f1os y se da una&nbsp;<strong>aton\u00eda muscular generalizada<\/strong>. En ocasiones, estas caracter\u00edsticas fisiol\u00f3gicas del sue\u00f1o REM, \u00abse introducen de alguna manera en la fase NO REM, es decir, entre el sue\u00f1o m\u00e1s profundo y la vigilia\u00bb, explica el doctor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La persona que se encuentra bajo esta<strong>&nbsp;par\u00e1lisis<\/strong>, est\u00e1 cognitivamente despierta pero experimenta una sensaci\u00f3n de paralizaci\u00f3n de, pr\u00e1cticamente, toda la<strong>&nbsp;musculatura voluntaria<\/strong>&nbsp;excepto los ojos y el diafragma respiratorio. Tambi\u00e9n es caracter\u00edstica la&nbsp;<strong>paralizaci\u00f3n de la laringe<\/strong>, lo cual imposibilita el habla de la persona mientras se produce este trastorno del sue\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La duraci\u00f3n de estos episodios suele ser variable. Generalmente son de una duraci\u00f3n corta, de entre veinte segundos hasta dos minutos. Pasado ese tiempo, la&nbsp;<strong>par\u00e1lisis&nbsp;<\/strong>remite espont\u00e1neamente y sin consecuencias. Hablar de un per\u00edodo de duraci\u00f3n m\u00e1s largo es inhabitual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCualquiera de nosotros, en una situaci\u00f3n de\u00a0<strong>privaci\u00f3n del sue\u00f1o cr\u00f3nica<\/strong>\u00a0o continuada, puede en alg\u00fan momento acabar desarrollando par\u00e1lisis del sue\u00f1o\u00bb, asegura Garc\u00eda-Borreguero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las circunstancias bajo las que se produce este&nbsp;<strong>fen\u00f3meno<\/strong>, el doctor Garc\u00eda-Borreguero sostiene que puede ocurrir como un&nbsp;<strong>s\u00edntoma aislado&nbsp;<\/strong>o en el contexto y\/o acompa\u00f1ado de otros s\u00edntomas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los s\u00edntomas que frecuentemente acompa\u00f1a a la par\u00e1lisis del sue\u00f1o son las alucinaciones hipnag\u00f3gicas (alucionaciones auditivas, visuales y\/o t\u00e1ctiles). Las m\u00e1s comunes son las de tipo sensitivo (cenest\u00e9sicas) y visuales, mientras que las auditivas son las m\u00e1s infrecuentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, el doctor matiza que \u00abse las llama&nbsp;<strong>alucinaciones&nbsp;<\/strong>pero en realidad son&nbsp;<strong>pseudoalucinaciones<\/strong>\u00ab, pues la persona que las padece sabe de manera fehaciente que lo que siente, ve o escucha no es real.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, aunque este tipo de pseudoalucinaciones puedan estar detr\u00e1s de supuestas experiencias paranormales, quien sufre par\u00e1lisis del sue\u00f1o \u00abraramente les da credibilidad\u00bb y lo m\u00e1s probable es que detr\u00e1s de estos sucesos \u00abhaya cuadros psiqui\u00e1tricos o esquizofr\u00e9nicos\u00bb, argumenta el doctor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa&nbsp;<strong>par\u00e1lisis del sue\u00f1o<\/strong>&nbsp;sirve m\u00e1s como un indicador de otras&nbsp;<strong>enfermedades&nbsp;<\/strong>que como un s\u00edntoma que se haya de tratar en s\u00ed mismo\u00bb, precisa el doctor Garc\u00eda-Borreguero.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPOR QU\u00c9 SE PRODUCE LA PAR\u00c1LISIS DEL SUE\u00d1O?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En orden de frecuencia (de mayor a menor probabilidad), las causas por las que un individuo puede llegar a desarrollar&nbsp;<strong>par\u00e1lisis del sue\u00f1o<\/strong>&nbsp;son:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asociado a otra patolog\u00eda<\/strong>: La par\u00e1lisis del sue\u00f1o puede ser s\u00edntoma de otra enfermedad. La m\u00e1s frecuente es la narcolepsia, una enfermedad por la que se tienen dificultades para mantenerse despierto durante el d\u00eda. Estos pacientes presentan de manera muy frecuente ataques de cataplejia (paralizaci\u00f3n muscular), par\u00e1lisis del sue\u00f1o y alucinaciones hipnag\u00f3gicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Causa aislada relacionada a&nbsp;<strong>privaci\u00f3n del sue\u00f1o severa<\/strong>: En segundo lugar, la par\u00e1lisis del sue\u00f1o afecta a sujetos sanos que se encuentran sometidos a privaci\u00f3n del sue\u00f1o severa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Causa de tipo familiar<\/strong>: La causa de tipo hereditario es la menos frecuente. Se produce cuando hay varios miembros de la familia que padecen par\u00e1lisis del sue\u00f1o como s\u00edntoma \u00fanico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para proceder a su diagn\u00f3stico, en primer lugar habr\u00e1 que descartar que el paciente sufra&nbsp;<strong>narcolepsia<\/strong>. Seguidamente, se har\u00e1 una investigaci\u00f3n sobre cu\u00e1nto duerme o cu\u00e1nto necesita dormir el paciente y, en su caso, determinar si hay d\u00e9ficit de sue\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si estas dos circunstancias no se producen habr\u00e1 que pensar si hay m\u00e1s casos en la familia y se presenta, por tanto, como s\u00edntoma \u00fanico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por tanto, si la par\u00e1lisis del sue\u00f1o aparece como s\u00edntoma aislado no tiene mayor importancia y no suele ser necesario tratarlo. En caso de que persista durante m\u00e1s de tres o cuatro semanas seguidas o de que produzca una p\u00e9rdida de calidad de vida y no permita conciliar bien el sue\u00f1o, habr\u00e1 que acudir al especialista ya que puede realizarse un tratamiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LA CLAVE EST\u00c1 EN EL DESCANSO<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>estr\u00e9s&nbsp;<\/strong>o el<strong>&nbsp;jet lag<\/strong>&nbsp;son situaciones que com\u00fanmente desencadenan los episodios de par\u00e1lisis del sue\u00f1o. Esto es as\u00ed, en la medida en que al dormir menos, se entra en privaci\u00f3n del sue\u00f1o y puede producirse este trastorno como s\u00edntoma del sue\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mantener&nbsp;<strong>horarios de sue\u00f1o estables<\/strong>, dormir por lo menos siete horas y media cada d\u00eda, evitar trabajos por turnos, trasnochar o evitar la toma de f\u00e1rmacos que influyan sobre el sue\u00f1o REM (como antidepresivos), ayudar\u00e1 a que estemos menos predispuestos a padecer par\u00e1lisis del sue\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre los&nbsp;<strong>antidepresivos<\/strong>, se\u00f1ala el doctor que \u00abson un arma de doble filo\u00bb. Estos pueden ser f\u00e1rmacos para tratar la par\u00e1lisis del sue\u00f1o pero a la vez, la utilizaci\u00f3n de antidepresivos pueden dar lugar a par\u00e1lisis del sue\u00f1o una vez se interrumpe el tratamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abExiste una lista de medicamentos que pueden tener relevancia en este sentido, por ello, deber\u00edamos consultar al m\u00e9dico si la medicaci\u00f3n que estamos tomando interfiere en este trastorno\u00bb, advierte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfEXISTEN RIESGOS PARA LA SALUD?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No, \u00abla par\u00e1lisis del sue\u00f1o no entra\u00f1a ning\u00fan riesgo para la salud\u00bb, asevera Garc\u00eda-Borreguero. La duraci\u00f3n de estos episodios es breve y no implica la paralizaci\u00f3n de ning\u00fan tejido muscular necesario para las funciones vitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, la primera vez que ocurre \u00abla persona suele asustarse y pensar que la ha dado un ictus o un accidente isqu\u00e9mico transitorio\u00bb, reconoce. En caso de que la par\u00e1lisis vaya acompa\u00f1ada de alucinaciones hipnag\u00f3gicas, el paciente \u00abpodr\u00e1 pensar que se est\u00e1 volviendo loco\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, es una situaci\u00f3n que se vive con cierta angustia y en la que el paciente debe mantener el control, ya que no corre ning\u00fan peligro y pasados unos segundos o minutos, la par\u00e1lisis ceder\u00e1 sin consecuencias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;par\u00e1lisis del sue\u00f1o&nbsp;es un fen\u00f3meno por el que se produce un despertar incompleto de la persona. Aparece en las transiciones entre el&nbsp;estado de sue\u00f1o&nbsp;y&nbsp;vigilia, normalmente en el momento de comenzar a dormir o en el de despertarse. Este trastorno del sue\u00f1o, que se sit\u00faa dentro del grupo de las&nbsp;parasomnias, seg\u00fan la Clasificaci\u00f3n Internacional de Trastornos del Sue\u00f1o, afecta a 1 de cada 1.000 habitantes. En una entrevista concedida a EFEsalud, el doctor Diego Garc\u00eda-Borreguero, director del Instituto de Investigaciones del Sue\u00f1o (IIS), y expresidente de la Sociedad Espa\u00f1ola del Sue\u00f1o (SES), explica las caracter\u00edsticas de la par\u00e1lisis del sue\u00f1o; un fen\u00f3meno del que destaca \u00abtal vez sea m\u00e1s frecuente de lo que pensamos\u00bb. Durante la&nbsp;fase del sue\u00f1o REM&nbsp;(rapid eye movements) existe una gran&nbsp;activaci\u00f3n de la corteza cerebral, se producen los sue\u00f1os y se da una&nbsp;aton\u00eda muscular generalizada. En ocasiones, estas caracter\u00edsticas fisiol\u00f3gicas del sue\u00f1o REM, \u00abse introducen de alguna manera en la fase NO REM, es decir, entre el sue\u00f1o m\u00e1s profundo y la vigilia\u00bb, explica el doctor. La persona que se encuentra bajo esta&nbsp;par\u00e1lisis, est\u00e1 cognitivamente despierta pero experimenta una sensaci\u00f3n de paralizaci\u00f3n de, pr\u00e1cticamente, toda la&nbsp;musculatura voluntaria&nbsp;excepto los ojos y el diafragma respiratorio. Tambi\u00e9n es caracter\u00edstica la&nbsp;paralizaci\u00f3n de la laringe, lo cual imposibilita el habla de la persona mientras se produce este trastorno del sue\u00f1o. La duraci\u00f3n de estos episodios suele ser variable. Generalmente son de una duraci\u00f3n corta, de entre veinte segundos hasta dos minutos. Pasado ese tiempo, la&nbsp;par\u00e1lisis&nbsp;remite espont\u00e1neamente y sin consecuencias. Hablar de un per\u00edodo de duraci\u00f3n m\u00e1s largo es inhabitual. \u00abCualquiera de nosotros, en una situaci\u00f3n de\u00a0privaci\u00f3n del sue\u00f1o cr\u00f3nica\u00a0o continuada, puede en alg\u00fan momento acabar desarrollando par\u00e1lisis del sue\u00f1o\u00bb, asegura Garc\u00eda-Borreguero. Entre las circunstancias bajo las que se produce este&nbsp;fen\u00f3meno, el doctor Garc\u00eda-Borreguero sostiene que puede ocurrir como un&nbsp;s\u00edntoma aislado&nbsp;o en el contexto y\/o acompa\u00f1ado de otros s\u00edntomas. Uno de los s\u00edntomas que frecuentemente acompa\u00f1a a la par\u00e1lisis del sue\u00f1o son las alucinaciones hipnag\u00f3gicas (alucionaciones auditivas, visuales y\/o t\u00e1ctiles). Las m\u00e1s comunes son las de tipo sensitivo (cenest\u00e9sicas) y visuales, mientras que las auditivas son las m\u00e1s infrecuentes. No obstante, el doctor matiza que \u00abse las llama&nbsp;alucinaciones&nbsp;pero en realidad son&nbsp;pseudoalucinaciones\u00ab, pues la persona que las padece sabe de manera fehaciente que lo que siente, ve o escucha no es real. Por ello, aunque este tipo de pseudoalucinaciones puedan estar detr\u00e1s de supuestas experiencias paranormales, quien sufre par\u00e1lisis del sue\u00f1o \u00abraramente les da credibilidad\u00bb y lo m\u00e1s probable es que detr\u00e1s de estos sucesos \u00abhaya cuadros psiqui\u00e1tricos o esquizofr\u00e9nicos\u00bb, argumenta el doctor. \u00abLa&nbsp;par\u00e1lisis del sue\u00f1o&nbsp;sirve m\u00e1s como un indicador de otras&nbsp;enfermedades&nbsp;que como un s\u00edntoma que se haya de tratar en s\u00ed mismo\u00bb, precisa el doctor Garc\u00eda-Borreguero. \u00bfPOR QU\u00c9 SE PRODUCE LA PAR\u00c1LISIS DEL SUE\u00d1O? En orden de frecuencia (de mayor a menor probabilidad), las causas por las que un individuo puede llegar a desarrollar&nbsp;par\u00e1lisis del sue\u00f1o&nbsp;son: Asociado a otra patolog\u00eda: La par\u00e1lisis del sue\u00f1o puede ser s\u00edntoma de otra enfermedad. La m\u00e1s frecuente es la narcolepsia, una enfermedad por la que se tienen dificultades para mantenerse despierto durante el d\u00eda. Estos pacientes presentan de manera muy frecuente ataques de cataplejia (paralizaci\u00f3n muscular), par\u00e1lisis del sue\u00f1o y alucinaciones hipnag\u00f3gicas. Causa aislada relacionada a&nbsp;privaci\u00f3n del sue\u00f1o severa: En segundo lugar, la par\u00e1lisis del sue\u00f1o afecta a sujetos sanos que se encuentran sometidos a privaci\u00f3n del sue\u00f1o severa. Causa de tipo familiar: La causa de tipo hereditario es la menos frecuente. Se produce cuando hay varios miembros de la familia que padecen par\u00e1lisis del sue\u00f1o como s\u00edntoma \u00fanico. Para proceder a su diagn\u00f3stico, en primer lugar habr\u00e1 que descartar que el paciente sufra&nbsp;narcolepsia. Seguidamente, se har\u00e1 una investigaci\u00f3n sobre cu\u00e1nto duerme o cu\u00e1nto necesita dormir el paciente y, en su caso, determinar si hay d\u00e9ficit de sue\u00f1o. Si estas dos circunstancias no se producen habr\u00e1 que pensar si hay m\u00e1s casos en la familia y se presenta, por tanto, como s\u00edntoma \u00fanico. Por tanto, si la par\u00e1lisis del sue\u00f1o aparece como s\u00edntoma aislado no tiene mayor importancia y no suele ser necesario tratarlo. En caso de que persista durante m\u00e1s de tres o cuatro semanas seguidas o de que produzca una p\u00e9rdida de calidad de vida y no permita conciliar bien el sue\u00f1o, habr\u00e1 que acudir al especialista ya que puede realizarse un tratamiento. LA CLAVE EST\u00c1 EN EL DESCANSO El&nbsp;estr\u00e9s&nbsp;o el&nbsp;jet lag&nbsp;son situaciones que com\u00fanmente desencadenan los episodios de par\u00e1lisis del sue\u00f1o. Esto es as\u00ed, en la medida en que al dormir menos, se entra en privaci\u00f3n del sue\u00f1o y puede producirse este trastorno como s\u00edntoma del sue\u00f1o. Mantener&nbsp;horarios de sue\u00f1o estables, dormir por lo menos siete horas y media cada d\u00eda, evitar trabajos por turnos, trasnochar o evitar la toma de f\u00e1rmacos que influyan sobre el sue\u00f1o REM (como antidepresivos), ayudar\u00e1 a que estemos menos predispuestos a padecer par\u00e1lisis del sue\u00f1o. Sobre los&nbsp;antidepresivos, se\u00f1ala el doctor que \u00abson un arma de doble filo\u00bb. Estos pueden ser f\u00e1rmacos para tratar la par\u00e1lisis del sue\u00f1o pero a la vez, la utilizaci\u00f3n de antidepresivos pueden dar lugar a par\u00e1lisis del sue\u00f1o una vez se interrumpe el tratamiento. \u00abExiste una lista de medicamentos que pueden tener relevancia en este sentido, por ello, deber\u00edamos consultar al m\u00e9dico si la medicaci\u00f3n que estamos tomando interfiere en este trastorno\u00bb, advierte. \u00bfEXISTEN RIESGOS PARA LA SALUD? No, \u00abla par\u00e1lisis del sue\u00f1o no entra\u00f1a ning\u00fan riesgo para la salud\u00bb, asevera Garc\u00eda-Borreguero. La duraci\u00f3n de estos episodios es breve y no implica la paralizaci\u00f3n de ning\u00fan tejido muscular necesario para las funciones vitales. No obstante, la primera vez que ocurre \u00abla persona suele asustarse y pensar que la ha dado un ictus o un accidente isqu\u00e9mico transitorio\u00bb, reconoce. En caso de que la par\u00e1lisis vaya acompa\u00f1ada de alucinaciones hipnag\u00f3gicas, el paciente \u00abpodr\u00e1 pensar que se est\u00e1 volviendo loco\u00bb. En definitiva, es una situaci\u00f3n que se vive con cierta angustia y en la que el paciente debe mantener el control, ya que no corre ning\u00fan peligro y pasados unos segundos o minutos, la par\u00e1lisis ceder\u00e1 sin consecuencias.<\/p>\n","protected":false},"author":9,"featured_media":95406,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-95405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95405"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95405\/revisions"}],"predecessor-version":[{"id":95407,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95405\/revisions\/95407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95406"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}