{"id":95484,"date":"2024-03-22T08:01:16","date_gmt":"2024-03-22T12:01:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95484"},"modified":"2024-03-22T08:01:18","modified_gmt":"2024-03-22T12:01:18","slug":"la-rd-seguira-deportando-a-los-ilegales-pese-a-pedido-de-acnur","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-rd-seguira-deportando-a-los-ilegales-pese-a-pedido-de-acnur\/","title":{"rendered":"La RD seguir\u00e1 deportando a los ilegales; pese a pedido de ACNUR"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Canciller-Roberto-Alvarez-1024x576.jpeg\" alt=\"\" class=\"wp-image-95485\" width=\"235\" height=\"132\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Canciller-Roberto-Alvarez-1024x576.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Canciller-Roberto-Alvarez-300x169.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Canciller-Roberto-Alvarez-768x432.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Canciller-Roberto-Alvarez-600x337.jpeg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/Canciller-Roberto-Alvarez.jpeg 1300w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Rep\u00fablica Dominicana mantendr\u00e1 su pol\u00edtica de deportar a toda persona que est\u00e9 de forma ilegal en su territorio, dijo este jueves el Ministerio de Relaciones Exteriores en una declaraci\u00f3n escrita, al ser consultado por CNN sobre la recomendaci\u00f3n que hizo la Agencia de la ONU para los Refugiados (ACNUR) para acoger refugiados haitianos en medio de la crisis que vive ese pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo ha dicho el canciller Roberto \u00c1lvarez en recientes declaraciones p\u00fablicas, no ha habido ning\u00fan cambio en la pol\u00edtica dominicana en cuanto a las deportaciones. Como pa\u00eds tenemos una pol\u00edtica establecida que por motivos del inter\u00e9s nacional estamos devolviendo a Hait\u00ed todas aquellas personas que est\u00e1n ilegal en territorio dominicano, de acuerdo a nuestra legislaci\u00f3n\u201d, asegur\u00f3 la Canciller\u00eda dominicana en su declaraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EL PEDIDO DE ACNUR<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ACNUR public\u00f3 este mi\u00e9rcoles una nueva gu\u00eda para que se brinde protecci\u00f3n internacional a quien llegue de Hait\u00ed, pa\u00eds vecino a Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El coordinador de la Mesa Nacional para las Migraciones y Refugiados de Rep\u00fablica Dominicana, William Charpentier, consider\u00f3 este jueves que el Gobierno se apresur\u00f3 al dar una respuesta a la convocatoria de ACNUR. Charpentier indic\u00f3 que el pa\u00eds es signatario de los acuerdos mencionados en el comunicado de la agencia de la ONU, por lo tanto debe reconocer los casos de quienes soliciten ser acogidos bajo el estatus de refugiados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Direcci\u00f3n de Migraci\u00f3n de Rep\u00fablica Dominicana inform\u00f3 a CNN que en lo que va del a\u00f1o han deportado cerca de 24.000 haitianos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mediados de 2023, ACNUR document\u00f3 312.000 refugiados haitianos y solicitantes de asilo en todo el mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Rep\u00fablica Dominicana mantendr\u00e1 su pol\u00edtica de deportar a toda persona que est\u00e9 de forma ilegal en su territorio, dijo este jueves el Ministerio de Relaciones Exteriores en una declaraci\u00f3n escrita, al ser consultado por CNN sobre la recomendaci\u00f3n que hizo la Agencia de la ONU para los Refugiados (ACNUR) para acoger refugiados haitianos en medio de la crisis que vive ese pa\u00eds. \u201cComo ha dicho el canciller Roberto \u00c1lvarez en recientes declaraciones p\u00fablicas, no ha habido ning\u00fan cambio en la pol\u00edtica dominicana en cuanto a las deportaciones. Como pa\u00eds tenemos una pol\u00edtica establecida que por motivos del inter\u00e9s nacional estamos devolviendo a Hait\u00ed todas aquellas personas que est\u00e1n ilegal en territorio dominicano, de acuerdo a nuestra legislaci\u00f3n\u201d, asegur\u00f3 la Canciller\u00eda dominicana en su declaraci\u00f3n. EL PEDIDO DE ACNUR ACNUR public\u00f3 este mi\u00e9rcoles una nueva gu\u00eda para que se brinde protecci\u00f3n internacional a quien llegue de Hait\u00ed, pa\u00eds vecino a Rep\u00fablica Dominicana. El coordinador de la Mesa Nacional para las Migraciones y Refugiados de Rep\u00fablica Dominicana, William Charpentier, consider\u00f3 este jueves que el Gobierno se apresur\u00f3 al dar una respuesta a la convocatoria de ACNUR. Charpentier indic\u00f3 que el pa\u00eds es signatario de los acuerdos mencionados en el comunicado de la agencia de la ONU, por lo tanto debe reconocer los casos de quienes soliciten ser acogidos bajo el estatus de refugiados. La Direcci\u00f3n de Migraci\u00f3n de Rep\u00fablica Dominicana inform\u00f3 a CNN que en lo que va del a\u00f1o han deportado cerca de 24.000 haitianos. A mediados de 2023, ACNUR document\u00f3 312.000 refugiados haitianos y solicitantes de asilo en todo el mundo.<\/p>\n","protected":false},"author":9,"featured_media":95485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-95484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95484"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95484\/revisions"}],"predecessor-version":[{"id":95486,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95484\/revisions\/95486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95485"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}