{"id":95493,"date":"2024-03-23T06:57:14","date_gmt":"2024-03-23T10:57:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95493"},"modified":"2024-03-23T06:57:15","modified_gmt":"2024-03-23T10:57:15","slug":"leones-renuevan-su-acuerdo-con-el-grande-ligas-jose-ramirez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/leones-renuevan-su-acuerdo-con-el-grande-ligas-jose-ramirez\/","title":{"rendered":"Leones renuevan su acuerdo con el Grande Ligas Jos\u00e9 Ram\u00edrez"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"181\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/03\/ramirez-300x181-1.jpg\" alt=\"\" class=\"wp-image-95494\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 23 mar.- Los Leones del Escogido anunciaron que han renovado su acuerdo con el tercera base Jos\u00e9 Ram\u00edrez, quien juega para los Guardianes de Cleveland en las Grandes Ligas, garantizando su continuidad con el equipo en la Liga de B\u00e9isbol Profesional Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La firma de Ram\u00edrez encabez\u00f3 los movimientos realizados por los Leones hoy, que tambi\u00e9n contrataron al jardinero Johan Mieses, el lanzador derecho Eduardo Rivera y el jugador del cuadro interior Abiatal Avelino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ram\u00edrez, considerado la principal figura de los Guardianes, lleg\u00f3 a los Leones antes del inicio de la pasada temporada dominicana, en un cambio desde los Toros del Este por el toletero de los Azulejos de Toronto Vladimir Guerrero Jr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El poderoso bateador de ambas manos se uniform\u00f3 con los melenudos, accionando en nueve partidos en los que flet\u00f3 un cuadrangular, anot\u00f3 nueve carreras y remolc\u00f3 cinco vueltas, aportando al avance de los Leones a la postemporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de Avelino, de 29 a\u00f1os, contratado desde la agencia libre, est\u00e1 supuesto a aportar al conjunto capitalino versatilidad y profundidad en su cuadro interior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo jugador de los rojos ha accionado en ocho campeonatos locales, vistiendo la franela de las Estrellas Orientales y de los Gigantes del Cibao, logrando cifrar su promedio de bateo en .250, con tres jonrones, 37 vueltas remolcadas y 73 anotadas, mostrando, adem\u00e1s, su velocidad en las bases, al sumar 32 robos en 163 juegos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mieses, de 28 a\u00f1os, y quien durante este verano jugar\u00e1 con los Hanshin Tigers de la Liga Japonesa de B\u00e9isbol Profesional, apenas ha visto acci\u00f3n en siete juegos en su carrera en la pelota dominicana,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la llegada de Mieses, quien ha conectado un m\u00e1ximo de 28 jonrones en una temporada del pa\u00eds asi\u00e1tico, los Leones consiguen poder ofensivo en su alineaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de Rivera, los escarlatas apuestan a que pueda trasladar a liga dominicana el \u00e9xito que logr\u00f3 con los Gigantes de Carolina en la Liga de B\u00e9isbol Profesional de Puerto Rico, para quienes lanz\u00f3 en 2023-24, logrando un porcentaje de carreras limpias permitidas de 1.85, con 48 ponches en 43.2 entradas, finalizando con un r\u00e9cord fue de 3-3 en 10 presentaciones, nueve de ellas como abridor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 23 mar.- Los Leones del Escogido anunciaron que han renovado su acuerdo con el tercera base Jos\u00e9 Ram\u00edrez, quien juega para los Guardianes de Cleveland en las Grandes Ligas, garantizando su continuidad con el equipo en la Liga de B\u00e9isbol Profesional Dominicana. La firma de Ram\u00edrez encabez\u00f3 los movimientos realizados por los Leones hoy, que tambi\u00e9n contrataron al jardinero Johan Mieses, el lanzador derecho Eduardo Rivera y el jugador del cuadro interior Abiatal Avelino. Ram\u00edrez, considerado la principal figura de los Guardianes, lleg\u00f3 a los Leones antes del inicio de la pasada temporada dominicana, en un cambio desde los Toros del Este por el toletero de los Azulejos de Toronto Vladimir Guerrero Jr. El poderoso bateador de ambas manos se uniform\u00f3 con los melenudos, accionando en nueve partidos en los que flet\u00f3 un cuadrangular, anot\u00f3 nueve carreras y remolc\u00f3 cinco vueltas, aportando al avance de los Leones a la postemporada. En el caso de Avelino, de 29 a\u00f1os, contratado desde la agencia libre, est\u00e1 supuesto a aportar al conjunto capitalino versatilidad y profundidad en su cuadro interior. El nuevo jugador de los rojos ha accionado en ocho campeonatos locales, vistiendo la franela de las Estrellas Orientales y de los Gigantes del Cibao, logrando cifrar su promedio de bateo en .250, con tres jonrones, 37 vueltas remolcadas y 73 anotadas, mostrando, adem\u00e1s, su velocidad en las bases, al sumar 32 robos en 163 juegos. Mieses, de 28 a\u00f1os, y quien durante este verano jugar\u00e1 con los Hanshin Tigers de la Liga Japonesa de B\u00e9isbol Profesional, apenas ha visto acci\u00f3n en siete juegos en su carrera en la pelota dominicana, Con la llegada de Mieses, quien ha conectado un m\u00e1ximo de 28 jonrones en una temporada del pa\u00eds asi\u00e1tico, los Leones consiguen poder ofensivo en su alineaci\u00f3n. En el caso de Rivera, los escarlatas apuestan a que pueda trasladar a liga dominicana el \u00e9xito que logr\u00f3 con los Gigantes de Carolina en la Liga de B\u00e9isbol Profesional de Puerto Rico, para quienes lanz\u00f3 en 2023-24, logrando un porcentaje de carreras limpias permitidas de 1.85, con 48 ponches en 43.2 entradas, finalizando con un r\u00e9cord fue de 3-3 en 10 presentaciones, nueve de ellas como abridor.<\/p>\n","protected":false},"author":9,"featured_media":95494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-95493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95493"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95493\/revisions"}],"predecessor-version":[{"id":95495,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95493\/revisions\/95495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95494"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}