{"id":95681,"date":"2024-04-02T12:11:51","date_gmt":"2024-04-02T16:11:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95681"},"modified":"2024-04-02T12:19:08","modified_gmt":"2024-04-02T16:19:08","slug":"exposicion-pictorica-la-semana-de-concienciacion-sobre-el-autismo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/exposicion-pictorica-la-semana-de-concienciacion-sobre-el-autismo\/","title":{"rendered":"Exposici\u00f3n pict\u00f3rica la semana de concienciaci\u00f3n sobre el autismo"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/IMG_4532-300x200-1.png\" alt=\"\" class=\"wp-image-95682\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 2 abr (EFE).- La exposici\u00f3n pict\u00f3rica \u2018Multiverso de colores\u2019 da apertura este martes a la semana de concienciaci\u00f3n sobre el autismo que auspician el Centro de Atenci\u00f3n para la Discapacidad (Caid) y la Fundaci\u00f3n Manos Unidas por el Autismo en una plaza comercial de la capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fundaci\u00f3n precis\u00f3 en un comunicado que la exposici\u00f3n es del adolescente Fernando Gabriel Quiroz, que se ha inclinado por el arte desde los tres a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSu obra nos transporta al mar con sus especies, olas y barcas, al cielo en diferentes trajes, al amanecer, la tarde y la lluvia. Su habilidad t\u00e9cnica, que abarca desde el manejo del dibujo hasta la destreza motora fina, destaca su capacidad para convertir el lienzo en una ventana a su mundo interno\u00bb, asegur\u00f3 el comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n cuenta con la curadur\u00eda y museograf\u00eda de los cubanos Mar\u00eda Fals Fors y Marcos Gonz\u00e1lez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras actividades incluyen la charla Entendiendo del TEA y su manejo integral, a impartirse el jueves de 6.00 a 8.00 de la noche a cargo del Caid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras, el domingo venidero el programa incluye las experiencias y testimonios de las presidentas de las fundaciones Manos Unidas por el Autismo, Odile Villavizar, e Integral Autismo e Inclusi\u00f3n Social de San Crist\u00f3bal, Alda Puello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clausura ser\u00e1 a las 5.45 de la tarde de ese d\u00eda con la participaci\u00f3n art\u00edstica de la \u2018T\u00eda Nancy\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TRASTORNO DEL ESPECTRO AUTISTA&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), el autismo, o trastorno del espectro autista, constituye un grupo de afecciones diversas relacionadas con el desarrollo del cerebro, que afecta la interacci\u00f3n social y la comunicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las caracter\u00edsticas pueden detectarse en la primera infancia, pero, a menudo, el autismo no se diagnostica hasta mucho m\u00e1s tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aproximadamente uno de cada 100 ni\u00f1os tiene autismo, seg\u00fan las cifras de la OMS, asegur\u00f3 la informaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las capacidades y las necesidades de las personas con autismo var\u00edan y pueden evolucionar con el tiempo. Aunque algunas personas con autismo pueden vivir de manera independiente, hay otras con discapacidades graves que necesitan constante atenci\u00f3n y apoyo durante toda su vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 2 abr (EFE).- La exposici\u00f3n pict\u00f3rica \u2018Multiverso de colores\u2019 da apertura este martes a la semana de concienciaci\u00f3n sobre el autismo que auspician el Centro de Atenci\u00f3n para la Discapacidad (Caid) y la Fundaci\u00f3n Manos Unidas por el Autismo en una plaza comercial de la capital. La fundaci\u00f3n precis\u00f3 en un comunicado que la exposici\u00f3n es del adolescente Fernando Gabriel Quiroz, que se ha inclinado por el arte desde los tres a\u00f1os. \u00abSu obra nos transporta al mar con sus especies, olas y barcas, al cielo en diferentes trajes, al amanecer, la tarde y la lluvia. Su habilidad t\u00e9cnica, que abarca desde el manejo del dibujo hasta la destreza motora fina, destaca su capacidad para convertir el lienzo en una ventana a su mundo interno\u00bb, asegur\u00f3 el comunicado. La exposici\u00f3n cuenta con la curadur\u00eda y museograf\u00eda de los cubanos Mar\u00eda Fals Fors y Marcos Gonz\u00e1lez. Otras actividades incluyen la charla Entendiendo del TEA y su manejo integral, a impartirse el jueves de 6.00 a 8.00 de la noche a cargo del Caid. Mientras, el domingo venidero el programa incluye las experiencias y testimonios de las presidentas de las fundaciones Manos Unidas por el Autismo, Odile Villavizar, e Integral Autismo e Inclusi\u00f3n Social de San Crist\u00f3bal, Alda Puello. La clausura ser\u00e1 a las 5.45 de la tarde de ese d\u00eda con la participaci\u00f3n art\u00edstica de la \u2018T\u00eda Nancy\u2019. TRASTORNO DEL ESPECTRO AUTISTA&nbsp; Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), el autismo, o trastorno del espectro autista, constituye un grupo de afecciones diversas relacionadas con el desarrollo del cerebro, que afecta la interacci\u00f3n social y la comunicaci\u00f3n. Las caracter\u00edsticas pueden detectarse en la primera infancia, pero, a menudo, el autismo no se diagnostica hasta mucho m\u00e1s tarde. Aproximadamente uno de cada 100 ni\u00f1os tiene autismo, seg\u00fan las cifras de la OMS, asegur\u00f3 la informaci\u00f3n Las capacidades y las necesidades de las personas con autismo var\u00edan y pueden evolucionar con el tiempo. Aunque algunas personas con autismo pueden vivir de manera independiente, hay otras con discapacidades graves que necesitan constante atenci\u00f3n y apoyo durante toda su vida.<\/p>\n","protected":false},"author":9,"featured_media":95682,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-95681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95681"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95681\/revisions"}],"predecessor-version":[{"id":95683,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95681\/revisions\/95683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95682"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}