{"id":95873,"date":"2024-04-15T07:18:38","date_gmt":"2024-04-15T11:18:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95873"},"modified":"2024-04-15T07:19:21","modified_gmt":"2024-04-15T11:19:21","slug":"minerd-dice-que-invierte-mas-de-rd93-mil-millones-en-docentes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/minerd-dice-que-invierte-mas-de-rd93-mil-millones-en-docentes\/","title":{"rendered":"Minerd dice que invierte mas de RD$93 mil millones en docentes"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Ministerio-de-Educaci\u00f3n-RD..jpg\" alt=\"\" class=\"wp-image-95874\" width=\"216\" height=\"125\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Ministerio-de-Educaci\u00f3n-RD..jpg 1000w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Ministerio-de-Educaci\u00f3n-RD.-300x173.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Ministerio-de-Educaci\u00f3n-RD.-768x444.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Ministerio-de-Educaci\u00f3n-RD.-600x347.jpg 600w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO.-<\/strong>&nbsp;En menos de cuatro a\u00f1os, el Ministerio dominicano de Educaci\u00f3n aument\u00f3 de RD$66,498 millones a RD$93,449 millones los recursos que dedica al pago de sueldos fijos del personal que imparte ense\u00f1anza en el sector p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este monto incluye la subida sostenida de los salarios, la inclusi\u00f3n de nuevo personal, el desembolso de los incentivos salariales que se derivan de la evaluaci\u00f3n del desempe\u00f1o y la igualaci\u00f3n de los sueldos de primaria al nivel de los docentes de secundaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La suma de los RD$93 mil millones no comprende, sin embargo, el gasto que el Minerd realiza en el rengl\u00f3n de pensiones y jubilaciones, que el a\u00f1o pasado fue de RD$28,271 millones, lo que represent\u00f3 un 11.19% del presupuesto ejecutado del a\u00f1o 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso significa que de los RD$252,700 millones presupuestados en 2023, m\u00e1s de RD$121,720 millones se gastaron en remuneraciones y contribuciones al personal docente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DI\u00c1LOGO PARA CONSENSUAR AUMENTO SALARIAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos est\u00e1n contenidos en un an\u00e1lisis que el Minerd present\u00f3 a la Asociaci\u00f3n Dominicana de Profesores (ADP), en el marco del di\u00e1logo que llevan a cabo para consensuar un incremento salarial a los docentes del sistema educativo preuniversitario este a\u00f1o 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto el porcentaje como la aplicaci\u00f3n del aumento salarial deben ser discutidos este mes, conforme lo indica el pacto suscrito por ambas entidades el 24 de julio de 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acuerdo tambi\u00e9n establece que el gremio magisterial debe garantizar el cumplimiento del calendario y el horario escolar en todos los centros educativos p\u00fablicos del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los recursos que el Ministerio de Educaci\u00f3n destin\u00f3 a gastos en personal el a\u00f1o pasado, el 83 % correspondi\u00f3 a los maestros. Ese porcentaje, en el a\u00f1o 2018, solo representaba 72% de la n\u00f3mina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-&nbsp;En menos de cuatro a\u00f1os, el Ministerio dominicano de Educaci\u00f3n aument\u00f3 de RD$66,498 millones a RD$93,449 millones los recursos que dedica al pago de sueldos fijos del personal que imparte ense\u00f1anza en el sector p\u00fablico. Este monto incluye la subida sostenida de los salarios, la inclusi\u00f3n de nuevo personal, el desembolso de los incentivos salariales que se derivan de la evaluaci\u00f3n del desempe\u00f1o y la igualaci\u00f3n de los sueldos de primaria al nivel de los docentes de secundaria. La suma de los RD$93 mil millones no comprende, sin embargo, el gasto que el Minerd realiza en el rengl\u00f3n de pensiones y jubilaciones, que el a\u00f1o pasado fue de RD$28,271 millones, lo que represent\u00f3 un 11.19% del presupuesto ejecutado del a\u00f1o 2023. Eso significa que de los RD$252,700 millones presupuestados en 2023, m\u00e1s de RD$121,720 millones se gastaron en remuneraciones y contribuciones al personal docente. DI\u00c1LOGO PARA CONSENSUAR AUMENTO SALARIAL Los datos est\u00e1n contenidos en un an\u00e1lisis que el Minerd present\u00f3 a la Asociaci\u00f3n Dominicana de Profesores (ADP), en el marco del di\u00e1logo que llevan a cabo para consensuar un incremento salarial a los docentes del sistema educativo preuniversitario este a\u00f1o 2024. Tanto el porcentaje como la aplicaci\u00f3n del aumento salarial deben ser discutidos este mes, conforme lo indica el pacto suscrito por ambas entidades el 24 de julio de 2023. El acuerdo tambi\u00e9n establece que el gremio magisterial debe garantizar el cumplimiento del calendario y el horario escolar en todos los centros educativos p\u00fablicos del pa\u00eds. De los recursos que el Ministerio de Educaci\u00f3n destin\u00f3 a gastos en personal el a\u00f1o pasado, el 83 % correspondi\u00f3 a los maestros. Ese porcentaje, en el a\u00f1o 2018, solo representaba 72% de la n\u00f3mina.<\/p>\n","protected":false},"author":9,"featured_media":95874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-95873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95873"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95873\/revisions"}],"predecessor-version":[{"id":95875,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95873\/revisions\/95875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95874"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}