{"id":95913,"date":"2024-04-18T07:34:12","date_gmt":"2024-04-18T11:34:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95913"},"modified":"2024-04-18T07:34:13","modified_gmt":"2024-04-18T11:34:13","slug":"clasico-de-mountain-bike-con-los-mejores-ciclistas-dominicanos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/clasico-de-mountain-bike-con-los-mejores-ciclistas-dominicanos\/","title":{"rendered":"Cl\u00e1sico de Mountain Bike con los mejores ciclistas dominicanos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Salida-1era-MTB-La-Fefada-2024.jpg\" alt=\"\" class=\"wp-image-95914\" width=\"237\" height=\"188\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Salida-1era-MTB-La-Fefada-2024.jpg 735w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Salida-1era-MTB-La-Fefada-2024-300x238.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/Salida-1era-MTB-La-Fefada-2024-600x475.jpg 600w\" sizes=\"auto, (max-width: 237px) 100vw, 237px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- En continuaci\u00f3n preparativa para la gran prueba internacional UCI, el &nbsp;Cl\u00e1sico de Mountain Bike \u201cLa FEFADA\u00bb realizar\u00e1 su segunda carrera este domingo 21 en el mismo Parque Ecodeportivo de Caballona y tendr\u00e1 como ingrediente especial la defensa del liderato del Yeudi Liranzo (Salcedo Cargo Express Team) y a Awdrey Martes (Team SDO) &nbsp;en la categor\u00eda \u00e9lite masculino y femenino, en un recorrido de 4 vueltas a un trazado de 6.7kms &nbsp;de campo traviesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, distribuidos en 19 categor\u00edas los campeones defensores de la 1era etapa &nbsp;a vencer este domingo son, en la \u00c9lite N2, Edward de Le\u00f3n (Partelomas MTB), en la Sub23, Alex Mu\u00f1oz (Team SDO), en Master A1, Wandy Reyes (Trek Dominicana), Master A2, Randy S\u00e1nchez (Oddis Mec\u00e1nica SC), Master B1, Felito Rojas (Deliveries), Master B2, Leonardo Chevalier (Puerto Plata), &nbsp;Master C, Obed Cabrera (Saltamontes\/ Inteja), Master D, Alexis Guzm\u00e1n(Saltamontes \/ Cannondale).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, defienden la camiseta verde en sus respectivas categor\u00edas, en la E-Bike Un-locked, Nathaniel Pe\u00f1a (BMC), E-Bike Locked, Luis Ulloa (Enduros Brothers), en Juveniles, Raymon Johan Hernandez (La Bicicleter\u00eda), en PreJuveniles, Yowal Ismael S\u00e1nchez (Deliveries MTB), y Lennys Hubber, en la categor\u00eda Master Femenina((Team SDO).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera lo hacen en los dem\u00e1s niveles, Infantil A, Christian Vald\u00e9z (Saltamontes\/Canondale), Infantil A, &nbsp;Jeremy Amezquita (Trek Dominicana), infantil C, el Ucraniano David Kochnev Riabo (Punta Cana Pro).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento que&nbsp; espera mantener la participaci\u00f3n de 200 ciclistas en la pista, es organizado por PlanetBike y cuenta con el apoyo log\u00edstico de VitaSalud, Cannondale, Xtreme Route Sport Wear, Montecci, Inside Deportivo y EB-Timing.&nbsp; Lo supervisa el Colegio Dominicano de Comisarios de Ciclismo y con el Aval de la Asociaci\u00f3n de Ciclismo del DN, Asocidisna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El &nbsp;Cl\u00e1sico de Mountain Bike \u201cLa FEFADA\u00bb es una serie puntuable de 4 carreras que desde el a\u00f1o 2001 viene realizando PlanetBike en el Gran Santo Domingo, en un circuito donde el ciclista es exigido desde su inicio, a partir de las 9:00 am.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00daltima ser\u00e1 internacional<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La novedad de esta temporada es que PlanetBike quiere concluir como una Fefada MTB Internacional, avalada por la Union Ciclists Internacional (UCI).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello se ha gestionado con la Federaci\u00f3n Dominicana de Ciclismo su inclusi\u00f3n en el calendario internacional de la Uni\u00f3n Ciclista Internacional (UCI), de manera que nuestros principales corredores tengan la oportunidad de enfrentarse a ciclistas extranjeros en nuestro patio y poder adquirir puntos UCI sin tener que irlo a buscar a otros pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fecha prevista de esta competencia es el 27 y 28 de julio, el escenario, La pista de MTB del Parque Ecodeportivo de Caballona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las inscripciones est\u00e1n a\u00fan abiertas y pueden encontrar el link de inscripci\u00f3n en las redes sociales de PlanetbikeRD o llamando al tel\u00e9fono 829-535-2152.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- En continuaci\u00f3n preparativa para la gran prueba internacional UCI, el &nbsp;Cl\u00e1sico de Mountain Bike \u201cLa FEFADA\u00bb realizar\u00e1 su segunda carrera este domingo 21 en el mismo Parque Ecodeportivo de Caballona y tendr\u00e1 como ingrediente especial la defensa del liderato del Yeudi Liranzo (Salcedo Cargo Express Team) y a Awdrey Martes (Team SDO) &nbsp;en la categor\u00eda \u00e9lite masculino y femenino, en un recorrido de 4 vueltas a un trazado de 6.7kms &nbsp;de campo traviesa. De igual forma, distribuidos en 19 categor\u00edas los campeones defensores de la 1era etapa &nbsp;a vencer este domingo son, en la \u00c9lite N2, Edward de Le\u00f3n (Partelomas MTB), en la Sub23, Alex Mu\u00f1oz (Team SDO), en Master A1, Wandy Reyes (Trek Dominicana), Master A2, Randy S\u00e1nchez (Oddis Mec\u00e1nica SC), Master B1, Felito Rojas (Deliveries), Master B2, Leonardo Chevalier (Puerto Plata), &nbsp;Master C, Obed Cabrera (Saltamontes\/ Inteja), Master D, Alexis Guzm\u00e1n(Saltamontes \/ Cannondale). Asimismo, defienden la camiseta verde en sus respectivas categor\u00edas, en la E-Bike Un-locked, Nathaniel Pe\u00f1a (BMC), E-Bike Locked, Luis Ulloa (Enduros Brothers), en Juveniles, Raymon Johan Hernandez (La Bicicleter\u00eda), en PreJuveniles, Yowal Ismael S\u00e1nchez (Deliveries MTB), y Lennys Hubber, en la categor\u00eda Master Femenina((Team SDO). De igual manera lo hacen en los dem\u00e1s niveles, Infantil A, Christian Vald\u00e9z (Saltamontes\/Canondale), Infantil A, &nbsp;Jeremy Amezquita (Trek Dominicana), infantil C, el Ucraniano David Kochnev Riabo (Punta Cana Pro). Este evento que&nbsp; espera mantener la participaci\u00f3n de 200 ciclistas en la pista, es organizado por PlanetBike y cuenta con el apoyo log\u00edstico de VitaSalud, Cannondale, Xtreme Route Sport Wear, Montecci, Inside Deportivo y EB-Timing.&nbsp; Lo supervisa el Colegio Dominicano de Comisarios de Ciclismo y con el Aval de la Asociaci\u00f3n de Ciclismo del DN, Asocidisna. El &nbsp;Cl\u00e1sico de Mountain Bike \u201cLa FEFADA\u00bb es una serie puntuable de 4 carreras que desde el a\u00f1o 2001 viene realizando PlanetBike en el Gran Santo Domingo, en un circuito donde el ciclista es exigido desde su inicio, a partir de las 9:00 am. \u00daltima ser\u00e1 internacional La novedad de esta temporada es que PlanetBike quiere concluir como una Fefada MTB Internacional, avalada por la Union Ciclists Internacional (UCI). Para ello se ha gestionado con la Federaci\u00f3n Dominicana de Ciclismo su inclusi\u00f3n en el calendario internacional de la Uni\u00f3n Ciclista Internacional (UCI), de manera que nuestros principales corredores tengan la oportunidad de enfrentarse a ciclistas extranjeros en nuestro patio y poder adquirir puntos UCI sin tener que irlo a buscar a otros pa\u00edses. La fecha prevista de esta competencia es el 27 y 28 de julio, el escenario, La pista de MTB del Parque Ecodeportivo de Caballona. Las inscripciones est\u00e1n a\u00fan abiertas y pueden encontrar el link de inscripci\u00f3n en las redes sociales de PlanetbikeRD o llamando al tel\u00e9fono 829-535-2152.<\/p>\n","protected":false},"author":9,"featured_media":95914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-95913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95913"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95913\/revisions"}],"predecessor-version":[{"id":95915,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95913\/revisions\/95915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95914"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}