{"id":95988,"date":"2024-04-22T06:43:30","date_gmt":"2024-04-22T10:43:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=95988"},"modified":"2024-04-22T06:43:37","modified_gmt":"2024-04-22T10:43:37","slug":"detectan-51383-criaderos-de-mosquito-transmisor-de-dengue","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/detectan-51383-criaderos-de-mosquito-transmisor-de-dengue\/","title":{"rendered":"Detectan 51,383 criaderos de mosquito transmisor de dengue"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/6625a37a515aa.jpeg\" alt=\"\" class=\"wp-image-95989\" width=\"243\" height=\"162\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/6625a37a515aa.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/6625a37a515aa-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/6625a37a515aa-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/6625a37a515aa-600x400.jpeg 600w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Unos 51,383 criaderos positivos a la crianza del mosquito Aedes aegypti, transmisor del dengue, fueron encontrados en viviendas visitadas en las diferentes provincias del pa\u00eds durante los primeros 10 d\u00edas de la Jornada Nacional de Movilizaci\u00f3n Social Contra el Dengue que se lleva a cabo en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante esas intervenciones, tambi\u00e9n fueron encontradas 1,458 personas con fiebre y se visitaron 117,763 viviendas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los recipientes que acumulan agua donde se cr\u00eda el mosquito transmisor del virus se encuentran tanques, botellas, gomas, floreros y latas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed se registra en la base de datos, a la cual tuvo acceso List\u00edn Diario, que recoge las intervenciones realizadas durante el per\u00edodo del ocho al 18 de este mes durante la Jornada de Movilizaci\u00f3n Social Contra el Dengue 2024 que lleva a cabo el Ministerio de Salud P\u00fablica junto a diferentes instituciones y organizaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe destaca que de las 117,763 viviendas visitadas, de las cuales 88,114 estaban abiertas y 23,841 estaban cerradas. En los hogares se registraron 276,806 residentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los recipientes encontrados en los hogares en diferentes provincias del pa\u00eds se registran 169,920 tanques de almacenamiento de agua y 137,819 otros identificados como botellas, gomas, floreros y latas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante las intervenciones, de acuerdo al reporte del Ministerio de Salud P\u00fablica, se eliminaron 71,623 criaderos de mosquitos mediante acciones de botar el agua acumulada, voltear los cacharros o eliminarlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, registra que fueron tratados con larvicidas 149,778 recipientes y se realizaron 6,918 acciones de fumigaci\u00f3n para eliminar el mosquito adulto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se realizaron durante esos 10 d\u00edas, de acuerdo al reporte del Ministerio de Salud, 138 horas de perifoneo; se entregaron 76,920 brochures o afiches; se entregaron 23,111 tapas para tanques de almacenamiento de agua; se hicieron 24,201 instrucciones con cloro para ense\u00f1ar a las familias c\u00f3mo limpiar los envases y se entregaron 2,411 mosquiteros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud P\u00fablica registra que en esas labores las direcciones de \u00e1reas, provinciales y regionales de salud contaron con el apoyo de 769 instituciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s de seis mil casos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la Jornada Nacional contra el Dengue que fue lanzada de manera oficial el pasado mi\u00e9rcoles 9 de abril, las autoridades buscan movilizar e integrar a la sociedad con acciones dirigidas a evitar una alta incidencia de dengue durante este a\u00f1o, que de acuerdo a las alertas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unos 51,383 criaderos positivos a la crianza del mosquito Aedes aegypti, transmisor del dengue, fueron encontrados en viviendas visitadas en las diferentes provincias del pa\u00eds durante los primeros 10 d\u00edas de la Jornada Nacional de Movilizaci\u00f3n Social Contra el Dengue que se lleva a cabo en el pa\u00eds. Durante esas intervenciones, tambi\u00e9n fueron encontradas 1,458 personas con fiebre y se visitaron 117,763 viviendas. Entre los recipientes que acumulan agua donde se cr\u00eda el mosquito transmisor del virus se encuentran tanques, botellas, gomas, floreros y latas. As\u00ed se registra en la base de datos, a la cual tuvo acceso List\u00edn Diario, que recoge las intervenciones realizadas durante el per\u00edodo del ocho al 18 de este mes durante la Jornada de Movilizaci\u00f3n Social Contra el Dengue 2024 que lleva a cabo el Ministerio de Salud P\u00fablica junto a diferentes instituciones y organizaciones. El informe destaca que de las 117,763 viviendas visitadas, de las cuales 88,114 estaban abiertas y 23,841 estaban cerradas. En los hogares se registraron 276,806 residentes. Entre los recipientes encontrados en los hogares en diferentes provincias del pa\u00eds se registran 169,920 tanques de almacenamiento de agua y 137,819 otros identificados como botellas, gomas, floreros y latas. Durante las intervenciones, de acuerdo al reporte del Ministerio de Salud P\u00fablica, se eliminaron 71,623 criaderos de mosquitos mediante acciones de botar el agua acumulada, voltear los cacharros o eliminarlos. Tambi\u00e9n, registra que fueron tratados con larvicidas 149,778 recipientes y se realizaron 6,918 acciones de fumigaci\u00f3n para eliminar el mosquito adulto. Asimismo, se realizaron durante esos 10 d\u00edas, de acuerdo al reporte del Ministerio de Salud, 138 horas de perifoneo; se entregaron 76,920 brochures o afiches; se entregaron 23,111 tapas para tanques de almacenamiento de agua; se hicieron 24,201 instrucciones con cloro para ense\u00f1ar a las familias c\u00f3mo limpiar los envases y se entregaron 2,411 mosquiteros. Salud P\u00fablica registra que en esas labores las direcciones de \u00e1reas, provinciales y regionales de salud contaron con el apoyo de 769 instituciones. M\u00e1s de seis mil casos Con la Jornada Nacional contra el Dengue que fue lanzada de manera oficial el pasado mi\u00e9rcoles 9 de abril, las autoridades buscan movilizar e integrar a la sociedad con acciones dirigidas a evitar una alta incidencia de dengue durante este a\u00f1o, que de acuerdo a las alertas<\/p>\n","protected":false},"author":9,"featured_media":95989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-95988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=95988"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95988\/revisions"}],"predecessor-version":[{"id":95990,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/95988\/revisions\/95990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/95989"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=95988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=95988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=95988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}