{"id":9606,"date":"2014-10-20T01:30:12","date_gmt":"2014-10-20T05:30:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9606"},"modified":"2014-10-20T01:30:12","modified_gmt":"2014-10-20T05:30:12","slug":"nueva-aplicacion-permite-a-los-sordos-escuchar-conversaciones-en-grupo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nueva-aplicacion-permite-a-los-sordos-escuchar-conversaciones-en-grupo\/","title":{"rendered":"Nueva aplicaci\u00f3n permite a los sordos \u00abescuchar\u00bb conversaciones en grupo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/aplicacion-para-sordos-escuchen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9607 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/aplicacion-para-sordos-escuchen.jpg\" alt=\"aplicacion para sordos escuchen\" width=\"630\" height=\"354\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/aplicacion-para-sordos-escuchen.jpg 630w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/aplicacion-para-sordos-escuchen-300x168.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><br \/>\nLos investigadores han desarrollado la primera aplicaci\u00f3n m\u00f3vil que convierte en una realidad las conversaciones entre personas sordas y oyentes. La aplicaci\u00f3n &#8216;escucha&#8217; e interpreta las conversaciones.<!--more--><\/p>\n<p>La aplicaci\u00f3n, llamada The Transcense y desarrollada por investigadores de Estados Unidos, Francia, los Pa\u00edses Bajos y China, conecta los &#8216;smartphones&#8217; de varios interlocutores en una habitaci\u00f3n y aprovecha los micr\u00f3fonos para &#8216;escuchar&#8217; a los que hablan, explica TechCrunch.<\/p>\n<p>Luego, utilizando los sistemas de reconocimiento de voz m\u00e1s avanzados, transcribe inmediatamente la conversaci\u00f3n en una pantalla. Las personas con problemas de audici\u00f3n tambi\u00e9n pueden utilizar la aplicaci\u00f3n para responder y obtener la atenci\u00f3n de un grupo mediante el uso de una voz digital personalizada.<\/p>\n<p>\u00abSe trata de un invento realmente fant\u00e1stico. Cada d\u00eda, 360 millones de personas quedan excluidas de conversaciones en grupo debido a sus problemas de audici\u00f3n\u00bb, recuerda Josephine Schallehn, de la Asociaci\u00f3n de la P\u00e9rdida de Audici\u00f3n.<\/p>\n<p>Actualmente los autores de The Transcense est\u00e1n recaudando fondos v\u00eda\u00a0Indiegogo\u00a0para lanzar al mercado la innovadora aplicaci\u00f3n. De momento ya han recaudado cerca del 80% de su meta de 25.000 de d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los investigadores han desarrollado la primera aplicaci\u00f3n m\u00f3vil que convierte en una realidad las conversaciones entre personas sordas y oyentes. La aplicaci\u00f3n &#8216;escucha&#8217; e interpreta las conversaciones.<\/p>\n","protected":false},"author":3,"featured_media":9607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-9606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9606"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9606\/revisions"}],"predecessor-version":[{"id":9608,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9606\/revisions\/9608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9607"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}