{"id":96094,"date":"2024-04-28T08:41:21","date_gmt":"2024-04-28T12:41:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96094"},"modified":"2024-04-28T08:41:22","modified_gmt":"2024-04-28T12:41:22","slug":"tribunal-rechaza-demanda-contra-asalto-en-progreso-filme-se-estrenara-el-2-de-mayo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tribunal-rechaza-demanda-contra-asalto-en-progreso-filme-se-estrenara-el-2-de-mayo\/","title":{"rendered":"Tribunal rechaza demanda contra \u201cAsalto en Progreso\u201d, filme se estrenar\u00e1 el 2 de mayo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"465\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/662da37830a4c.jpeg\" alt=\"\" class=\"wp-image-96095\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/662da37830a4c.jpeg 950w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/662da37830a4c-300x147.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/662da37830a4c-768x376.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/662da37830a4c-600x294.jpeg 600w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La pel\u00edcula \u00abAsalto en Progreso\u00bb finalmente tiene el camino despejado para llegar a las salas de cine del pa\u00eds a partir del pr\u00f3ximo 2 de mayo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la C\u00e1mara Civil y Comercial del Juzgado de Primera Instancia del Distrito Nacional, Miguel \u00c1ngel D\u00edaz Villalona, rechaz\u00f3 la demanda de derecho de autor interpuesta por GT Films y Cirilo Michael Toribio Corniel contra La Aldea Studio, Francisco de Jes\u00fas Disla Ferreira (El Indio), Anna Iris G\u00f3mez y el director Josell Hern\u00e1ndez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez de los Referimientos fundament\u00f3 su decisi\u00f3n en el entendido de que el derecho de autor se aplica a las obras producidas en torno a un hecho hist\u00f3rico, pero no otorga exclusividad sobre el hecho en s\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsto significa que sobre un mismo hecho hist\u00f3rico, o hecho de notoriedad p\u00fablica, como el asalto ocurrido en la entidad financiera, pueden surgir diferentes obras literarias o art\u00edsticas, siendo \u00e9stas \u00faltimas las protegidas por el derecho de autor, no as\u00ed el hecho hist\u00f3rico o de notoriedad p\u00fablica ilustrado\u00bb, estableci\u00f3 en la sentencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utiliz\u00f3 como ejemplo las producciones realizadas sobre el tr\u00e1gico suceso del 11 de septiembre de 2001, el ataque terrorista a las Torres Gemelas de Nueva York.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTodas estas obras cinematogr\u00e1ficas versan sobre el mismo hecho y cada una de ellas, de forma individual, est\u00e1 protegida por el derecho de autor. Lo mismo ocurre con el caso que ocupa al tribunal, donde cada una de las obras cinematogr\u00e1ficas tiene la protecci\u00f3n del derecho de autor, pero el suceso del asalto ocurrido en la entidad financiera es de dominio p\u00fablico\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por medio de la demanda, GT Films y Cirilo persegu\u00edan sin fundamento jur\u00eddico que los productores se abstuvieran de \u201cutilizar, vender, comercializar, transmitir, obsequiar, divulgar, promocionar, realizar premiere de pel\u00edculas, proyectar pel\u00edculas, de marcas y derechos registrados, como la careta y sus colores reivindicados en ONAPI seg\u00fan registro de Marca Mixta de la ONAPI no. 232593, los registros de registro de la ONDA no. 0007059 y no. 000945, y derechos de autor cedidos por Luis Eduardo Lora Iglesias (Huchi Lora) a Toribio Corniel\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante lo expuesto, el juzgado consider\u00f3 que la demanda contra los productores de \u00abAsalto en Progreso\u00bb carece de base legal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con respecto a la solicitud sobre el uso de la m\u00e1scara que utiliz\u00f3 el asaltante para penetrar al banco aquel 1 de marzo de 1993 , el magistrado consider\u00f3 que el registro de la careta en la ONAPI es un \u00abadefesio\u00bb.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo se puede apropiar de algo que no le pertenece, ya que no confeccion\u00f3 dicha m\u00e1scara, la cual se utiliza en los carnavales y es un producto gen\u00e9rico importado desde China\u00bb, puntualiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El filme \u201cAsalto en Progreso\u201d, dirigido por Josell Hern\u00e1ndez, es una obra cinematogr\u00e1fica que fusiona drama, intriga y la cruda realidad de un suceso que dej\u00f3 una marca imborrable en la memoria de la sociedad dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El largometraje cuenta con un elenco estelar de la industria cinematogr\u00e1fica dominicana, incluyendo a figuras destacadas como Pepe Sierra, Mar\u00eda Castillo, Hony Estrella, Irving Alberti, Richard Douglas, Francis Cruz y Jochy Santos, entre otros destacados actores. Josell Hern\u00e1ndez tiene grandes expectativas para su pel\u00edcula, previendo que se convertir\u00e1 en el drama m\u00e1s comercial de la historia del cine local. Con su enfoque en la resiliencia familiar, Hern\u00e1ndez espera que el p\u00fablico se lleve un mensaje poderoso sobre el valor de la familia y la importancia de mantener la esperanza, incluso en circunstancias dif\u00edciles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pel\u00edcula \u00abAsalto en Progreso\u00bb finalmente tiene el camino despejado para llegar a las salas de cine del pa\u00eds a partir del pr\u00f3ximo 2 de mayo.&nbsp; El presidente de la C\u00e1mara Civil y Comercial del Juzgado de Primera Instancia del Distrito Nacional, Miguel \u00c1ngel D\u00edaz Villalona, rechaz\u00f3 la demanda de derecho de autor interpuesta por GT Films y Cirilo Michael Toribio Corniel contra La Aldea Studio, Francisco de Jes\u00fas Disla Ferreira (El Indio), Anna Iris G\u00f3mez y el director Josell Hern\u00e1ndez. El juez de los Referimientos fundament\u00f3 su decisi\u00f3n en el entendido de que el derecho de autor se aplica a las obras producidas en torno a un hecho hist\u00f3rico, pero no otorga exclusividad sobre el hecho en s\u00ed. \u00abEsto significa que sobre un mismo hecho hist\u00f3rico, o hecho de notoriedad p\u00fablica, como el asalto ocurrido en la entidad financiera, pueden surgir diferentes obras literarias o art\u00edsticas, siendo \u00e9stas \u00faltimas las protegidas por el derecho de autor, no as\u00ed el hecho hist\u00f3rico o de notoriedad p\u00fablica ilustrado\u00bb, estableci\u00f3 en la sentencia. Utiliz\u00f3 como ejemplo las producciones realizadas sobre el tr\u00e1gico suceso del 11 de septiembre de 2001, el ataque terrorista a las Torres Gemelas de Nueva York.&nbsp; \u00abTodas estas obras cinematogr\u00e1ficas versan sobre el mismo hecho y cada una de ellas, de forma individual, est\u00e1 protegida por el derecho de autor. Lo mismo ocurre con el caso que ocupa al tribunal, donde cada una de las obras cinematogr\u00e1ficas tiene la protecci\u00f3n del derecho de autor, pero el suceso del asalto ocurrido en la entidad financiera es de dominio p\u00fablico\u00bb, afirm\u00f3. Por medio de la demanda, GT Films y Cirilo persegu\u00edan sin fundamento jur\u00eddico que los productores se abstuvieran de \u201cutilizar, vender, comercializar, transmitir, obsequiar, divulgar, promocionar, realizar premiere de pel\u00edculas, proyectar pel\u00edculas, de marcas y derechos registrados, como la careta y sus colores reivindicados en ONAPI seg\u00fan registro de Marca Mixta de la ONAPI no. 232593, los registros de registro de la ONDA no. 0007059 y no. 000945, y derechos de autor cedidos por Luis Eduardo Lora Iglesias (Huchi Lora) a Toribio Corniel\u201d. Ante lo expuesto, el juzgado consider\u00f3 que la demanda contra los productores de \u00abAsalto en Progreso\u00bb carece de base legal.&nbsp; Con respecto a la solicitud sobre el uso de la m\u00e1scara que utiliz\u00f3 el asaltante para penetrar al banco aquel 1 de marzo de 1993 , el magistrado consider\u00f3 que el registro de la careta en la ONAPI es un \u00abadefesio\u00bb.&nbsp; \u00abNo se puede apropiar de algo que no le pertenece, ya que no confeccion\u00f3 dicha m\u00e1scara, la cual se utiliza en los carnavales y es un producto gen\u00e9rico importado desde China\u00bb, puntualiz\u00f3. El filme \u201cAsalto en Progreso\u201d, dirigido por Josell Hern\u00e1ndez, es una obra cinematogr\u00e1fica que fusiona drama, intriga y la cruda realidad de un suceso que dej\u00f3 una marca imborrable en la memoria de la sociedad dominicana. El largometraje cuenta con un elenco estelar de la industria cinematogr\u00e1fica dominicana, incluyendo a figuras destacadas como Pepe Sierra, Mar\u00eda Castillo, Hony Estrella, Irving Alberti, Richard Douglas, Francis Cruz y Jochy Santos, entre otros destacados actores. Josell Hern\u00e1ndez tiene grandes expectativas para su pel\u00edcula, previendo que se convertir\u00e1 en el drama m\u00e1s comercial de la historia del cine local. Con su enfoque en la resiliencia familiar, Hern\u00e1ndez espera que el p\u00fablico se lleve un mensaje poderoso sobre el valor de la familia y la importancia de mantener la esperanza, incluso en circunstancias dif\u00edciles.<\/p>\n","protected":false},"author":9,"featured_media":96095,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[387],"tags":[],"class_list":["post-96094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96094"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96094\/revisions"}],"predecessor-version":[{"id":96096,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96094\/revisions\/96096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96095"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}