{"id":96100,"date":"2024-04-28T08:47:07","date_gmt":"2024-04-28T12:47:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96100"},"modified":"2024-04-28T08:47:12","modified_gmt":"2024-04-28T12:47:12","slug":"estados-unidos-felicita-republica-dominicana-por-lucha-anticrimen","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/estados-unidos-felicita-republica-dominicana-por-lucha-anticrimen\/","title":{"rendered":"Estados Unidos felicita Rep\u00fablica Dominicana por lucha anticrimen"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/De-izquierda-a-derecha.jpg\" alt=\"\" class=\"wp-image-96101\" width=\"232\" height=\"155\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/De-izquierda-a-derecha.jpg 695w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/De-izquierda-a-derecha-300x201.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/De-izquierda-a-derecha-600x402.jpg 600w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- Una delegaci\u00f3n de alto nivel de Rep\u00fablica Dominicana, invitada a Washington, Estados Unidos (EE.UU.) fue felicitada por la lucha de este pa\u00eds caribe\u00f1o contra el crimen organizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Direcci\u00f3n Nacional de Control de Drogas (DNDC) indic\u00f3 que la representaci\u00f3n dominicana fue encabezada por la Procuradora General de la Rep\u00fablica, doctora Miriam Germ\u00e1n Brito; el vicealmirante Jos\u00e9 Manuel Cabrera Ulloa, presidente de la DNCD, a los que acompa\u00f1aron otros funcionarios gubernamentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La invitaci\u00f3n fue cursada por la Administradora de la Drug Enforcement Administration (DEA por sus siglas en ingl\u00e9s), Anne Wilgram y Ronald L. Davis, director de los United Marshals Service.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FELICITACI\u00d3N POR OPERACIONES RECIENTES<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/almomento.net\/wp-content\/uploads\/2024\/04\/Otra.jpg\" alt=\"\" class=\"wp-image-950615\" \/><figcaption>De izquierda a derecha Anne Wilgran, administradora de la DEA; Miriam Germ\u00e1n Brito, procuradora general de la Rep\u00fablica Dominicana; vicealmirante Jos\u00e9 M. Cabrera Ulloa, presidente de la DNCD y Renita Denise Foster, directora de la divisi\u00f3n Caribe Marshals<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su estancia en Washington entre el 15 y 19 de este mes, la DEA felicit\u00f3 al Gobierno dominicano por exitosas operaciones conjuntas con duros golpes al narcotr\u00e1fico y el crimen organizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n el director de los U.S Marshals, Ronald E. Davis, reconoci\u00f3 de manera especial a este pa\u00eds por escalar del d\u00e9cimo al tercer lugar en la captura de fugitivos de la justicia estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte del apoyo continuo de EE.UU. a Dominicana en ese rengl\u00f3n, tambi\u00e9n se trataron temas para fortalecer las relaciones de cooperaci\u00f3n y de acci\u00f3n r\u00e1pida efectiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>OPERACI\u00d3N CAYM\u00c1N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ejemplo de \u00e9xito, las partes mencionaron la reciente operaci\u00f3n Caym\u00e1n, reconocida por los organismos estadounidenses como una de las m\u00e1s contundentes de los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las reuniones realizadas en Washington, los invitados dominicanos enfatizaron el compromiso de continuar en la lucha contra el crimen organizado en todos los escenarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Una delegaci\u00f3n de alto nivel de Rep\u00fablica Dominicana, invitada a Washington, Estados Unidos (EE.UU.) fue felicitada por la lucha de este pa\u00eds caribe\u00f1o contra el crimen organizado. La Direcci\u00f3n Nacional de Control de Drogas (DNDC) indic\u00f3 que la representaci\u00f3n dominicana fue encabezada por la Procuradora General de la Rep\u00fablica, doctora Miriam Germ\u00e1n Brito; el vicealmirante Jos\u00e9 Manuel Cabrera Ulloa, presidente de la DNCD, a los que acompa\u00f1aron otros funcionarios gubernamentales. La invitaci\u00f3n fue cursada por la Administradora de la Drug Enforcement Administration (DEA por sus siglas en ingl\u00e9s), Anne Wilgram y Ronald L. Davis, director de los United Marshals Service. FELICITACI\u00d3N POR OPERACIONES RECIENTES Durante su estancia en Washington entre el 15 y 19 de este mes, la DEA felicit\u00f3 al Gobierno dominicano por exitosas operaciones conjuntas con duros golpes al narcotr\u00e1fico y el crimen organizado. Tambi\u00e9n el director de los U.S Marshals, Ronald E. Davis, reconoci\u00f3 de manera especial a este pa\u00eds por escalar del d\u00e9cimo al tercer lugar en la captura de fugitivos de la justicia estadounidense. Como parte del apoyo continuo de EE.UU. a Dominicana en ese rengl\u00f3n, tambi\u00e9n se trataron temas para fortalecer las relaciones de cooperaci\u00f3n y de acci\u00f3n r\u00e1pida efectiva. OPERACI\u00d3N CAYM\u00c1N Como ejemplo de \u00e9xito, las partes mencionaron la reciente operaci\u00f3n Caym\u00e1n, reconocida por los organismos estadounidenses como una de las m\u00e1s contundentes de los \u00faltimos a\u00f1os. En las reuniones realizadas en Washington, los invitados dominicanos enfatizaron el compromiso de continuar en la lucha contra el crimen organizado en todos los escenarios.<\/p>\n","protected":false},"author":9,"featured_media":96101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-96100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96100"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96100\/revisions"}],"predecessor-version":[{"id":96102,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96100\/revisions\/96102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96101"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}