{"id":9612,"date":"2014-10-20T11:41:14","date_gmt":"2014-10-20T15:41:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9612"},"modified":"2014-10-20T11:41:14","modified_gmt":"2014-10-20T15:41:14","slug":"14-alimentos-que-ayudan-a-enfrentar-el-cancer","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/14-alimentos-que-ayudan-a-enfrentar-el-cancer\/","title":{"rendered":"14 alimentos que ayudan a enfrentar el c\u00e1ncer"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/avena-668x400x80xX.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9613 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/avena-668x400x80xX-300x200.jpg\" alt=\"avena-668x400x80xX\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/avena-668x400x80xX-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/avena-668x400x80xX.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El 19 de octubre se conmemora la lucha contra el c\u00e1ncer de mama, pero no s\u00f3lo ese <label>d\u00eda<\/label>debemos cuidarnos, tocarnos y estar pendientes de nuestra <label>salud<\/label>. Esta puede ser una enfermedad silenciosa, y para \u00abcombatirla\u00bb, no s\u00f3lo bastan los medicamentos o las terapias. \u00abSomos lo que comemos\u00bb, aseguran, y nuestro <label>cuerpo<\/label> necesita nutrientes y vitaminas para ser fuerte y combatir esta enfermedad, por eso, te presentamos 1<label>alimentos<\/label> que te ayudan a enfrentar el c\u00e1ncer.<!--more--><\/p>\n<p>T\u00f3cate. En primer lugar. No s\u00f3lo el 19 de octubre. Hazlo con <label>frecuencia<\/label>, como un h\u00e1bito. Cuida tu salud f\u00edsica y mental, tu alimentaci\u00f3n, tu peso, intenta dejar las preocupaciones a un lado, se feliz, vive. Cuidate.<\/p>\n<p>La entrenadora personal de la ISSA con un master en Fitness Nutrition, Sascha Barboza, comparte con sus seguidores de las redes sociales, 14 alimentos que ayudan a tu cuerpo a combatir el c\u00e1ncer.<\/p>\n<p>Quieres saber <a href=\"http:\/\/informe21.com\/saschafitness\/%C2%BFcomo-bajar-los-trigliceridos\" target=\"_blank\">\u00bfC\u00f3mo bajar los triglic\u00e9ridos?<\/a><\/p>\n<p><strong>14 Alimentos que pueden ayudar a prevenir el c\u00e1ncer de mama.<\/strong><\/p>\n<p><strong>1 Linaza. <\/strong>Ya sea molida o en aceite de linaza. Los omega-3, lignanos y fibra que se encuentran en la linaza forman un escudo protector contra las c\u00e9lulas cancerosas responsables de causar c\u00e1ncer de mama. Agrega linaza a tu avena cocida, batidos y panquecas.<\/p>\n<p><strong>2 Granada.<\/strong> Super recomendable para prevenir c\u00e1ncer de seno. Contiene un \u00e1cido el\u00e1gico polifenol, con propiedades antioxidantes que impiden el crecimiento del c\u00e1ncer.<\/p>\n<p><strong>3 Las nueces del Brasil.<\/strong> Altas en en selenio, fibra y fitoqu\u00edmicos, las nueces de Brasil pueden ayudar a combatir la inflamaci\u00f3n, mejorar el sistema inmunol\u00f3gico y prevenir el crecimiento del tumor.<\/p>\n<p><strong><a href=\"http:\/\/informe21.com\/vegetales\/15-razones-para-comer-vegetales\" target=\"_blank\">4 Vegetales de hojas de color verde oscuro. <\/a><\/strong>Desde espinaca, col rizada (kale), lechuga romana y acelgas, las verduras de hoja verde oscuro, probablemente, se consideran unas de las verduras con mas componentes que nuestro cuerpo necesita para defenderse de las c\u00e9lulas cancerosas, es decir, fibra, vitamina B, fitoqu\u00edmicos , clorofila etc.<\/p>\n<p><strong>5 Br\u00f3coli y vegetales cruc\u00edferos como coles de bruselas y coliflor.<\/strong> Altos en sulforafano. El evita que ciertas enzimas activen los agentes causantes del c\u00e1ncer en el cuerpo y aumenta la producci\u00f3n en el cuerpo de otras enzimas que eliminan los carcin\u00f3genos del sistema antes de que puedan da\u00f1ar las c\u00e9lulas.<\/p>\n<p><strong>6 Ajo.<\/strong> Ademas de aportar mucho sabor a la comida, el ajo y otras verduras similares como cebolla , cebollin y ajo porro\/puerro, contienen un componente que pueden frenar el crecimiento del tumor y prevenir el riesgo de c\u00e1ncer de mama y prostata.<\/p>\n<p><strong><a href=\"http:\/\/informe21.com\/saschafitness\/saschafitness-pierde-la-grasa-consumiendo-grasa\" target=\"_blank\">7 Salm\u00f3n.<\/a> <\/strong>Una gran fuente de omega-3 y vitaminas B12 y D, el salm\u00f3n puede proporcionarle al cuerpo los nutrientes que necesita para regular el crecimiento celular y prevenir el c\u00e1ncer.<\/p>\n<p><a href=\"http:\/\/informe21.com\/saschafitness\/saschafitness-beneficios-de-la-canela\" target=\"_blank\">Beneficios de la canela<\/a><\/p>\n<p><strong><a href=\"http:\/\/informe21.com\/te-verde\/sascha-fitness-el-te-verde-ayuda-a-quemar-grasa\" target=\"_blank\">8 T\u00e9 verde y Matcha. <\/a><\/strong>Los antioxidantes y fitoqu\u00edmicos en el t\u00e9 verde pueden ser un aliado y una gran herramienta para prevenir distintos tipos de c\u00e1ncer. Dos tazas de t\u00e9 verde al d\u00eda pueden ayudar a mantener el c\u00e1ncer a raya.<\/p>\n<p><strong>9 Picante. <\/strong>La mayor\u00eda tienen alg\u00fan fitoqu\u00edmico o nutriente que ayudar\u00e1 a combatir el c\u00e1ncer. Chiles, cayena y jalape\u00f1os tienen capsaicina que combaten el crecimiento de las c\u00e9lulas cancer\u00edgenas.<\/p>\n<p><strong>10 C\u00farcuma. <\/strong>Una especia super poderosa. Puede inhibir muchos tipos de c\u00e9lulas de c\u00e1ncer como el de mama, pulm\u00f3n, gastrointestinal y c\u00e1ncer de piel. Una cucharadita de c\u00farcuma diaria te llevara lejos.<\/p>\n<p><strong>11 Nueces.<\/strong> Son altos en omega-3, fitoesteroles y antioxidantes, las nueces (esas de navidad-walnuts) son alimento ideal contra el c\u00e1ncer de seno.<\/p>\n<p><strong>12 Frutos del bosque:<\/strong> fresas, moras, frambuesas etc. Son una bomba de antioxidantes y fitoqu\u00edmicos que ayudan a reducir la oxidaci\u00f3n y la formaci\u00f3n de c\u00e9lulas cancerosas en el cuerpo.<\/p>\n<p><strong><a href=\"http:\/\/informe21.com\/bajar-de-peso\/saschafitness-10-razones-para-comer-avena\" target=\"_blank\">13 Cereales integrales naturales:<\/a> <\/strong>Avena, amaranto, quinoa, arroz integral. Son altos en fibra y ayudan a reducir los niveles de estr\u00f3geno en el cuerpo ayud\u00e1ndote as\u00ed a ser menos propensa al c\u00e1ncer de mamas.<\/p>\n<p><strong><a href=\"http:\/\/informe21.com\/saschafitness\/saschafitness-9-alimentos-saludables-y-altos-en-fibra\" target=\"_blank\">14 Legumbres Lentejas y frijoles: <\/a><\/strong>Contienen acido folico, fibra y una gran cantidad de nutrientes que previenen el riesgo de c\u00e1ncer.<\/p>\n<p><a href=\"http:\/\/informe21.com\/saschafitness\/saschafitness-%C2%BFcomo-comenzar-una-vida-saludable\" target=\"_blank\">\u00bfC\u00f3mo comenzar una vida saludable?<\/a><\/p>\n<p><strong>QUE EVITAR.<\/strong><\/p>\n<p><strong>Soya:<\/strong> A menos que sea fermentada como el Tempeh, y si en tu familia hay casos de c\u00e1ncer de mamas ni siquiera consumas este tipo, la soya, sobretodo la no fermentada , contiene imitadores del estr\u00f3geno y anti nutrientes, te hace m\u00e1s propenso al c\u00e1ncer de mamas.<\/p>\n<p>Disminuye las bebidas alcoholicas, el exceso te hace m\u00e1s propensa.<\/p>\n<p><a href=\"http:\/\/informe21.com\/azucar\/el-azucar-una-nueva-droga-razones-para-dejar-de-consumirla\" target=\"_blank\">Evita el az\u00facar <\/a>y los carbohidratos refinados como la harina.<\/p>\n<p>Nada de grasas transaturadas como margarina y frituras.<\/p>\n<p>Trata de llevar una vida tranquila, haz ejercicio regularmente, cardiovascular y de fuerza. Y sobre todas las cosas, EXAMINATE, t\u00f3cate y hazte el autoexamen<\/p>\n<p><iframe loading=\"lazy\" id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/instagram.com\/p\/uV48ZFmKdx\/embed\/?v=2\" width=\"300\" height=\"686\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-0\"><\/iframe><\/p>\n<p>Consulta los especiales de<br \/>\n<a href=\"http:\/\/informe21.com\/category\/tags\/saschafitness\">Consejos de Sascha Fitness<\/a><br \/>\n<a href=\"http:\/\/informe21.com\/category\/tags\/dra-samar-yorde\">Recomendaciones de Samar Yorde<\/a><br \/>\n<a href=\"http:\/\/informe21.com\/category\/tags\/alebfitness\" target=\"_blank\">Tips de Alejandra Fitness<\/a><br \/>\n<a href=\"http:\/\/informe21.com\/category\/tags\/figura-sana\" target=\"_blank\">Recetas \u201cLight\u201d<\/a><\/p>\n<p><strong>AJV\/ Informe21<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 19 de octubre se conmemora la lucha contra el c\u00e1ncer de mama, pero no s\u00f3lo ese d\u00edadebemos cuidarnos, tocarnos y estar pendientes de nuestra salud. Esta puede ser una enfermedad silenciosa, y para \u00abcombatirla\u00bb, no s\u00f3lo bastan los medicamentos o las terapias. \u00abSomos lo que comemos\u00bb, aseguran, y nuestro cuerpo necesita nutrientes y vitaminas para ser fuerte y combatir esta enfermedad, por eso, te presentamos 1alimentos que te ayudan a enfrentar el c\u00e1ncer.<\/p>\n","protected":false},"author":3,"featured_media":9613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9612"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9612\/revisions"}],"predecessor-version":[{"id":9614,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9612\/revisions\/9614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9613"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}