{"id":96125,"date":"2024-04-30T06:26:42","date_gmt":"2024-04-30T10:26:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96125"},"modified":"2024-04-30T06:26:43","modified_gmt":"2024-04-30T10:26:43","slug":"karl-towns-avanza-a-los-playoffs-nba-por-primera-vez-en-su-carrer","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/karl-towns-avanza-a-los-playoffs-nba-por-primera-vez-en-su-carrer\/","title":{"rendered":"Karl Towns avanza a los playoffs NBA por primera vez en su carrer"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/04\/kt-300x169-1.jpg\" alt=\"\" class=\"wp-image-96126\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">PHOENIX.- Minnesota Timberwolves\u00a0gan\u00f3 su primera serie de postemporada desde 2004 al barrer a Phoenix Sunx en cuatro encuentros. Unos Timberwolves que contaban con Kevin Garnett, Latrell Sprewell, Wally Szczerbiak y otros m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esa ocasi\u00f3n Minnesota avanz\u00f3 hasta las finales de la Conferencia del Oeste al derrotar a Dallas Mavericks y Sacramento King, hasta caer derrotados ante Los Angeles Lakers de Shaq, Kobe, Karl Malone y Gary Payton.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora los Timberwolves de&nbsp;<strong><a href=\"https:\/\/www.espn.com.do\/basquetbol\/nba\/jugador\/_\/id\/3136195\/karl-anthony-towns\">Karl-Anthony Towns<\/a><\/strong>,&nbsp;<a href=\"https:\/\/www.espn.com.do\/basquetbol\/nba\/jugador\/_\/id\/4594268\/anthony-edwards\">Anthony Edwards<\/a>&nbsp;y Rudy Gober buscar\u00e1n seguir avanzando y ser\u00e1n rival&nbsp; de los Denver Nuggets que despacharon a Los Angeles Lakers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ara todos la victoria seguro tiene un sabor especial. Pero mucho m\u00e1s para Towns quien avanza por primera vez en una serie de postemporada despu\u00e9s de casi una d\u00e9cada y tres intentos fallidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2018, su primera experiencia en playoffs, cay\u00f3 en cinco partidos ante Houston Rockets para posteriormente hacerlo nueva vez frente a Memphis Grizzlies en 2022 durante seis partidos. La pasada postemporada los Denver Nuggets, eventuales campeones, solo necesitaron cinco juegos para eliminar a KAT y los Timberwolves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora con un magistral Anthony Edwards, los Twolves barrieron al contrario por primera vez en su historia en la postemporada, al derrotar en cuatro encuentros a Phoenix, que con el tr\u00edo de Kevin Durant, Bradley Beal y Devin Booker, muchos esperaban que fuera un equipo que pudiera competir por el campeonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Towns finaliz\u00f3 el encuentro con un doble-doble, su segundo de la serie, anotando 28 puntos y capturando 10 rebotes, tirando de 11-17 desde el tabloncillo y sumando 3 asistencias. Karl Towns anot\u00f3 15 puntos en la primera mitad, su mayor cantidad en una mitad en su carrera en la postemporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">KAT tambi\u00e9n fue relevante a la defensiva ya que durante la serie, siendo el defensor principal ante Kevin Durant, limit\u00f3 a la estrella de los Suns a un 33.3% de efectividad desde el campo, solo anot\u00e1ndole un triple.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero todos los ojos estuvieron puestos en Edwards, un jugador que va en ascenso en su carrera y como un veterano l\u00edder, Towns tiene bien claro lo que sigue si los Timberwolves desean seguir avanzando en la postemporada y ser relevantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs especial. Ya sab\u00eda que era especial cuando lleg\u00f3 a Minnesota\u201d, expres\u00f3 KAT sobre Edwards al finalizar el encuentro. \u201c<strong>Mi trabajo es ayudarle a alcanzar su mayor potencial, ayudarle a ser lo mejor que puede llegar a ser<\/strong>. Es especial\u2026 Juntos podemos hacer algo especial aqu\u00ed\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PHOENIX.- Minnesota Timberwolves\u00a0gan\u00f3 su primera serie de postemporada desde 2004 al barrer a Phoenix Sunx en cuatro encuentros. Unos Timberwolves que contaban con Kevin Garnett, Latrell Sprewell, Wally Szczerbiak y otros m\u00e1s. En esa ocasi\u00f3n Minnesota avanz\u00f3 hasta las finales de la Conferencia del Oeste al derrotar a Dallas Mavericks y Sacramento King, hasta caer derrotados ante Los Angeles Lakers de Shaq, Kobe, Karl Malone y Gary Payton. Ahora los Timberwolves de&nbsp;Karl-Anthony Towns,&nbsp;Anthony Edwards&nbsp;y Rudy Gober buscar\u00e1n seguir avanzando y ser\u00e1n rival&nbsp; de los Denver Nuggets que despacharon a Los Angeles Lakers. ara todos la victoria seguro tiene un sabor especial. Pero mucho m\u00e1s para Towns quien avanza por primera vez en una serie de postemporada despu\u00e9s de casi una d\u00e9cada y tres intentos fallidos. En 2018, su primera experiencia en playoffs, cay\u00f3 en cinco partidos ante Houston Rockets para posteriormente hacerlo nueva vez frente a Memphis Grizzlies en 2022 durante seis partidos. La pasada postemporada los Denver Nuggets, eventuales campeones, solo necesitaron cinco juegos para eliminar a KAT y los Timberwolves. Ahora con un magistral Anthony Edwards, los Twolves barrieron al contrario por primera vez en su historia en la postemporada, al derrotar en cuatro encuentros a Phoenix, que con el tr\u00edo de Kevin Durant, Bradley Beal y Devin Booker, muchos esperaban que fuera un equipo que pudiera competir por el campeonato. Towns finaliz\u00f3 el encuentro con un doble-doble, su segundo de la serie, anotando 28 puntos y capturando 10 rebotes, tirando de 11-17 desde el tabloncillo y sumando 3 asistencias. Karl Towns anot\u00f3 15 puntos en la primera mitad, su mayor cantidad en una mitad en su carrera en la postemporada. KAT tambi\u00e9n fue relevante a la defensiva ya que durante la serie, siendo el defensor principal ante Kevin Durant, limit\u00f3 a la estrella de los Suns a un 33.3% de efectividad desde el campo, solo anot\u00e1ndole un triple. Pero todos los ojos estuvieron puestos en Edwards, un jugador que va en ascenso en su carrera y como un veterano l\u00edder, Towns tiene bien claro lo que sigue si los Timberwolves desean seguir avanzando en la postemporada y ser relevantes. \u201cEs especial. Ya sab\u00eda que era especial cuando lleg\u00f3 a Minnesota\u201d, expres\u00f3 KAT sobre Edwards al finalizar el encuentro. \u201cMi trabajo es ayudarle a alcanzar su mayor potencial, ayudarle a ser lo mejor que puede llegar a ser. Es especial\u2026 Juntos podemos hacer algo especial aqu\u00ed\u201d.<\/p>\n","protected":false},"author":9,"featured_media":96126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-96125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96125"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96125\/revisions"}],"predecessor-version":[{"id":96127,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96125\/revisions\/96127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96126"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}