{"id":96204,"date":"2024-05-05T05:54:17","date_gmt":"2024-05-05T09:54:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96204"},"modified":"2024-05-05T05:54:18","modified_gmt":"2024-05-05T09:54:18","slug":"los-toros-adquieren-a-gerson-moreno-en-cambio-con-estrellas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-toros-adquieren-a-gerson-moreno-en-cambio-con-estrellas\/","title":{"rendered":"Los Toros adquieren a Gerson Moreno en cambio con Estrellas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/i-300x169-1.jpg\" alt=\"\" class=\"wp-image-96205\" width=\"259\" height=\"146\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">LA ROMANA.- Los Toros del Este anunciaron la adquisici\u00f3n del relevista derecho Gerson Moreno en un cambio desde las Estrellas Orientales en la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana (Lidom).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el cambio por Moreno, los Toros enviaron a las Estrellas al jugador del cuadro interior Rodolfo Castro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al anunciar el cambio, el gerente general de los Toros, Jes\u00fas Mej\u00eda, destac\u00f3 la intenci\u00f3n del equipo de fortalecer su relevo, con la llegada del veterano diestro, de 28 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEste movimiento est\u00e1 enfocado en fortalecer el relevo, nos da un lanzador de poder relevista para la temporada completa\u00bb, precis\u00f3 Mej\u00eda, en un comunicado servido desde su oficina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ejecutivo tambi\u00e9n se refiri\u00f3 a la salida de Castro, con la cual indica que contar\u00e1n con espacio para probar a otros jugadores en el cuadro interior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNos abre espacio en el cuadro interior para otros jugadores que entendemos ya est\u00e1n listos para contribuir y asumir roles importantes\u00bb, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su carrera en la Lidom, Moreno cuenta con marca de 6-2, 2.31 en 52 partidos, en los que suma 61 ponches en 46.2 entradas lanzadas, en las que solo ha permitido 41 imparables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En postemporada ha sido igual de efectivo, acumulando una marca de 2-0, con porcentaje de carreras limpias de 2.70 en 23 encuentros y este verano est\u00e1 lanzando con Las Vegas Aviators, sucursal AAA de los Atl\u00e9ticos de Oakland.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De su lado, Castro vio acci\u00f3n en 65 partidos con los Toros, en los cuales promedi\u00f3 .214 con un par de cuadrangulares y 26 remolcadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Toros han sumado mediante cambio, adem\u00e1s de Moreno, a los jardineros Sandro Fabi\u00e1n, George Valera y Jhonkensy Noel; el receptor Francisco Pe\u00f1a, y los tambi\u00e9n lanzadores Cristian Charle, Arodys Vizca\u00edno y el zurdo Yeury Gervacio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA ROMANA.- Los Toros del Este anunciaron la adquisici\u00f3n del relevista derecho Gerson Moreno en un cambio desde las Estrellas Orientales en la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana (Lidom). En el cambio por Moreno, los Toros enviaron a las Estrellas al jugador del cuadro interior Rodolfo Castro. Al anunciar el cambio, el gerente general de los Toros, Jes\u00fas Mej\u00eda, destac\u00f3 la intenci\u00f3n del equipo de fortalecer su relevo, con la llegada del veterano diestro, de 28 a\u00f1os. \u00abEste movimiento est\u00e1 enfocado en fortalecer el relevo, nos da un lanzador de poder relevista para la temporada completa\u00bb, precis\u00f3 Mej\u00eda, en un comunicado servido desde su oficina. El ejecutivo tambi\u00e9n se refiri\u00f3 a la salida de Castro, con la cual indica que contar\u00e1n con espacio para probar a otros jugadores en el cuadro interior. \u00abNos abre espacio en el cuadro interior para otros jugadores que entendemos ya est\u00e1n listos para contribuir y asumir roles importantes\u00bb, explic\u00f3. En su carrera en la Lidom, Moreno cuenta con marca de 6-2, 2.31 en 52 partidos, en los que suma 61 ponches en 46.2 entradas lanzadas, en las que solo ha permitido 41 imparables. En postemporada ha sido igual de efectivo, acumulando una marca de 2-0, con porcentaje de carreras limpias de 2.70 en 23 encuentros y este verano est\u00e1 lanzando con Las Vegas Aviators, sucursal AAA de los Atl\u00e9ticos de Oakland. De su lado, Castro vio acci\u00f3n en 65 partidos con los Toros, en los cuales promedi\u00f3 .214 con un par de cuadrangulares y 26 remolcadas. Los Toros han sumado mediante cambio, adem\u00e1s de Moreno, a los jardineros Sandro Fabi\u00e1n, George Valera y Jhonkensy Noel; el receptor Francisco Pe\u00f1a, y los tambi\u00e9n lanzadores Cristian Charle, Arodys Vizca\u00edno y el zurdo Yeury Gervacio.<\/p>\n","protected":false},"author":9,"featured_media":96205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-96204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96204"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96204\/revisions"}],"predecessor-version":[{"id":96206,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96204\/revisions\/96206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96205"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}