{"id":96237,"date":"2024-05-07T07:10:26","date_gmt":"2024-05-07T11:10:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96237"},"modified":"2024-05-07T07:10:43","modified_gmt":"2024-05-07T11:10:43","slug":"adp-abre-compas-de-espera-72-horas-para-decidir-sus-acciones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/adp-abre-compas-de-espera-72-horas-para-decidir-sus-acciones\/","title":{"rendered":"ADP abre comp\u00e1s de espera 72 horas para decidir sus acciones"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/ADP-Comite-Ejecuivo-Nacional.jpg\" alt=\"\" class=\"wp-image-96238\" width=\"238\" height=\"133\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/ADP-Comite-Ejecuivo-Nacional.jpg 678w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/ADP-Comite-Ejecuivo-Nacional-300x167.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/ADP-Comite-Ejecuivo-Nacional-600x335.jpg 600w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 6 may .- El presidente de la Asociaci\u00f3n Dominicana Profesores (ADP), Eduardo Hidalgo, anunci\u00f3 este lunes un comp\u00e1s de espera de 72 horas tras el cual el Comit\u00e9 Ejecutivo Nacional de ese gremio decidir\u00e1 cu\u00e1les ser\u00e1n las pr\u00f3ximas acciones que tomar\u00e1 para exigir al Gobierno diversas mejoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo puso de manifiesto en un video publicado en el perfil oficial de la ADP en la red social X, donde su dirigente tambi\u00e9n avanz\u00f3 que la organizaci\u00f3n ha acogido la&nbsp;<strong>mediaci\u00f3n del Defensor del Pueblo, Pablo Ulloa<\/strong>, quien ha invitado a los representantes de los profesores a una reuni\u00f3n el pr\u00f3ximo mi\u00e9rcoles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>REITERA OPOSICI\u00d3N A AUMENTO 8 %<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, dijo no estar de acuerdo con el aumento salarial del 8 % anunciado por el Ministerio de Educaci\u00f3n despu\u00e9s de los paros y concentraciones que los docentes llevaron a cabo en demanda de mejoras salariales, ya que dista del incremento del 20 % que exige el gremio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNosotros ratificamos que no estamos de acuerdo con ese m\u00edsero 8 % que el ministro (\u00c1ngel) Hern\u00e1ndez, de manera unilateral, ha aplicado y que no llena las expectativas del sindicato ni del magisterio\u00bb, insisti\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el departamento de Educaci\u00f3n, el salario de un maestro de primaria es de 63,829 pesos dominicanos, mientras que el de secundaria es de 63,092 pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>OTRAS MEJORAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del incremento salarial del 20 %, los maestros reclaman otras mejoras como la construcci\u00f3n de dos hospitales, centros sociales, aumento de personal y la inclusi\u00f3n en el programa de Medicamentos de Alto Costo del Ministerio de Salud P\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dirigente magisterial asegur\u00f3 que la ADP siempre ha apostado al di\u00e1logo, \u00abpero respetuoso y sincero, no matizado por la difamaci\u00f3n y acusaciones\u00bb y denunci\u00f3 que el profesorado es v\u00edctima de \u00abdifamaci\u00f3n\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHay ataques innecesarios a la organizaci\u00f3n magisterial m\u00e1s antigua que existe en la Rep\u00fablica Dominicana, que es la ADP, que cumpli\u00f3 54 a\u00f1os\u201d, agreg\u00f3 en este sentido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hidalgo manifest\u00f3 que la jornada de lucha de todo el Cibao que se lleva a cabo en 14 provincias, se mantiene y se ha desarrollado exitosamente en alrededor del 100 % de los centros educativos de esa regi\u00f3n.EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 6 may .- El presidente de la Asociaci\u00f3n Dominicana Profesores (ADP), Eduardo Hidalgo, anunci\u00f3 este lunes un comp\u00e1s de espera de 72 horas tras el cual el Comit\u00e9 Ejecutivo Nacional de ese gremio decidir\u00e1 cu\u00e1les ser\u00e1n las pr\u00f3ximas acciones que tomar\u00e1 para exigir al Gobierno diversas mejoras. As\u00ed lo puso de manifiesto en un video publicado en el perfil oficial de la ADP en la red social X, donde su dirigente tambi\u00e9n avanz\u00f3 que la organizaci\u00f3n ha acogido la&nbsp;mediaci\u00f3n del Defensor del Pueblo, Pablo Ulloa, quien ha invitado a los representantes de los profesores a una reuni\u00f3n el pr\u00f3ximo mi\u00e9rcoles. REITERA OPOSICI\u00d3N A AUMENTO 8 % Asimismo, dijo no estar de acuerdo con el aumento salarial del 8 % anunciado por el Ministerio de Educaci\u00f3n despu\u00e9s de los paros y concentraciones que los docentes llevaron a cabo en demanda de mejoras salariales, ya que dista del incremento del 20 % que exige el gremio. \u00abNosotros ratificamos que no estamos de acuerdo con ese m\u00edsero 8 % que el ministro (\u00c1ngel) Hern\u00e1ndez, de manera unilateral, ha aplicado y que no llena las expectativas del sindicato ni del magisterio\u00bb, insisti\u00f3. De acuerdo con el departamento de Educaci\u00f3n, el salario de un maestro de primaria es de 63,829 pesos dominicanos, mientras que el de secundaria es de 63,092 pesos. OTRAS MEJORAS Adem\u00e1s del incremento salarial del 20 %, los maestros reclaman otras mejoras como la construcci\u00f3n de dos hospitales, centros sociales, aumento de personal y la inclusi\u00f3n en el programa de Medicamentos de Alto Costo del Ministerio de Salud P\u00fablica. El dirigente magisterial asegur\u00f3 que la ADP siempre ha apostado al di\u00e1logo, \u00abpero respetuoso y sincero, no matizado por la difamaci\u00f3n y acusaciones\u00bb y denunci\u00f3 que el profesorado es v\u00edctima de \u00abdifamaci\u00f3n\u00bb. \u00abHay ataques innecesarios a la organizaci\u00f3n magisterial m\u00e1s antigua que existe en la Rep\u00fablica Dominicana, que es la ADP, que cumpli\u00f3 54 a\u00f1os\u201d, agreg\u00f3 en este sentido. Hidalgo manifest\u00f3 que la jornada de lucha de todo el Cibao que se lleva a cabo en 14 provincias, se mantiene y se ha desarrollado exitosamente en alrededor del 100 % de los centros educativos de esa regi\u00f3n.EFE<\/p>\n","protected":false},"author":9,"featured_media":96238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-96237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96237"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96237\/revisions"}],"predecessor-version":[{"id":96239,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96237\/revisions\/96239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96238"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}