{"id":96243,"date":"2024-05-08T05:22:15","date_gmt":"2024-05-08T09:22:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96243"},"modified":"2024-05-08T05:22:17","modified_gmt":"2024-05-08T09:22:17","slug":"luis-abinader-llega-a-washington-recibira-reconocimiento-en-la-oea","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/luis-abinader-llega-a-washington-recibira-reconocimiento-en-la-oea\/","title":{"rendered":"Luis Abinader llega a Washington, recibir\u00e1 reconocimiento en la OEA"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-07-at-8.58.48-PM-scaled-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-96244\" width=\"248\" height=\"164\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-07-at-8.58.48-PM-scaled-1-1024x683.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-07-at-8.58.48-PM-scaled-1-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-07-at-8.58.48-PM-scaled-1-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-07-at-8.58.48-PM-scaled-1-600x400.jpeg 600w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Washington. \u2013 El presidente de Rep\u00fablica Dominicana Luis Abinader lleg\u00f3 la noche de este martes a esta ciudad, donde recibir\u00e1 en la Organizaci\u00f3n de Estados Americanos (OEA) el \u00abPremio al Liderazgo en las Am\u00e9ricas\u00bb&nbsp;y participar\u00e1 como orador en la 54 Conferencia Anual de este organismo hemisf\u00e9rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El premio, otorgado por el Consejo de las Am\u00e9ricas,&nbsp; es porque se considera que el Mandatario dominicano ha trabajado para promover la seguridad regional, apoyar la democracia y luchar contra la corrupci\u00f3n desde que asumi\u00f3 la presidencia en el a\u00f1o 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto tendr\u00e1 lugar este mi\u00e9rcoles 8 de mayo en la sede de la OEA.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/almomento.net\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-07-at-8.58.47-PM-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/almomento.net\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-07-at-8.58.47-PM-scaled.jpeg\" alt=\"\" class=\"wp-image-952774\" \/><\/a><figcaption>El Presidente Abinader y la primera Dama, Raquel Arbaje, a su llegada.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DETALLES DE LA PREMIACION<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este reconocimiento se otorga a funcionarios elegidos democr\u00e1ticamente que hayan demostrado un compromiso excepcional con el Hemisferio Oeste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ha sido entregado en el pasado a otros l\u00edderes de la regi\u00f3n, entre ellos Luis Almagro, secretario General de la Organizaci\u00f3n de Estados Americanos (OEA), en 2022; Bill Cassidy, senador de Estados Unidos, en 2021,&nbsp; y Marco Rubio, tambi\u00e9n senador de este pa\u00eds,&nbsp; en 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Conferencia Anual de Washington sobre las Am\u00e9ricas es el principal evento sobre la regi\u00f3n en el que, cada a\u00f1o, funcionarios del m\u00e1s alto nivel hablan sobre comercio,&nbsp; democracia, energ\u00eda y otros temas.&nbsp;&nbsp;Tambi\u00e9n ofrece a los participantes la oportunidad de interactuar con l\u00edderes empresariales y pol\u00edticos, miembros de la comunidad diplom\u00e1tica e invitados especiales de todo el hemisferio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario viaj\u00f3 a Washington acompa\u00f1ado de la primera dama, Raquel Arbaje; los ministros de Relaciones Exteriores, Roberto \u00c1lvarez; de Hacienda, Jos\u00e9 Manuel Vicente, y de Econom\u00eda, Pavel Isa, as\u00ed como sus respectivos asistentes,. A ellos se sum\u00f3&nbsp; la embajadora dominicana en Washington, Sonia Guzm\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington. \u2013 El presidente de Rep\u00fablica Dominicana Luis Abinader lleg\u00f3 la noche de este martes a esta ciudad, donde recibir\u00e1 en la Organizaci\u00f3n de Estados Americanos (OEA) el \u00abPremio al Liderazgo en las Am\u00e9ricas\u00bb&nbsp;y participar\u00e1 como orador en la 54 Conferencia Anual de este organismo hemisf\u00e9rico. El premio, otorgado por el Consejo de las Am\u00e9ricas,&nbsp; es porque se considera que el Mandatario dominicano ha trabajado para promover la seguridad regional, apoyar la democracia y luchar contra la corrupci\u00f3n desde que asumi\u00f3 la presidencia en el a\u00f1o 2020. El acto tendr\u00e1 lugar este mi\u00e9rcoles 8 de mayo en la sede de la OEA. DETALLES DE LA PREMIACION Este reconocimiento se otorga a funcionarios elegidos democr\u00e1ticamente que hayan demostrado un compromiso excepcional con el Hemisferio Oeste. Ha sido entregado en el pasado a otros l\u00edderes de la regi\u00f3n, entre ellos Luis Almagro, secretario General de la Organizaci\u00f3n de Estados Americanos (OEA), en 2022; Bill Cassidy, senador de Estados Unidos, en 2021,&nbsp; y Marco Rubio, tambi\u00e9n senador de este pa\u00eds,&nbsp; en 2019. La Conferencia Anual de Washington sobre las Am\u00e9ricas es el principal evento sobre la regi\u00f3n en el que, cada a\u00f1o, funcionarios del m\u00e1s alto nivel hablan sobre comercio,&nbsp; democracia, energ\u00eda y otros temas.&nbsp;&nbsp;Tambi\u00e9n ofrece a los participantes la oportunidad de interactuar con l\u00edderes empresariales y pol\u00edticos, miembros de la comunidad diplom\u00e1tica e invitados especiales de todo el hemisferio. El mandatario viaj\u00f3 a Washington acompa\u00f1ado de la primera dama, Raquel Arbaje; los ministros de Relaciones Exteriores, Roberto \u00c1lvarez; de Hacienda, Jos\u00e9 Manuel Vicente, y de Econom\u00eda, Pavel Isa, as\u00ed como sus respectivos asistentes,. A ellos se sum\u00f3&nbsp; la embajadora dominicana en Washington, Sonia Guzm\u00e1n.<\/p>\n","protected":false},"author":9,"featured_media":96244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-96243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96243"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96243\/revisions"}],"predecessor-version":[{"id":96245,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96243\/revisions\/96245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96244"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}